{"id":29676,"date":"2020-09-23T18:50:58","date_gmt":"2020-09-23T17:50:58","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=29676"},"modified":"2020-09-23T18:50:58","modified_gmt":"2020-09-23T17:50:58","slug":"perversos-silogismos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/perversos-silogismos\/","title":{"rendered":"Perversos silogismos"},"content":{"rendered":"<p>Hemos llegado a un punto de polarizaci\u00f3n y odio cainita en el que cada vez m\u00e1s gente despacha cualquier argumento sin siquiera escucharlo o reflexionar sobre \u00e9l, \u00fanicamente por venir de quien viene.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/perversos-silogismos\/espana-cainita\/\" rel=\"attachment wp-att-29677\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29677\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/espa\u00f1a-cainita-300x144.jpg\" alt=\"\" width=\"300\" height=\"144\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/espa\u00f1a-cainita-300x144.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/espa\u00f1a-cainita-768x369.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/espa\u00f1a-cainita-644x309.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/espa\u00f1a-cainita.jpg 1354w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Gente de derechas que odia cervalmente a Pedro y Pablo, nuestros Picapiedra de la Moncloa, plenamente convencida de que todo lo que hacen, dicen y piensan es err\u00f3neo y nos llevar\u00e1 al m\u00e1s absoluto de los desastres. Normal, dado que Castro, Stalin y los ayatol\u00e1s les inspiran.<\/p>\n<p>Gente de izquierdas para quienes, desde los tiempos de Aznar, todo el PP y, posteriormente, Ciudadanos en pleno; son fachas. Y punto. Fachas o fascistas, por no repetirse en exceso. Normal, que todos ellos tienen chapas de Franco, Hitler y Mussolini en la nevera, junto a los recuerdos de Benidorm y un relieve de Torremolinos.<\/p>\n<p>Estamos en un punto en que los procesos mentales le han dado la vuelta a cualquier atisbo de l\u00f3gica, utilizando para ello un perverso silogismo: Pedro S\u00e1nchez \/ Pablo Casado siempre est\u00e1n equivocados. Esta idea la han propuesto Pedro S\u00e1nchez \/ Pablo Casado, ergo, esta idea es equivocada.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/perversos-silogismos\/espana-silogismo\/\" rel=\"attachment wp-att-29678\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29678\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-silogismo-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-silogismo-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-silogismo-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-silogismo-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-silogismo.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A partir de ah\u00ed, toca trabajar para destrozar la idea de turno con cualquier tipo de argumento, sea verdadero o falso, sin empacho en utilizar el ad hominem a diestro y siniestro o en recurrir al socorrido \u2018y t\u00fa m\u00e1s\u2019.<\/p>\n<p>Esto ocurre a nivel nacional, pero tambi\u00e9n sucede en el espectro auton\u00f3mico y local. El odio y el desprecio se han ense\u00f1oreado de amplias capas de ciudadanos de a pie dado que muchos pol\u00edticos se parecen cada vez m\u00e1s a actores y actrices de vodevil, recitando de corrido los papeles que les escriben y multiplicando sus astracanadas sobre el escenario. Es lo que espolea, a su vez, a las bases de fieles ac\u00f3litos, a los periodistas, analistas y comentaristas hoolligan y a cientos de miles de internautas desocupados.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/perversos-silogismos\/espana-y-tu-mas\/\" rel=\"attachment wp-att-29679\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29679\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-Y-t\u00fa-m\u00e1s-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-Y-t\u00fa-m\u00e1s-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-Y-t\u00fa-m\u00e1s-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/09\/Espa\u00f1a-Y-t\u00fa-m\u00e1s.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Desconf\u00eden de quienes siempre ven mal lo que hacen los otros. Sospechen del discurso permanentemente frentista y exaltado. Cuestionen las verdades universales y las soluciones m\u00e1gicas. Recuerden que hasta un reloj parado da bien la hora dos veces al d\u00eda. Es imposible que el rival lo haga todo mal todo el tiempo. Es igualmente improbable que los nuestros acierten siempre y en todo momento. El forofismo, para el f\u00fatbol. Y que decida el VAR.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-29227\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29227 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos llegado a un punto de polarizaci\u00f3n y odio cainita en el que cada vez m\u00e1s gente despacha cualquier argumento sin siquiera escucharlo o reflexionar sobre \u00e9l, \u00fanicamente por venir de quien viene. Gente de derechas que odia cervalmente a Pedro y Pablo, nuestros Picapiedra de la Moncloa, plenamente convencida de que todo lo que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[19469,19468,19470,19471,19467,17268,11392],"class_list":["post-29676","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-argumento-ad-hominem","tag-espana-cainita","tag-los-mios","tag-los-nuestros","tag-silogismos","tag-todos-fachas","tag-y-tu-mas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=29676"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29676\/revisions"}],"predecessor-version":[{"id":29681,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29676\/revisions\/29681"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=29676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=29676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=29676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}