{"id":29321,"date":"2020-07-13T18:35:25","date_gmt":"2020-07-13T17:35:25","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=29321"},"modified":"2020-07-13T18:36:22","modified_gmt":"2020-07-13T17:36:22","slug":"tierra-esferica-mentes-planas","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/tierra-esferica-mentes-planas\/","title":{"rendered":"Tierra esf\u00e9rica, mentes planas"},"content":{"rendered":"<p>La imagen de la portada del XL Semanal representaba una esfera de color marr\u00f3n surcada por hileras de personas en movimiento. Nada m\u00e1s verla supe que era de Genov\u00e9s, uno de los pintores espa\u00f1oles con una obra m\u00e1s personal y reconocible. Hace unos a\u00f1os, en ARCO, disfrut\u00e9 acerc\u00e1ndome a escasos cent\u00edmetros de dos de sus cuadros, maravillado por c\u00f3mo consegu\u00eda que unos \u2018borrones\u2019 de pintura apenas sugeridos en el lienzo, vistos desde lejos, parecieran personas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/tierra-esferica-mentes-planas\/xl-semanal-genoves\/\" rel=\"attachment wp-att-29325\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29325\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/XL-Semanal-Genov\u00e9s-229x300.jpg\" alt=\"\" width=\"229\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/XL-Semanal-Genov\u00e9s-229x300.jpg 229w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/XL-Semanal-Genov\u00e9s-768x1006.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/XL-Semanal-Genov\u00e9s-644x843.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/XL-Semanal-Genov\u00e9s.jpg 782w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/a><\/p>\n<p>Genov\u00e9s consegu\u00eda con sus cuadros el efecto contrario a lo sugerido por Harry Lime en \u2018El tercer hombre\u2019: la distancia dotaba de humanidad y personalidad a la imagen esbozada en el cuadro.<\/p>\n<p>En su \u00faltimo obra, inacabada, Genov\u00e9s muestra a decenas de personas dando vueltas por el mundo. Para su hijo, el artista busca lecturas filos\u00f3ficas y existencialistas, dado que siempre le damos vueltas a lo mismo. Superpuestas sobre un marr\u00f3n esf\u00e9rico tan terr\u00e1queo y terrenal como lunar y marciano, esas tiras con personas en movimiento, por su condici\u00f3n n\u00f3mada y emigrante, tambi\u00e9n se me asemejan a alambre de espino. Aunque esa impresi\u00f3n est\u00e1 condicionada por haber visto muchas obras de Juan Vida estos d\u00edas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/tierra-esferica-mentes-planas\/juan-vida-2\/\" rel=\"attachment wp-att-29323\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29323\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Juan-Vida-246x300.jpg\" alt=\"\" width=\"246\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Juan-Vida-246x300.jpg 246w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Juan-Vida-768x938.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Juan-Vida-644x787.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Juan-Vida.jpg 786w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" \/><\/a><\/p>\n<p>Contrasta la perspectiva cil\u00edndrica, el ojo de buey de la esfera terrestre, con el encefalograma plano de esa peste del siglo XXI que son los terraplanistas. El fin de semana se hizo viral el v\u00eddeo de una tatuadora granadina que ped\u00eda explicaciones sobre el imposible discurrir del Nilo en una tierra esf\u00e9rica. \u201cY no me veng\u00e1is con la mariconada de la gravedad porque para m\u00ed, la gravedad no existe\u201d, remataba su maravillosa alocuci\u00f3n. Y digo bien maravillosa porque, gracias a su \u00e9xito y al margen de los insultos y los mesamientos de cabello virtuales, aparecieron en la red multitud de v\u00eddeos cient\u00edficos estupendos.<\/p>\n<p>Me encant\u00f3, por ejemplo, uno de Carl Sagan sobre Erat\u00f3stenes en el que, con la ayuda de un simple palo \u2014\u00a1un palo, un palo!\u2014 demuestra cient\u00edficamente que la tierra es esf\u00e9rica. Paradojas de la vida: ahora que llevamos en el bolsillo m\u00f3viles de ultim\u00edsima generaci\u00f3n con no se cu\u00e1ntos terabytes de capacidad, hay que volver a los b\u00e1sicos y demostrar emp\u00edricamente que la tierra es redonda y que las vacunas salvan vidas. (<a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/vivan-las-vacunas\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>, mi opini\u00f3n sobre la hez antivacunas)<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/tierra-esferica-mentes-planas\/gilipollas\/\" rel=\"attachment wp-att-29324\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29324\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Gilipollas-300x224.png\" alt=\"\" width=\"300\" height=\"224\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Gilipollas-300x224.png 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Gilipollas-644x480.png 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/07\/Gilipollas.png 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Son las contradicciones del siglo XXI, denunciadas por Umberto Eco: \u201clas redes sociales le dan el derecho de hablar a legiones de imb\u00e9ciles\u201d. Ser\u00e1 por eso que esas mismas redes se encargan de matarle una y otra vez, c\u00edclicamente, dos o tres veces por a\u00f1o.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-29227\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29227 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/00000-Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La imagen de la portada del XL Semanal representaba una esfera de color marr\u00f3n surcada por hileras de personas en movimiento. Nada m\u00e1s verla supe que era de Genov\u00e9s, uno de los pintores espa\u00f1oles con una obra m\u00e1s personal y reconocible. Hace unos a\u00f1os, en ARCO, disfrut\u00e9 acerc\u00e1ndome a escasos cent\u00edmetros de dos de sus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[19242,19244,3773,19243],"class_list":["post-29321","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-genoves-postumo","tag-gilpollas-siglo-xxi","tag-juan-vida","tag-las-vacunas-matan"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=29321"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29321\/revisions"}],"predecessor-version":[{"id":29328,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29321\/revisions\/29328"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=29321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=29321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=29321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}