{"id":29087,"date":"2020-05-27T13:57:18","date_gmt":"2020-05-27T12:57:18","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=29087"},"modified":"2020-05-27T13:57:18","modified_gmt":"2020-05-27T12:57:18","slug":"por-fin-vuelve-el-futbol","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/por-fin-vuelve-el-futbol\/","title":{"rendered":"Por fin vuelve el f\u00fatbol"},"content":{"rendered":"<p>Qu\u00e9 bueno que vuelva el f\u00fatbol. Si por m\u00ed fuera, y con permiso de la musculatura de los jugadores, empezar\u00eda el pr\u00f3ximo fin de semana: de todas las medidas de la desescalada, esta es trascendental.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/por-fin-vuelve-el-futbol\/futbol\/\" rel=\"attachment wp-att-29088\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-29088\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/05\/F\u00fatbol.jpg\" alt=\"\" width=\"259\" height=\"195\" \/><\/a><\/p>\n<p>Desde que se paralizaron la Liga, Champion\u2019s y dem\u00e1s competiciones futbol\u00edsticas, esto es un no vivir, con miles de vocacionales entrenadores de barra de bar mutados en epidemi\u00f3logos, soci\u00f3logos y polit\u00f3logos.<\/p>\n<p>Los kilovatios de energ\u00eda diariamente empleados en discutir de f\u00fatbol se canalizaron hacia temas como el control de la pandemia, la gesti\u00f3n del estado de alarma y las fases de desescalada. Lo que hubiera estado muy bien\u2026 si no se estuvieran tratando con el incendiario forofismo partidista con el que habitualmente se habla de deporte.<\/p>\n<p>A m\u00ed, el f\u00fatbol, me trae al pairo. Me resulta indiferente desde hace a\u00f1os. Sin embargo, cada vez que un intelectual (o aspirante a) suelta lo de que es el opio del pueblo, me sale sarpullido. Nunca he entendido la supuesta superioridad moral del que invierte dos horas en ver una pel\u00edcula rumana en VOS sobre el que disfruta de un partido del Granada C.F. Esa necesidad permanente de descalificar al otro. \u00a1C\u00f3mo si fuese incompatible ver deporte con ser un buen lector!<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/por-fin-vuelve-el-futbol\/futbol-pandemia\/\" rel=\"attachment wp-att-29089\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-29089\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/05\/Futbol-pandemia.jpg\" alt=\"\" width=\"286\" height=\"176\" \/><\/a><\/p>\n<p>\u201cEs que hay mucha gente para la que lo \u00fanico importante en la vida es el f\u00fatbol, que le tiene el seso sorbido\u201d. \u00a1Pues muy bien! \u00a1All\u00e1 ella! Mejor que esa encendida pasi\u00f3n forofista se canalice a trav\u00e9s del bal\u00f3n en vez de derivarse hacia cuestiones sanitarias o cient\u00edficas. Mejor que se cuestionen las alineaciones, t\u00e1cticas y cambios realizados por el entrenador del Real Madrid que las actuaciones y recomendaciones del secretario general de la OMS.<\/p>\n<p>Y no porque considere infalible a la OMS o al doctor Sim\u00f3n, sino porque las opiniones de Fulano, Mengano y Zutano sobre c\u00f3mo afectan las mutaciones del virus a la gesti\u00f3n de la pandemia tienen tanto fundamento y utilidad pr\u00e1ctica como mis pron\u00f3sticos para la Quiniela.<\/p>\n<p>Sosten\u00eda Von Clausewitz que la guerra es la continuaci\u00f3n de la pol\u00edtica por otros medios. Consideraba la guerra moderna como un acto pol\u00edtico, confiri\u00e9ndole un preocupante elemento racional. Adem\u00e1s, los otros dos elementos de la guerra ser\u00edan el odio, la enemistad y la violencia primitiva por una parte; y el juego del azar y las probabilidades, por otro.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/por-fin-vuelve-el-futbol\/futbol-discusiones\/\" rel=\"attachment wp-att-29090\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-29090\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/05\/F\u00fatbol-discusiones-150x300.jpg\" alt=\"\" width=\"150\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/05\/F\u00fatbol-discusiones-150x300.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/05\/F\u00fatbol-discusiones.jpg 159w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p>\u00bfNo es mucho mejor que la continuaci\u00f3n de la pol\u00edtica por otros medios acabe en el f\u00fatbol, absorbiendo el at\u00e1vico primitivismo del ser humano y la excitante aleatoriedad nerviosa que provoca el juego?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 bueno que vuelva el f\u00fatbol. Si por m\u00ed fuera, y con permiso de la musculatura de los jugadores, empezar\u00eda el pr\u00f3ximo fin de semana: de todas las medidas de la desescalada, esta es trascendental. Desde que se paralizaron la Liga, Champion\u2019s y dem\u00e1s competiciones futbol\u00edsticas, esto es un no vivir, con miles de vocacionales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13,8,6],"tags":[19083,19086,19084,19085],"class_list":["post-29087","post","type-post","status-publish","format-standard","hentry","category-deporte-vida-empresa","category-deportes","category-opinion","tag-discutir-de-futbol","tag-el-cinefilo-futbolero","tag-que-vuelva-el-futbol","tag-ver-futbol"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=29087"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29087\/revisions"}],"predecessor-version":[{"id":29092,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29087\/revisions\/29092"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=29087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=29087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=29087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}