{"id":28991,"date":"2020-04-22T14:18:36","date_gmt":"2020-04-22T13:18:36","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28991"},"modified":"2020-04-22T14:18:36","modified_gmt":"2020-04-22T13:18:36","slug":"el-dia-del-libro-en-una-nueva-normalidad","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-dia-del-libro-en-una-nueva-normalidad\/","title":{"rendered":"El D\u00eda del Libro en una Nueva Normalidad"},"content":{"rendered":"<p>Ma\u00f1ana se celebra el D\u00eda del Libro m\u00e1s extra\u00f1o de la historia. Lo que no tiene nada de raro dado que, desde hace seis semanas, todo lo que nos ocurre cada d\u00eda oscila entre lo kafkiano y lo dist\u00f3pico.<\/p>\n<p>Me encant\u00f3 una foto del muro de Fran J. Ortiz, invitando a poner en la ventana un r\u00f3tulo con las palabras \u2018Dirigido por David Lynch\u2019. Ser\u00eda una forma de asomarnos a la vida de ah\u00ed fuera con unos ojos diferentes a los habituales. Unos ojos que nos permitan adivinar una realidad m\u00e1s all\u00e1 de la aparente.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-dia-del-libro-en-una-nueva-normalidad\/david-lynch\/\" rel=\"attachment wp-att-28992\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28992\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/David-Lynch-205x300.jpg\" alt=\"\" width=\"205\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/David-Lynch-205x300.jpg 205w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/David-Lynch-644x942.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/David-Lynch.jpg 656w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/a><\/p>\n<p>Ma\u00f1ana se celebra el D\u00eda del Libro con las librer\u00edas cerradas al p\u00fablico, parad\u00f3jicamente. Por fortuna, algunas de las m\u00e1s peque\u00f1as y combativas de Granada siguen trabajando a trav\u00e9s de Correos o empresas de mensajer\u00eda, que no todo va a ser Amazon.<\/p>\n<p>Ma\u00f1ana se celebra el D\u00eda del Libro y nos encuentra encerrados en casa a la mayor\u00eda de nosotros, con 24 horas por delante para, por ejemplo, leer. Que no todo va a ser hacer bizcochos, entregarse al teletrabajo y\/o a la teleformaci\u00f3n, propia o ajena; y petar la agenda con videoconferencias a trav\u00e9s del Zoom.<\/p>\n<p>No s\u00e9 ustedes, pero yo s\u00ed estoy tratando de leer con generosidad. Al principio me costaba concentrarme, pero ya me he adaptado. Es cierto que leo mucho sobre la Covid-19, dedic\u00e1ndole tiempo a la prensa, impresa y digital. Al coronavirus y a las consecuencias de la pandemia que utilizar la t\u00e1ctica del avestruz y meter la cabeza en un agujero tampoco es razonable. Pero tambi\u00e9n estoy leyendo muchos c\u00f3mics, novelas y cuentos. Por ejemplo, dos novelones de cerca de 1000 p\u00e1ginas: \u2018Dune\u2019 y \u201922\/11\/63\u2019<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-dia-del-libro-en-una-nueva-normalidad\/dune-y-cune\/\" rel=\"attachment wp-att-28993\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28993\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Dune-y-Cune-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Dune-y-Cune-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Dune-y-Cune-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Dune-y-Cune-644x859.jpg 644w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>El D\u00eda del Libro nos sorprende preparando nuestro desembarco en una Nueva Normalidad, que ser\u00eda el t\u00edtulo perfecto para una serie dist\u00f3pica de Netflix o la HBO. Una Nueva Normalidad. De hecho, #NN tiene visos de convertirse en un hashtag de lo m\u00e1s popular y recurrente.<\/p>\n<p>La nueva normalidad har\u00e1 que, aun levant\u00e1ndose el confinamiento, nuestro hogar sea un espacio donde pasaremos mucho m\u00e1s tiempo que anta\u00f1o. De ah\u00ed la importancia de atesorar una buena, variada y nutrida biblioteca. Ma\u00f1ana, el 23 de abril m\u00e1s extra\u00f1o de nuestra vida, los libros ser\u00e1n m\u00e1s importantes que nunca.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana se celebra el D\u00eda del Libro m\u00e1s extra\u00f1o de la historia. Lo que no tiene nada de raro dado que, desde hace seis semanas, todo lo que nos ocurre cada d\u00eda oscila entre lo kafkiano y lo dist\u00f3pico. Me encant\u00f3 una foto del muro de Fran J. Ortiz, invitando a poner en la ventana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,6],"tags":[19021,964,19019,19020],"class_list":["post-28991","post","type-post","status-publish","format-standard","hentry","category-literarios","category-opinion","tag-celebrar-el-dia-del-libro","tag-dia-del-libro","tag-dia-del-libro-2020","tag-una-nueva-normalidad"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28991"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28991\/revisions"}],"predecessor-version":[{"id":28995,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28991\/revisions\/28995"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}