{"id":28966,"date":"2020-04-16T12:32:23","date_gmt":"2020-04-16T11:32:23","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28966"},"modified":"2020-04-16T12:32:23","modified_gmt":"2020-04-16T11:32:23","slug":"modelo-economico-productivo-y-social","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/modelo-economico-productivo-y-social\/","title":{"rendered":"Modelo econ\u00f3mico, productivo y social"},"content":{"rendered":"<p>Para m\u00ed, lo tristemente revelador de la profunda crisis que estamos viviendo es que muestra las carencias, fallas y debilidades del modelo econ\u00f3mico y productivo de nuestro pa\u00eds.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/modelo-economico-productivo-y-social\/3d-illustration-abstract-viral-infection-causing-chronic-disease\/\" rel=\"attachment wp-att-28967\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28967\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a-coronavirus-300x157.jpg\" alt=\"\" width=\"300\" height=\"157\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a-coronavirus-300x157.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a-coronavirus-768x401.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a-coronavirus-644x336.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a-coronavirus.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Durante a\u00f1os y a\u00f1os se nos ha llenado la boca hablando de E-commerce y E-learning, conectividad, internet de las cosas, 5S, Smart Cities, Human Tech, rob\u00f3tica e inteligencia artificial.<\/p>\n<p>Sin embargo, vamos para seis semanas desde que se decret\u00f3 el Estado de Alarma y, de momento, seguimos sin mascarillas, sin tests r\u00e1pidos y sin App alguna que monitorice a las personas infectadas para hacer un seguimiento de sus contactos y movimientos.<\/p>\n<p>Hay loables pr\u00e1cticas a peque\u00f1a escala, sin resultados apreciables por el momento.<\/p>\n<p>No lean esto como una cr\u00edtica al gobierno. No lo es. Si en vez de estos hubieran estado los otros, habr\u00eda ocurrido exactamente lo mismo. Hubiera dado igual. Porque esta no es una crisis de gobierno. Ni de timonel. Es una crisis de identidad social, econ\u00f3mica y productiva.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/modelo-economico-productivo-y-social\/espana\/\" rel=\"attachment wp-att-28968\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28968\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a-300x164.jpg\" alt=\"\" width=\"300\" height=\"164\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a-300x164.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/04\/Espa\u00f1a.jpg 304w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ahora es momento de continuar doblando la curva, minimizar los contagios y meter en vereda al bicho. OK. Pero a no mucho tardar deber\u00edamos pensar y debatir sobre el modelo econ\u00f3mico, productivo y social de la Espa\u00f1a del futuro.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para m\u00ed, lo tristemente revelador de la profunda crisis que estamos viviendo es que muestra las carencias, fallas y debilidades del modelo econ\u00f3mico y productivo de nuestro pa\u00eds. Durante a\u00f1os y a\u00f1os se nos ha llenado la boca hablando de E-commerce y E-learning, conectividad, internet de las cosas, 5S, Smart Cities, Human Tech, rob\u00f3tica e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[19010,18375,19011],"class_list":["post-28966","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-espana-productividad","tag-espana-trasnochada","tag-futuro-economico-de-espana"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28966"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28966\/revisions"}],"predecessor-version":[{"id":28970,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28966\/revisions\/28970"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}