{"id":28664,"date":"2020-02-11T06:37:30","date_gmt":"2020-02-11T05:37:30","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28664"},"modified":"2020-02-10T20:01:34","modified_gmt":"2020-02-10T19:01:34","slug":"parasitos-jocosos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/parasitos-jocosos\/","title":{"rendered":"Par\u00e1sitos jocosos"},"content":{"rendered":"<p>No me importa que Pedro Almod\u00f3var y Antonio Banderas se hayan ido de vac\u00edo, dados los premios de la Academia de Hollywood de este a\u00f1o. Aunque hab\u00eda pensado quedarme a ver la ceremonia, les confieso que me venci\u00f3 el sue\u00f1o. Por eso, al abrir los ojos y comprobar que la ganadora absoluta hab\u00eda sido \u2018Par\u00e1sitos\u2019, casi descuajeringo la cama del brinco que pegu\u00e9.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=28665\" rel=\"attachment wp-att-28665\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28665\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Par\u00e1sitos.jpg\" alt=\"\" width=\"184\" height=\"273\" \/><\/a><\/p>\n<p>Es la pel\u00edcula que con m\u00e1s ah\u00ednco y empe\u00f1o he recomendado en los \u00faltimos meses. \u00bfRecuerdan ustedes que, de cara a la jornada de reflexi\u00f3n de las pasadas elecciones, les aconsejaba ir al cine a verla? (L\u00e9anlo <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/reflexionar-con-parasitos\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>)<\/p>\n<p>La pel\u00edcula del coreano Bong Joon-ho es soberbia. Es apasionante, desconcertante y cruelmente divertida. Humor negro, drama y thriller se dan la mano en un t\u00edtulo que ya es referencial en la historia del cine. Una pel\u00edcula de denuncia social repleta de cargas de profundidad que la HBO va a convertir en serie. O en \u201cpel\u00edcula expandida de alta calidad\u201d, en definici\u00f3n del propio Joon-ho, que no ha dudado en afrontar el reto.<\/p>\n<p>Las cosas est\u00e1n cambiando a una velocidad vertiginosa en el mundo del cine. \u00bfVieron ustedes las im\u00e1genes de la llegada del cineasta al aeropuerto Incheon de Corea del Sur, tras la consecuci\u00f3n de la Palma de Oro en Cannes con \u2018Par\u00e1sitos\u2019? En Espa\u00f1a s\u00f3lo concita a tanta prensa un futbolista\u2026 o el ganador de programas como \u2018La isla de las tentaciones\u2019.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=28666\" rel=\"attachment wp-att-28666\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28666\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Bong-joon-ho-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Bong-joon-ho-300x170.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Bong-joon-ho-768x435.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Bong-joon-ho-644x365.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Bong-joon-ho.jpg 921w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El cine es una industria global que, adem\u00e1s, cada vez est\u00e1 m\u00e1s globalizada. Un a\u00f1o arrasa \u2018Roma\u2019 en Hollywood, una pel\u00edcula mexicana producida por Netflix, y al a\u00f1o siguiente, un cineasta coreano les moja la oreja a Scorsese y a Tarantino en su propia casa.<\/p>\n<p>Sin olvidar al \u2018Joker\u2019 y su militancia nihilista, un alegato cuasi anarquista que Joaquin Phoenix expande inteligente y exponencialmente cada vez que recoge un premio. Tambi\u00e9n les habl\u00e9 de ella. (Leer <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-joker-noir\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a> y <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/ver-el-mundo-arder\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>)<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=28667\" rel=\"attachment wp-att-28667\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-28667\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Joker-Music.jpg\" alt=\"\" width=\"225\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Joker-Music.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/00-Joker-Music-150x150.jpg 150w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Y de su m\u00fasica, compuesta por la chelista islandesa Hildur Guonad\u00f3ttir, la gran triunfadora del a\u00f1o gracias al Guas\u00f3n y a la serie \u2018Chernobyl\u2019. Insisto: ser\u00eda flipante escucharla en el Festival de M\u00fasica y Danza de Granada. (Leer <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/musica-de-infierno-y-locura\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd)<\/a><\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No me importa que Pedro Almod\u00f3var y Antonio Banderas se hayan ido de vac\u00edo, dados los premios de la Academia de Hollywood de este a\u00f1o. Aunque hab\u00eda pensado quedarme a ver la ceremonia, les confieso que me venci\u00f3 el sue\u00f1o. Por eso, al abrir los ojos y comprobar que la ganadora absoluta hab\u00eda sido \u2018Par\u00e1sitos\u2019, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,6],"tags":[14496,18801,18684,18395,18802],"class_list":["post-28664","post","type-post","status-publish","format-standard","hentry","category-cine","category-opinion","tag-bong-joon-ho","tag-joker-oscar","tag-oscar-2020","tag-parasitos-pelicula","tag-parasitos-serie-hbo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28664"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28664\/revisions"}],"predecessor-version":[{"id":28681,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28664\/revisions\/28681"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}