{"id":28423,"date":"2020-01-02T18:40:46","date_gmt":"2020-01-02T17:40:46","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28423"},"modified":"2020-01-05T18:46:37","modified_gmt":"2020-01-05T17:46:37","slug":"un-2020-sin-existencia-real","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/un-2020-sin-existencia-real\/","title":{"rendered":"Un 2020 sin existencia real"},"content":{"rendered":"<p>Estoy con los prop\u00f3sitos de A\u00f1o Nuevo. Pero antes de nada, feliz 2020. \u00bfC\u00f3mo lo llevan? Imagino que bien, salvo que confiaran en el reloj de Plaza del Carmen para comerse las uvas, claro. \u00a1Qu\u00e9 cosas pasan en esta Granada nuestra! Pero no se preocupen. Ya ver\u00e1n como lo de tremolar el pend\u00f3n sale a pedir de boca.<\/p>\n<p>Mi 2020 comenz\u00f3 en un lugar inusual: el Teatro Lope de Vega de Madrid, en el intermedio de la representaci\u00f3n del musical \u2018El Rey Le\u00f3n\u2019, con uvas, antifaces y confeti. Fue toda una experiencia darle la bienvenida al a\u00f1o mezclados con cientos de entusiastas amantes del musical, junto al equipo t\u00e9cnico y art\u00edstico de la compa\u00f1\u00eda que lleva 9 a\u00f1os consecutivos representando las aventuras de Simba, Nala y Scar.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/un-2020-sin-existencia-real\/el-rey-leon-nochevieja\/\" rel=\"attachment wp-att-28424\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28424\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/El-Rey-Le\u00f3n-Nochevieja-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/El-Rey-Le\u00f3n-Nochevieja-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/El-Rey-Le\u00f3n-Nochevieja-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/El-Rey-Le\u00f3n-Nochevieja-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Me emocion\u00e9 con el musical. El despliegue visual y creativo de los trajes y las marionetas que representan a los animales de la sabana resulta prodigioso. Me despellej\u00e9 las manos de tanto aplaudir. Si est\u00e1n pensando en hacer un regalo diferente y original para Reyes, es una inmejorable opci\u00f3n, pero si visitar Madrid no se encuentra entre sus planes m\u00e1s inmediatos, una entrada para el Circo del Sol, que act\u00faa en Granada dentro de un par de semanas, es otro acierto garantizado. Una experiencia art\u00edstica total que compendia lo mejor de las artes para ofrecer un espect\u00e1culo \u00fanico y singular. Estuvimos hace unos meses en su carpa de M\u00e1laga, viendo \u2018Kooza\u2019, y salimos flotando. \u00bfQu\u00e9 tal resultar\u00e1 el \u2018Corteo\u2019 que no tardaremos en disfrutar en el Palacio de Deportes? Otra gozada, seguro.<\/p>\n<p>Para este 2020 quiero hacer m\u00e1s cosas terrenales, f\u00edsicas y t\u00e1ctiles a la vez que apostar por experiencias imposibles, transitar por lugares inexistentes o acechar a animales mitol\u00f3gicos. Es un ejercicio que exige derrochar imaginaci\u00f3n para encontrar lugares que est\u00e1n m\u00e1s all\u00e1 del Google Maps y seres u objetos perdidos en la noche de los tiempos.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/un-2020-sin-existencia-real\/tutankamon-ifema\/\" rel=\"attachment wp-att-28425\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28425\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/Tutankam\u00f3n-IFEMA-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/Tutankam\u00f3n-IFEMA-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/Tutankam\u00f3n-IFEMA-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/01\/Tutankam\u00f3n-IFEMA-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Todav\u00eda no tengo muy claro c\u00f3mo hacerlo, pero la exposici\u00f3n sobre Tutankam\u00f3n en IFEMA es un buen comienzo: lo m\u00e1s importante que hay en ella es la audiogu\u00eda, sin cuyo concurso, el recorrido carece de sentido o inter\u00e9s, dado que no hay una sola pieza original. Y, aun as\u00ed, resulta apasionante. Como la exposici\u00f3n inmersiva en la obra de Van Gogh que se puede disfrutar en el C\u00edrculo de Bellas Artes. La nada, m\u00e1s hermosa que nunca.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estoy con los prop\u00f3sitos de A\u00f1o Nuevo. Pero antes de nada, feliz 2020. \u00bfC\u00f3mo lo llevan? Imagino que bien, salvo que confiaran en el reloj de Plaza del Carmen para comerse las uvas, claro. \u00a1Qu\u00e9 cosas pasan en esta Granada nuestra! Pero no se preocupen. Ya ver\u00e1n como lo de tremolar el pend\u00f3n sale a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[18641,18643,18642],"class_list":["post-28423","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-2020-sin-existencia-real","tag-el-rey-leon-musical","tag-tutankamon-ifema"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28423"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28423\/revisions"}],"predecessor-version":[{"id":28427,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28423\/revisions\/28427"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}