{"id":28218,"date":"2019-12-02T12:53:25","date_gmt":"2019-12-02T11:53:25","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28218"},"modified":"2019-12-02T12:53:25","modified_gmt":"2019-12-02T11:53:25","slug":"cine-y-trabajo-sostenible","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/cine-y-trabajo-sostenible\/","title":{"rendered":"Cine y trabajo sostenible"},"content":{"rendered":"<p>\u2018Black Mirror\u2019, de la que hemos hablado mucho y bien en otras ocasiones, es una serie visionaria que alerta sobre un futuro dist\u00f3pico provocado por los excesos y el abuso de la tecnolog\u00eda. Cada vez que se estrena una nueva temporada, arden las redes y los peri\u00f3dicos se llenan de sesudos an\u00e1lisis sociol\u00f3gicos sobre el abismo hacia el que nos dirigimos.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cine-y-trabajo-sostenible\/sorry-we-missed-you\/\" rel=\"attachment wp-att-28219\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28219\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-We-missed-you-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-We-missed-you-200x300.jpg 200w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-We-missed-you.jpg 400w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p>El cine Madrigal proyecta ahora mismo una pel\u00edcula imprescindible, \u2018Sorry, We Missed You\u2019, del combativo y octogenario director Ken Loach. Los protagonistas son los cuatro miembros de una familia que fue de clase media pero que hoy se precipita peligrosamente hacia la pobreza. Para tratar de revertir la situaci\u00f3n, el padre se convierte en aut\u00f3nomo, se compra una furgoneta y comienza a trabajar como repartidor para una de esas nuevas y molonas empresas tecnol\u00f3gicas. La clave para hacer bien su trabajo es obedecer las instrucciones de una m\u00e1quina que lo mismo le muestra las mejores rutas para llegar a su destino que sirve para comprobar la recepci\u00f3n de los pedidos y seguir su trazabilidad. Un terminal que lo sabe todo, incluso el tiempo que el conductor pasa fuera de la furgoneta, chiv\u00e1ndose con una alarma.<\/p>\n<p>Nada de lo que cuenta Loach es ciencia ficci\u00f3n. La autoexplotaci\u00f3n a la que se someten los protagonistas, echando jornadas de 14 horas diarias y teniendo que mear en una botella de pl\u00e1stico para no perder tiempo y entregar la mercanc\u00eda en hora, ocurre aqu\u00ed y ahora. Lo hemos visto con el caso de los falsos aut\u00f3nomos de Glovo, sin ir m\u00e1s lejos.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cine-y-trabajo-sostenible\/sorry-ken-loach\/\" rel=\"attachment wp-att-28220\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28220\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-Ken-Loach-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-Ken-Loach-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-Ken-Loach-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-Ken-Loach-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/12\/Sorry-Ken-Loach.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los consumidores nos hemos vuelto tan exigentes, queri\u00e9ndolo todo y queri\u00e9ndolo ya en la puerta de nuestra casa, que fomentamos una nueva modalidad de trabajo precario que empobrece a la sociedad.<\/p>\n<p>Dentro de un par de semanas, en el programa \u2018Los ODS, de cine\u2019 que est\u00e1 desarrollando la plataforma Granada4Energy en la ETS de Ingenier\u00eda de Caminos, Canales y Puertos, hablaremos de todo ello. Los Objetivos de Desarrollo Sostenible incluyen el de \u2018fomentar el crecimiento econ\u00f3mico sostenido, inclusivo y sostenible, el empleo pleno y productivo, y el trabajo decente para todos\u2019. Los cineastas Ken Loach y Robert Gu\u00e9diguian ser\u00e1n nuestros ejemplares e imprescindibles gu\u00edas cin\u00e9filos.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2018Black Mirror\u2019, de la que hemos hablado mucho y bien en otras ocasiones, es una serie visionaria que alerta sobre un futuro dist\u00f3pico provocado por los excesos y el abuso de la tecnolog\u00eda. Cada vez que se estrena una nueva temporada, arden las redes y los peri\u00f3dicos se llenan de sesudos an\u00e1lisis sociol\u00f3gicos sobre el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,6],"tags":[18495,9139,18493,18490,18494,18492,18496,18491],"class_list":["post-28218","post","type-post","status-publish","format-standard","hentry","category-cine","category-opinion","tag-cine-ken-loach","tag-cine-madrigal","tag-cine-y-ods","tag-falsos-autonomos","tag-objetivos-desarrollo-sostenible","tag-ods-de-cine","tag-robert-guediguian","tag-sorry-we-missed-you"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28218"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28218\/revisions"}],"predecessor-version":[{"id":28222,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28218\/revisions\/28222"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}