{"id":28170,"date":"2019-11-21T14:03:23","date_gmt":"2019-11-21T13:03:23","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28170"},"modified":"2019-11-25T14:08:30","modified_gmt":"2019-11-25T13:08:30","slug":"de-infamias-balas-y-hongos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/de-infamias-balas-y-hongos\/","title":{"rendered":"De infamias, balas y hongos"},"content":{"rendered":"<p>Hoy les quiero hablar de tres de mis lecturas m\u00e1s recientes, muy diferentes entre s\u00ed aunque sean bien negras y bien criminales. Comencemos por la \u2018Infamia\u2019 de Ledicia Costas, autora gallega con un amplio bagaje en literatura infantil y juvenil, cuyo Premio Nacional gan\u00f3 hace unos a\u00f1os, y que da el salto a la novela negra con una historia corta, seca y contundente.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/de-infamias-balas-y-hongos\/bajo-cero-koepp\/\" rel=\"attachment wp-att-28171\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28171\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bajo-cero-koepp-186x300.jpg\" alt=\"\" width=\"186\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bajo-cero-koepp-186x300.jpg 186w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bajo-cero-koepp.jpg 613w\" sizes=\"auto, (max-width: 186px) 100vw, 186px\" \/><\/a><\/p>\n<p>La trama arranca con la llegada de Emma Cruz a un peque\u00f1o pueblo llamado Merlo, lo suficientemente cercano a la Facultad de Derecho donde va a impartir clases, pero lo necesariamente aislado como para tratar de retirarse del mundanal ruido, buscando ordenar sus ideas\u2026 y sus sentimientos.<\/p>\n<p>Merlo la recibe como todos los pueblos peque\u00f1os, con una mezcla de suspicacia y curiosidad acrecentada por la celebraci\u00f3n un triste aniversario: los 25 a\u00f1os de la desaparici\u00f3n de dos ni\u00f1as, las hermanas Giraud, de 6 y 13 a\u00f1os de edad. Una desaparici\u00f3n que qued\u00f3 sin resolver, para escarnio y dolor de una comunidad que todav\u00eda no ha superado el trauma.<\/p>\n<p>A partir de aqu\u00ed, \u2018Infamia\u2019, publicada por la editorial Destino, desgrana una historia dura y descarnada en la que, m\u00e1s all\u00e1 de las culpabilidades y la resoluci\u00f3n del misterio, la autora se centra en las motivaciones y, sobre todo, en las consecuencias de la ejecuci\u00f3n de actos violentos en el seno de una comunidad peque\u00f1a donde todo el mundo se conoce. Una novela de denuncia de una sociedad machista y hom\u00f3foba que nos confronta con nuestras propias contradicciones, sean por acci\u00f3n o por omisi\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/de-infamias-balas-y-hongos\/infamila-ledicia-costas\/\" rel=\"attachment wp-att-28172\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28172\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Infamila-Ledicia-Costas-176x300.jpg\" alt=\"\" width=\"176\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Infamila-Ledicia-Costas-176x300.jpg 176w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Infamila-Ledicia-Costas.jpg 250w\" sizes=\"auto, (max-width: 176px) 100vw, 176px\" \/><\/a><\/p>\n<p>La escritora navarra Susana Rodr\u00edguez Lezaun cambia de registro en \u2018Una bala con mi nombre\u2019, publicada por Harper Collins Ib\u00e9rica, y nos traslada a Massachusetts, en la Costa Este de los Estados Unidos, donde conoceremos a Zoe Bennett, una seria restauradora del Museo de Bellas Artes de Boston que se ve sumergida en un torbellino de acci\u00f3n y misterio.<\/p>\n<p>\u2018Una bala con mi nombre\u2019 es una novela que gustar\u00e1 a los amantes de las tramas con robos de piezas art\u00edsticas de valor singular y a los aficionados a las historias de amor fou, loco y tempestuoso. Una novela que se lee a la velocidad del rayo y que resulta de lo m\u00e1s entretenida.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/de-infamias-balas-y-hongos\/una-bala-con-mi-nombre\/\" rel=\"attachment wp-att-28173\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28173\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Una-bala-con-mi-nombre-205x300.jpg\" alt=\"\" width=\"205\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Una-bala-con-mi-nombre-205x300.jpg 205w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Una-bala-con-mi-nombre.jpg 353w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/a><\/p>\n<p>Igualmente publicada por Harper Collins Ib\u00e9rica, nos llega \u2018Bajo cero\u2019 un thriller desternillante en el que un posible fin del mundo se da la mano con una panda de protagonistas a cada cu\u00e1l m\u00e1s loco y zumbado.<\/p>\n<p>El autor de la novela es David Koepp, reconocido guionista de pel\u00edculas tan famosas de la historia del cine como \u2018Parque Jur\u00e1sico\u2019, \u2018Misi\u00f3n: Imposible\u2019, \u2018La guerra de los mundos\u2019 o una de las \u00faltimas obras maestras del Brian De Palma m\u00e1s noir, \u2018Carlito\u2019s Way\u2019, estrenada en Espa\u00f1a con el t\u00edtulo de \u2018Atrapado por su pasado\u2019 y en la que Al Pacino hace una de las grandes interpretaciones de su carrera.<\/p>\n<p>Con m\u00e1s de 30 guiones a sus espaldas, Koepp escribe \u2018Bajo cero\u2019 imprimi\u00e9ndole un indudable ritmo cinematogr\u00e1fico, a trav\u00e9s de cap\u00edtulos que funcionan como las secuencias de una pel\u00edcula y en las que el lector visualiza im\u00e1genes a un ritmo vertiginoso.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/de-infamias-balas-y-hongos\/bajo-cero-david-koepp\/\" rel=\"attachment wp-att-28174\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28174\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bajo-cero-David-Koepp-205x300.jpg\" alt=\"\" width=\"205\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bajo-cero-David-Koepp-205x300.jpg 205w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bajo-cero-David-Koepp.jpg 341w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/a><\/p>\n<p>La novela parte de un hecho inquietante: la aparici\u00f3n de un misterioso hongo en una remota localidad australiana donde cayeron los restos de cierta basura espacial. Se trata de un organismo inteligente con una proverbial capacidad mutante y con una letal capacidad destructora de cualquier forma de vida que se le ponga a tiro.<\/p>\n<p>Tres miembros de un equipo especializado del Pent\u00e1gono acuden a Australia y consiguen encapsular al hongo. Lo depositan en unas instalaciones del gobierno perfectamente adecuadas para albergar y estudiar este tipo de fenomenolog\u00edas y siguen con su vida. Hasta que, varios a\u00f1os despu\u00e9s, ya jubilado, Robert Diaz recibe una llamada de tel\u00e9fono a altas horas de la madrugada\u2026<\/p>\n<p>Las 300 p\u00e1ginas de \u2018Bajo cero\u2019 son adrenalina pura. Una vez que empiezas a leerlas, buscas cualquier excusa para no hacer lo que quiera que debas hacer con tal de seguir leyendo. La acci\u00f3n se sucede entre el terror bacteriano y apocal\u00edptico y el humor m\u00e1s desopilante. Hay referencias a mil y una pel\u00edculas y a series de televisi\u00f3n tan populares como las de zombis. Pero sin que la novela sea de zombis. Ustedes me entienden. Adem\u00e1s, los protagonistas son enormes perdedores que, sobre el papel, lo tienen todo en contra. Y, sin embargo\u2026<\/p>\n<p>\u2018Infamia\u2019, \u2018Una bala con mi nombre\u2019 y \u2018Bajo cero\u2019 son tres novelas muy diferentes entre s\u00ed que demuestran la enorme versatilidad y variedad de un g\u00e9nero negro que no se agota nunca. Desde las historias de denuncia m\u00e1s asfixiantes a una desprejuiciada novela sobre atracos protagonizada por un personaje tan improbable como encantador, pasando por una \u00e1cida cr\u00edtica a un mundo que no cree en la emergencia clim\u00e1tica que nos amenaza con llevarnos por delante, que precariza a su juventud y que deja en manos de cualquier chupatintas cuestiones tan importantes como la de la seguridad nacional. E internacional. Y global.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy les quiero hablar de tres de mis lecturas m\u00e1s recientes, muy diferentes entre s\u00ed aunque sean bien negras y bien criminales. Comencemos por la \u2018Infamia\u2019 de Ledicia Costas, autora gallega con un amplio bagaje en literatura infantil y juvenil, cuyo Premio Nacional gan\u00f3 hace unos a\u00f1os, y que da el salto a la novela [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,21,11774],"tags":[18454,18455,18456,11263,14859,18458,18459,18461,18460,18457],"class_list":["post-28170","post","type-post","status-publish","format-standard","hentry","category-literarios","category-negra-y-criminal","category-rincon-oscuro","tag-bajo-cero","tag-bajo-cero-harper-collins","tag-bajo-cero-koepp","tag-david-koepp","tag-el-rincon-oscuro-jesus-lens","tag-infamia","tag-infamia-ledicia-costas","tag-ledicia-costas","tag-susana-rodriguez-lezaun","tag-una-bala-con-mi-nombre"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28170"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28170\/revisions"}],"predecessor-version":[{"id":28176,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28170\/revisions\/28176"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}