{"id":28140,"date":"2019-11-20T20:02:52","date_gmt":"2019-11-20T19:02:52","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28140"},"modified":"2019-11-23T20:07:25","modified_gmt":"2019-11-23T19:07:25","slug":"repensar-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/repensar-granada\/","title":{"rendered":"Repensar Granada"},"content":{"rendered":"<p>Lo ha vuelto a decir, otra vez, el alcalde Granada. A Luis Salvador, me refiero, por si a alguien le cupiese alguna duda. \u201cUna oportunidad para repensar la ciudad\u201d, se\u00f1al\u00f3 al hablar sobre el 2031 y la candidatura a la Capitalidad Europea de la Cultura.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/repensar-granada\/aranda-capitalidad\/\" rel=\"attachment wp-att-28142\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28142\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Aranda-Capitalidad-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Aranda-Capitalidad-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Aranda-Capitalidad.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Digo que lo ha vuelto a decir porque, en su momento, ya lo expres\u00f3 as\u00ed el anterior alcalde granadino, Paco Cuenca. La pena es que, inmediatamente despu\u00e9s, el consistorio encabezado por los socialistas se desentendi\u00f3 del tema.<\/p>\n<p>Luis Salvador ha hecho bandera del 2031 desde el d\u00eda en que tom\u00f3 posesi\u00f3n del cargo. L\u00e1stima que, desde entonces, hayamos perdido un par de festivales de cine y otro de t\u00edteres por el camino. Y el de fotograf\u00eda. El Festival Internacional de Jazz ha quedado reducido a su m\u00ednima expresi\u00f3n y el Premio Garc\u00eda Lorca de Poes\u00eda viene con m\u00e1s calma que las obras del AVE barato a Sevilla.<\/p>\n<p>Est\u00e1 bien repensar la Granada cultural que queremos en el 2031, pero a este paso, lo mismo nos encontramos con la de 1950.<\/p>\n<p>Menos mal que Pilar Aranda, la rectora magn\u00edfica de nuestra UGR, ejerce como tal y apela a cosas tan sensatas como establecer una nueva dimensi\u00f3n en la relaci\u00f3n entre ciudad y universidad, creando el neologismo \u2018Universidad ciudadana\u2019, sobre el que debemos reflexionar mucho y bien.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/repensar-granada\/aranda-acelerador\/\" rel=\"attachment wp-att-28144\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28144\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Aranda-acelerador-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Aranda-acelerador-300x186.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Aranda-acelerador.jpg 621w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El concepto apela a la tradicional generaci\u00f3n y transmisi\u00f3n del conocimiento, pero unido a la proyecci\u00f3n social de la actividad universitaria m\u00e1s all\u00e1 del \u00e1mbito econ\u00f3mico, tecnol\u00f3gico, cultural o divulgativo.<\/p>\n<p>Confieso que, escuchadas en boca de otro, dudar\u00eda del valor de esas palabras. Las considerar\u00eda una declaraci\u00f3n de principios. Un brindis al sol. Que vengan de Pilar Aranda, sin embargo, les confiere un valor especial.<\/p>\n<p>La UGR es el gran agente cultural de la Granada del siglo XXI. Hay que destacar y reivindicar, sobre todo, el tit\u00e1nico trabajo que hace La Madraza, el Centro de Cultura Contempor\u00e1nea que dirige Ricardo Anguita. Cine, m\u00fasica, arte, c\u00f3mic, literatura, conferencias\u2026 todas las disciplinas art\u00edsticas encuentran espacio en una programaci\u00f3n que es para quitarse el sombrero. Formas de creer, de verdad, en el 2031.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo ha vuelto a decir, otra vez, el alcalde Granada. A Luis Salvador, me refiero, por si a alguien le cupiese alguna duda. \u201cUna oportunidad para repensar la ciudad\u201d, se\u00f1al\u00f3 al hablar sobre el 2031 y la candidatura a la Capitalidad Europea de la Cultura. Digo que lo ha vuelto a decir porque, en su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[18441,17685,18438,18440,18439],"class_list":["post-28140","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-luis-salvador-capitalidad-cultural","tag-pilar-aranda","tag-pilar-aranda-capitalidad","tag-pilar-aranda-universidad-ciudadana","tag-universidad-ciudadana"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28140"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28140\/revisions"}],"predecessor-version":[{"id":28146,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28140\/revisions\/28146"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}