{"id":28081,"date":"2019-11-12T21:09:31","date_gmt":"2019-11-12T20:09:31","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28081"},"modified":"2019-11-13T21:10:53","modified_gmt":"2019-11-13T20:10:53","slug":"13-2","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/13-2\/","title":{"rendered":"1+3"},"content":{"rendered":"<p>Es lo que tiene ver demasiadas series de televisi\u00f3n: terminas crey\u00e9ndote un showrunner todopoderoso y mol\u00f3n, capaz de controlar todos los giros de guion hasta llegar el desenlace deseado. La pol\u00edtica, sin embargo, es veleidosa, caprichosa e imprevisible. \u00a1Que se lo digan a tanto gur\u00fa visionario, anta\u00f1o conocido como consejero \u00e1ulico!<\/p>\n<p>Al despertar, el dinosaurio segu\u00eda all\u00ed. Pero m\u00e1s gordo, m\u00e1s grande y mucho m\u00e1s crecido y rugiente. De una gobernabilidad complicada, Espa\u00f1a ha desembocado en una gobernabilidad imposible, salvo movimientos inesperados.<\/p>\n<p>Dejando al margen las c\u00e1balas y los apresurados an\u00e1lisis de las \u00faltimas horas, la mayor\u00eda de ellos m\u00e1s basados en deseos que en realidades posibles o probables, centr\u00e9monos en Granada capital, donde Sebasti\u00e1n P\u00e9rez ha estado quieto y callado\u2026 hasta ahora.<\/p>\n<p>Tras la fallida operaci\u00f3n Puente de Plata senatorial, Sebasti\u00e1n P\u00e9rez se queda en casa. El PP ha ganado en Granada capital y Ciudadanos ha quedado laminado. \u00bfC\u00f3mo afectar\u00e1n los resultados del domingo a la alcald\u00eda de Luis Salvador? Habr\u00e1 que estar atentos al congreso extraordinario del partido naranja, pero los proyectos personalistas son muy dif\u00edciles de reencauzar cuando hacen aguas.<\/p>\n<p>Que las del 10-N no eran elecciones municipales, lo sabemos todos. Que la llegada de Salvador a la alcald\u00eda fue rocambolesca, tambi\u00e9n. Si gobernar con 4 concejales estaba siendo tarea harto dif\u00edcil, como el actual alcalde se empe\u00f1e en seguir neg\u00e1ndole el 2+2 a Sebasti\u00e1n P\u00e9rez, ser\u00e1 misi\u00f3n imposible.<\/p>\n<p>No es halag\u00fce\u00f1o el panorama para la capital granadina. Con el horizonte judicial de Paco Cuenca sin despejar, el auge de Vox y la debacle de Ciudadanos no hacen sino enmara\u00f1ar el futuro. El presupuesto, por ejemplo. \u00bfSer\u00e1n capaces de ponerse de acuerdo PP, Cs y Vox para sacar adelante un presupuesto, en estas condiciones? \u00bfSer\u00e1 requisito sine qua non dejar resuelto lo del 2+2?<\/p>\n<p>Malos tiempos para la l\u00edrica. Peores a\u00fan para la pol\u00edtica. El ruido de fondo que nos espera en las pr\u00f3ximas semanas no har\u00e1 sino alejarnos la cruda realidad de un gobierno precario, tanto all\u00ed como aqu\u00ed. Lo mismo, del 2+2 se empieza a hablar del 1+3\u2026<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es lo que tiene ver demasiadas series de televisi\u00f3n: terminas crey\u00e9ndote un showrunner todopoderoso y mol\u00f3n, capaz de controlar todos los giros de guion hasta llegar el desenlace deseado. La pol\u00edtica, sin embargo, es veleidosa, caprichosa e imprevisible. \u00a1Que se lo digan a tanto gur\u00fa visionario, anta\u00f1o conocido como consejero \u00e1ulico! Al despertar, el dinosaurio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[18407,17798,12338,1830],"class_list":["post-28081","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-18407","tag-alcalde-de-granada","tag-luis-salvador","tag-sebastian-perez"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28081"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28081\/revisions"}],"predecessor-version":[{"id":28082,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28081\/revisions\/28082"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}