{"id":28075,"date":"2019-11-13T21:06:29","date_gmt":"2019-11-13T20:06:29","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28075"},"modified":"2019-11-13T21:06:29","modified_gmt":"2019-11-13T20:06:29","slug":"se-armara-el-belen","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/se-armara-el-belen\/","title":{"rendered":"Se armar\u00e1 el Bel\u00e9n"},"content":{"rendered":"<p>Que soy feliz viajando, ya lo saben ustedes. Que cada vez disfruto m\u00e1s de los periplos de interior, cercanos y por paisajes familiares, tambi\u00e9n. Alejarse del entorno, aunque sea durante tres d\u00edas, es esencial para oxigenarse y desintoxicarse (pronunciar con el acento de Superrat\u00f3n): tomar distancias nos permite tener una visi\u00f3n de conjunto a la vez que nos hace relativizar las cosas de casa.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/se-armara-el-belen\/belen-napolitano\/\" rel=\"attachment wp-att-28076\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28076\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-napolitano-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-napolitano-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-napolitano-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-napolitano-644x859.jpg 644w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>El pasado lunes, por ejemplo, andaba por Murcia tras disfrutar de las bondades de Cartagena. Despu\u00e9s de un paseo por la Catedral y sus alrededores y de hacer un alto para comprar unas salazones, visitamos el Casino, un monumental edificio recientemente restaurado que nos conecta con los tiempos de los ateneos, los c\u00edrculos culturales y las asociaciones de amigos del pa\u00eds; cuando internet s\u00f3lo era una fantas\u00eda y la sociedad civil se reun\u00eda con afecto, calidez y frecuencia.<\/p>\n<p>Me encant\u00f3 la sala \u00e1rabe, un pastiche entre lo kistch y lo naif que, sin embargo, rebosa de encanto. Como la biblioteca inglesa o la sala de esgrima. \u00a1Qu\u00e9 lujazo! En los m\u00e1s amplios sentidos de la expresi\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/se-armara-el-belen\/belen-napolitano-salzillo\/\" rel=\"attachment wp-att-28077\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28077\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-Salzillo-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-Salzillo-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-Salzillo-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-Salzillo-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pero lo mejor de todo fue el Museo Salzillo. Les confieso que lo visit\u00e9 con un cierto escepticismo, que la imaginer\u00eda religiosa y la iconograf\u00eda de Semana Santa no son dos de mis pasiones, precisamente. Sin embargo, y al margen de los pasos del Viernes Santo murciano, alucin\u00e9 con sus dos belenes.<\/p>\n<p>Adem\u00e1s del exuberante Bel\u00e9n del propio Salzillo, salvado de ser vendido por piezas gracias a una suscripci\u00f3n popular y al propio ayuntamiento de Murcia, resulta obligatorio visitar el monumental Bel\u00e9n Napolitano reunido por los hermanos Garc\u00eda de Castro, compuesto por 600 piezas fabricadas en el siglo XVIII.<\/p>\n<p>Se trata de un Bel\u00e9n eminentemente laico y de car\u00e1cter popular, narrativo, protagonizado por decenas y decenas de personajes de la calle, representantes de oficios varios de la propia N\u00e1poles de aquellos a\u00f1os.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/se-armara-el-belen\/belen-napolitano-cajagranada\/\" rel=\"attachment wp-att-28078\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28078\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-CajaGranada-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-CajaGranada-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-CajaGranada-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Bel\u00e9n-Napolitano-CajaGranada-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pero si no tienen previsto ir a Murcia pr\u00f3ximamente, no se preocupen: CajaGranada Fundaci\u00f3n y Bankia ya se est\u00e1n preparando para armar el Bel\u00e9n en el centro de exposiciones de Puerta Real, dentro de unas semanas.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que soy feliz viajando, ya lo saben ustedes. Que cada vez disfruto m\u00e1s de los periplos de interior, cercanos y por paisajes familiares, tambi\u00e9n. Alejarse del entorno, aunque sea durante tres d\u00edas, es esencial para oxigenarse y desintoxicarse (pronunciar con el acento de Superrat\u00f3n): tomar distancias nos permite tener una visi\u00f3n de conjunto a la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[33,6],"tags":[18402,18406,18404,18405,18403],"class_list":["post-28075","post","type-post","status-publish","format-standard","hentry","category-arte","category-opinion","tag-belen","tag-belen-cajagranada","tag-belen-napolitano","tag-belen-salzillo","tag-se-armo-el-belen"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28075"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28075\/revisions"}],"predecessor-version":[{"id":28080,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28075\/revisions\/28080"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}