{"id":28008,"date":"2019-11-02T17:54:38","date_gmt":"2019-11-02T16:54:38","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=28008"},"modified":"2019-11-02T17:54:38","modified_gmt":"2019-11-02T16:54:38","slug":"el-gran-instigador","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-gran-instigador\/","title":{"rendered":"El Gran Instigador"},"content":{"rendered":"<p>Pasamos el mejor Halloween posible en el Lemon Rock, celebrando su cuarto cumplea\u00f1os de la mano de Jorge Rodr\u00edguez Morata, El Gran Instigador, en afortunada definici\u00f3n de ese genio \u2014nunca nos cansaremos de reivindicarlo\u2014 que es Antonio Arias.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-gran-instigador\/antonio-arias-jesus-lens\/\" rel=\"attachment wp-att-28009\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28009\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Antonio-Arias-Jes\u00fas-Lens-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Antonio-Arias-Jes\u00fas-Lens-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Antonio-Arias-Jes\u00fas-Lens-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/Antonio-Arias-Jes\u00fas-Lens-644x859.jpg 644w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>No s\u00e9 si fue casualidad, pero reunirnos la Noche de los Muertos para disfrutar de semejante pedazo de concierto tuvo todo el sentido del mundo. Del terrenal y del del M\u00e1s All\u00e1.<\/p>\n<p>El Coro de la UGR nos convoc\u00f3 a un cita en que hizo un amplio y completo repaso de sus \u00faltimos trabajos. Por ejemplo, de algunos de los temas que interpretaron en la boda de Guille y Eric, el bater\u00eda de Lagartija Nick y Los Planetas, con cositas tan maravillosas como \u2018Life or Mars\u2019.<\/p>\n<p>A continuaci\u00f3n, de la mano del extraordinario actor V\u00edctor Burgos, disfrutamos de varios fragmentos del espect\u00e1culo \u2018Bandas Mon\u00f3logas\u2019, producido por el festival Granada Noir y estrenado en el Teatro CajaGranada hace unas semanas. \u00a1Ay, ese Al Pacino interpretando al mism\u00edsimo Satan\u00e1s y la reivindicaci\u00f3n de la buena suerte que hizo Fernando Le\u00f3n de Aranoa en \u2018Princesas\u2019, con m\u00fasica de Manu Chao!<\/p>\n<p>Lleg\u00f3 el turno de David Monta\u00f1\u00e9s y sus \u2018Bodas alqu\u00edmicas\u2019, de cuyo estreno pudimos gozar en la iglesia de Pampaneira, el pasado agosto, durante el festival Sulayr. Y, como guinda del pastel, cuatro temas de Antonio Arias, con su hermano Jes\u00fas en el recuerdo de todos los presentes. Sonaron temas de \u2018Los cielos cabizbajos\u2019, esa obra maestra, tan desgarradoramente triste como luminosa, que no deben perderse.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-gran-instigador\/david-montanes-jesus-lens\/\" rel=\"attachment wp-att-28010\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-28010\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/David-Monta\u00f1\u00e9s-Jes\u00fas-Lens-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/David-Monta\u00f1\u00e9s-Jes\u00fas-Lens-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/David-Monta\u00f1\u00e9s-Jes\u00fas-Lens-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/11\/David-Monta\u00f1\u00e9s-Jes\u00fas-Lens-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Que la noche de los muertos se interpretaran las canciones compuestas por Jes\u00fas en memoria de los fallecidos en los bombardeos Somalia, Hiroshima y Sarajevo, fue un acto de justicia po\u00e9tica que nos puso los pelos como escarpias.<\/p>\n<p>\u201c\u00bfCon qu\u00e9 est\u00e1s ahora?\u201d Es lo primero que le pregunto a ese Gran Instigador que es Jorge, siempre que nos vemos. Porque su cabeza bulle de brillantes ideas y vibrantes proyectos que suelen llegar a buen puerto. Les anticipo que la que est\u00e1 preparando con ocasi\u00f3n del quinto centenario de la primera vuelta al mundo, es de \u00f3rdago a la grande.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/jesus_lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pasamos el mejor Halloween posible en el Lemon Rock, celebrando su cuarto cumplea\u00f1os de la mano de Jorge Rodr\u00edguez Morata, El Gran Instigador, en afortunada definici\u00f3n de ese genio \u2014nunca nos cansaremos de reivindicarlo\u2014 que es Antonio Arias. No s\u00e9 si fue casualidad, pero reunirnos la Noche de los Muertos para disfrutar de semejante pedazo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17,6],"tags":[13483,17340,17339,17338,15862],"class_list":["post-28008","post","type-post","status-publish","format-standard","hentry","category-musica","category-opinion","tag-antonio-arias","tag-coro-ugr","tag-david-montanes","tag-jorge-rodriguez-morata","tag-lemon-rock"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28008"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28008\/revisions"}],"predecessor-version":[{"id":28012,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28008\/revisions\/28012"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=28008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=28008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=28008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}