{"id":27997,"date":"2019-10-31T06:34:21","date_gmt":"2019-10-31T05:34:21","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27997"},"modified":"2019-10-30T19:36:36","modified_gmt":"2019-10-30T18:36:36","slug":"ciclon-en-el-pts","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ciclon-en-el-pts\/","title":{"rendered":"Cicl\u00f3n en el PTS"},"content":{"rendered":"<p>Que Jes\u00fas Quero haya salido a defender furibundamente las cuentas del PTS entra dentro de lo l\u00f3gico y lo normal, que para algo ha estado al frente de uno de los mascarones de proa del desarrollo t\u00e9cnico, cient\u00edfico y econ\u00f3mico de Granada durante a\u00f1os y a\u00f1os.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=27998\" rel=\"attachment wp-att-27998\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27998\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/PTS-Granada-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/PTS-Granada-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/PTS-Granada.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La cosa comenz\u00f3 el lunes, cuando el consejero de Econom\u00eda, Conocimiento, Empresas y Universidad de la Junta de Andaluc\u00eda, Rogelio Velasco, hac\u00eda saltar las alarmas, anunciando el rescate del Parque Tecnol\u00f3gico de la Salud y una auditor\u00eda que sirva para depurar responsabilidades por una presunta mala gesti\u00f3n y un agujero de 18 millones de euros.<\/p>\n<p>Las reacciones no se hicieron esperar, con un cruce de acusaciones, datos y partidas presupuestarias que cuestionan muy seriamente la acusaci\u00f3n del consejero. Sobre todo, porque las cuentas de la Fundaci\u00f3n PTS han sido aprobadas por unanimidad este 2019. Y en esa unanimidad est\u00e1 la Junta, claro. Adem\u00e1s, la rectora de la Universidad de Granada, Pilar Aranda, ha sido muy taxativa al se\u00f1alar que \u201cla situaci\u00f3n econ\u00f3mica del PTS es de las mejores de los parques de Espa\u00f1a\u201d.<\/p>\n<p>As\u00ed las cosas, no queda m\u00e1s remedio que entender en clave electoralista la cortina de humo extendida por el consejero Velasco en torno al PTS. Electoralista e insensata, tambi\u00e9n. \u00bfPor qu\u00e9 no denuncia la mala gesti\u00f3n previa en los tribunales, de haber sospechas fundadas sobre la misma? \u00bfY c\u00f3mo es eso de que va a solicitar una auditor\u00eda? \u00bfAhora? \u00a1Que el bipartito ya lleva en San Telmo un pu\u00f1ado de meses!<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=27999\" rel=\"attachment wp-att-27999\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27999\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Gobierno-Cambio-Andaluz-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Gobierno-Cambio-Andaluz-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Gobierno-Cambio-Andaluz-768x512.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Gobierno-Cambio-Andaluz-644x429.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Gobierno-Cambio-Andaluz.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Lo que nos lleva a hacernos otras preguntas. La primera y m\u00e1s inmediata: \u00bfqu\u00e9 pas\u00f3 con tanta auditor\u00eda prometida, precisamente, a la llegada de PP y Cs al gobierno andaluz? \u00bfQu\u00e9 hay de la famosa limpieza de cajones? \u00bfY de la mugre camuflada bajo las alfombras, tras a\u00f1os y a\u00f1os de gobierno del PSOE?<\/p>\n<p>Una vez m\u00e1s se demuestra que nuestros pol\u00edticos se encuentran mucho m\u00e1s c\u00f3modos en la oposici\u00f3n que mandando. \u00a1Qu\u00e9 ganas de conocer el balance del primer a\u00f1o del llamado gobierno del cambio! Ver\u00e1s t\u00fa que, al final, contra Susana viv\u00edan mejor.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/jesus_lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que Jes\u00fas Quero haya salido a defender furibundamente las cuentas del PTS entra dentro de lo l\u00f3gico y lo normal, que para algo ha estado al frente de uno de los mascarones de proa del desarrollo t\u00e9cnico, cient\u00edfico y econ\u00f3mico de Granada durante a\u00f1os y a\u00f1os. La cosa comenz\u00f3 el lunes, cuando el consejero de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[18340,18342,18341,10152,18339],"class_list":["post-27997","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-18-millones","tag-agujero-pts","tag-escandalo-pts","tag-pts","tag-rogelio-velasco"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27997"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27997\/revisions"}],"predecessor-version":[{"id":28000,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27997\/revisions\/28000"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}