{"id":27963,"date":"2019-10-25T13:46:19","date_gmt":"2019-10-25T12:46:19","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27963"},"modified":"2019-10-26T13:59:09","modified_gmt":"2019-10-26T12:59:09","slug":"faltan-granadas-en-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/faltan-granadas-en-granada\/","title":{"rendered":"Faltan granadas en Granada"},"content":{"rendered":"<p>Uno cree que sabe de algo hasta que empieza a estudiar un tema en profundidad y cobra socr\u00e1tica conciencia de que apenas sab\u00eda nada. Me ha pasado estos d\u00edas con una fruta que, por l\u00f3gica y cercan\u00eda, deber\u00eda resultarnos de lo m\u00e1s conocida, habitual y cercana. Y sin embargo\u2026<a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/faltan-granadas-en-granada\/granadas-lens\/\" rel=\"attachment wp-att-27965\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27965\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granadas-Lens-230x300.jpg\" alt=\"\" width=\"230\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granadas-Lens-230x300.jpg 230w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granadas-Lens-644x841.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granadas-Lens.jpg 735w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a>No les voy a glosar las bondades de la granada. Les emplazo a unas p\u00e1ginas m\u00e1s adelante de este IDEAL, al suplemento Gourmet de hoy viernes, donde hemos preparado un completo reportaje especial sobre ella. (Leer <a href=\"https:\/\/gourmet.ideal.es\/actualidad\/fruta-granado-20191025215825-nt.html\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>)<\/p>\n<p>Lo resumir\u00e9 en dos palabras: sen-sacional. La granada es prodigiosa, en todos los sentidos de la palabra, desde lo puramente culinario a lo nutricional. Es una de esas s\u00faper-frutas que suponen un chute de salud en vena y que ofrecen infinidad de posibilidades gastron\u00f3micas, en fruto o en jugo. Pero ya les digo que, si les pica la curiosidad, lean el Gourmet.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/faltan-granadas-en-granada\/granada-lens\/\" rel=\"attachment wp-att-27964\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27964\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Lens-229x300.jpg\" alt=\"\" width=\"229\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Lens-229x300.jpg 229w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Lens-644x843.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Lens.jpg 733w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/a><\/p>\n<p>Lo que me ha llamado poderosamente la atenci\u00f3n es la poca presencia de las granadas en la oferta gastron\u00f3mica de Granada. Como me dec\u00eda el chef Chechu Gonz\u00e1lez, de Mar\u00eda de la O, faltan granadas en Granada. De hecho, en el patio de su restaurante hay algunos granados y est\u00e1 terminando de ultimar un postre para servir en un molde que reproduzca sobre el plato su singular forma. Que, como le dec\u00eda Antonio Arias a Chechu, vivimos en una tierra con nombre de bomba. \u00a1Ah\u00ed es nada! \u00a0(Por cierto que <a href=\"https:\/\/gourmet.ideal.es\/recetas\/jugo-granada-helado-20191025220506-nt.html\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>\u00a0pod\u00e9is disfrutar de la exquisita receta creada para nuestro suplemento por Chechu).<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/faltan-granadas-en-granada\/granada-maria-de-la-o\/\" rel=\"attachment wp-att-27966\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27966\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Mar\u00eda-de-la-O-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Mar\u00eda-de-la-O-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Mar\u00eda-de-la-O-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Mar\u00eda-de-la-O-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Mar\u00eda-de-la-O.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Vale. La granada es una fruta dura de pelar. Con malafoll\u00e1, para variar. Trabajosilla y, si me apuran, ingrata. Pero adem\u00e1s de ser la \u00fanica fruta presente en el escudo de Espa\u00f1a, representa la diversidad dentro de la unidad, es s\u00edmbolo de fertilidad y prosperidad y su color rojo pasi\u00f3n es puro fuego. (Aqu\u00ed ten\u00e9is dos recetas m\u00e1s: de <a href=\"https:\/\/gourmet.ideal.es\/recetas\/crema-puerro-manzana-20191026235830-nt.html#vca=modulos&amp;vso=ideal&amp;vmc=lo-mas-leido&amp;vli=recetas\" target=\"_blank\" rel=\"noopener\">Ana Entreolivos<\/a> y la de la foto de abajo, <a href=\"https:\/\/gourmet.ideal.es\/recetas\/tartar-ternera-granada-20191025220909-nt.html#vca=modulos&amp;vso=ideal&amp;vmc=lo-mas-leido&amp;vli=recetas\" target=\"_blank\" rel=\"noopener\">de Jos\u00e9 Caracuel<\/a>, de Casa Piolas)<\/p>\n<figure id=\"attachment_27967\" aria-describedby=\"caption-attachment-27967\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/faltan-granadas-en-granada\/granada-casa-piolas\/\" rel=\"attachment wp-att-27967\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27967\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Casa-Piolas-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Casa-Piolas-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Casa-Piolas-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Casa-Piolas-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Granada-Casa-Piolas.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-27967\" class=\"wp-caption-text\">Tartar de ternera y granada de Casa Piolas<\/figcaption><\/figure>\n<p>\u00bfC\u00f3mo es posible que la granada pase tan desapercibida en la gastronom\u00eda de nuestra tierra? \u00bfC\u00f3mo no existen unas jornadas gastron\u00f3micas, tan populares en oto\u00f1o, dedicadas a un fruto que ahora est\u00e1 de temporada? A nada que alguien le echara imaginaci\u00f3n y acertara con la comunicaci\u00f3n, unas Jornadas de la Granada, en Granada, podr\u00edan ser la bomba.<\/p>\n<p>Jes\u00fas Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno cree que sabe de algo hasta que empieza a estudiar un tema en profundidad y cobra socr\u00e1tica conciencia de que apenas sab\u00eda nada. Me ha pasado estos d\u00edas con una fruta que, por l\u00f3gica y cercan\u00eda, deber\u00eda resultarnos de lo m\u00e1s conocida, habitual y cercana. Y sin embargo\u2026No les voy a glosar las bondades [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[16338,6],"tags":[18316,17109,18314,111,18318,18317,18313,17116,18319,18315],"class_list":["post-27963","post","type-post","status-publish","format-standard","hentry","category-gourmet","category-opinion","tag-ana-entreolivos","tag-casa-piolas","tag-chechu-gonzalez","tag-granada","tag-granada-antioxidante","tag-granada-fruta","tag-granadas-en-granada","tag-jose-caracuel","tag-jugo-de-granada","tag-maria-de-la-o"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27963"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27963\/revisions"}],"predecessor-version":[{"id":27969,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27963\/revisions\/27969"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}