{"id":27928,"date":"2019-10-21T18:40:43","date_gmt":"2019-10-21T17:40:43","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27928"},"modified":"2019-10-23T11:33:00","modified_gmt":"2019-10-23T10:33:00","slug":"berlin-iluminada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/berlin-iluminada\/","title":{"rendered":"Berl\u00edn iluminada"},"content":{"rendered":"<p>El s\u00e1bado anduvimos la nada desde\u00f1able cantidad de 18 kil\u00f3metros por Berl\u00edn. El camino que hicimos a la luz del d\u00eda, entre Alexanderplatz, la Puerta de Brandenburgo y la futurista Postdamerplatz; volvimos a hacerlo de noche y de vuelta para disfrutar de un brillante espect\u00e1culo: el festival de las luces que, durante unos d\u00edas, decora decenas de los m\u00e1s significativos edificios de Berl\u00edn con coloridas y vistosas propuestas lum\u00ednicas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/berlin-iluminada\/festival-of-lights\/\" rel=\"attachment wp-att-27929\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27929\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No se trata de proyectar luz sobre los edificios en mitad de un caos sonoro-musical. Son aut\u00e9nticas creaciones lum\u00ednicas perfectamente adaptadas a los edificios en que se proyectan. En algunos casos se trata de proyecciones fijas que, por ejemplo, muestran el aspecto original de un hotel, hace 100 a\u00f1os o m\u00e1s. En ese caso, el Festival de las Luces funciona como una m\u00e1quina del tiempo que, gracias a la tecnolog\u00eda m\u00e1s moderna, nos conduce al pasado de una de las grandes capitales de Europa.<\/p>\n<p>El m\u00e1s brillante de estos montajes, para m\u00ed, fue el que iluminaba la Universidad m\u00e1s antigua de Alemania, dedicada al viajero, expedicionario y naturalista Von Humboldt; con una colorida panoplia de plantas, insectos, \u00e1rboles, r\u00edos e incluso fieras de las selvas sudamericanas por las que viaj\u00f3 y de cuyas riquezas dej\u00f3 testimonio en su trabajo.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/berlin-iluminada\/festival-of-lights-von-humboldt\/\" rel=\"attachment wp-att-27930\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27930\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-von-Humboldt-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-von-Humboldt-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-von-Humboldt-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-von-Humboldt-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pero las m\u00e1s espectaculares eran las proyecciones din\u00e1micas que cuentan historias. Por ejemplo, la realizada sobre la mism\u00edsima Puerta de Brandenburgo, una declaraci\u00f3n de amor a Berl\u00edn, a la ca\u00edda del Muro y a la reunificaci\u00f3n alemana. Una gozada de espect\u00e1culo que concitaba el inter\u00e9s y la atenci\u00f3n de miles y miles de espectadores que abarrotaban las plazas, calles y avenidas de Berl\u00edn.<\/p>\n<p>Jam\u00e1s en mi vida hab\u00eda visto nada igual. Inmensas y kilom\u00e9tricas avenidas cortadas al tr\u00e1fico y tomadas por la gente que, armada con m\u00f3viles, c\u00e1maras fotogr\u00e1ficas y tr\u00edpodes, se afanaba por captar y retener la esencia ef\u00edmera de los monumentos de Berl\u00edn, tuneados y disfrazados para la ocasi\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/berlin-iluminada\/festival-of-lights-berlin\/\" rel=\"attachment wp-att-27931\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27931\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-berl\u00edn-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-berl\u00edn-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-berl\u00edn-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/10\/Festival-of-lights-berl\u00edn-644x859.jpg 644w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Al llegar a Alexanderplatz, la torre de televisi\u00f3n acog\u00eda a todo lo largo una proyecci\u00f3n vertical que derrochaba imaginaci\u00f3n, acci\u00f3n y buen humor. \u00a1Qu\u00e9 tort\u00edcolis me ha agarrado, oigan!<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/jesus_lens\" target=\"_blank\" rel=\"attachment noopener wp-att-27689\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-27689 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/09\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado anduvimos la nada desde\u00f1able cantidad de 18 kil\u00f3metros por Berl\u00edn. El camino que hicimos a la luz del d\u00eda, entre Alexanderplatz, la Puerta de Brandenburgo y la futurista Postdamerplatz; volvimos a hacerlo de noche y de vuelta para disfrutar de un brillante espect\u00e1culo: el festival de las luces que, durante unos d\u00edas, decora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,24],"tags":[18291,18292,18290,18289,18293],"class_list":["post-27928","post","type-post","status-publish","format-standard","hentry","category-opinion","category-viajes","tag-edificios-iluminados","tag-festival-de-la-luz","tag-festival-of-lights","tag-festival-of-lights-berlin","tag-viajar-a-berlin"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27928"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27928\/revisions"}],"predecessor-version":[{"id":27947,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27928\/revisions\/27947"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}