{"id":27630,"date":"2019-09-01T13:51:24","date_gmt":"2019-09-01T12:51:24","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27630"},"modified":"2019-09-01T13:51:24","modified_gmt":"2019-09-01T12:51:24","slug":"el-apreton","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-apreton\/","title":{"rendered":"El apret\u00f3n"},"content":{"rendered":"<p>Es muy po\u00e9tica la explicaci\u00f3n que Luis Salvador ha dado acerca del pacto, acuerdo o compromiso sobre la alternancia en la alcald\u00eda de Granada. El ya famoso 2+2 por el que Salvador y Sebasti\u00e1n P\u00e9rez deber\u00edan repartirse el puesto de alcalde no qued\u00f3 sellado como Dios y la tradici\u00f3n mandan, dado que, en realidad, no hubo apret\u00f3n de manos entre ellos. Aludir a aquel estrechamiento tan s\u00f3lo es una met\u00e1fora.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/cultura-para-salvador\/0-luis-salvador-nuevo-alcalde\/\" rel=\"attachment wp-att-27445\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27445\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Luis-Salvador-nuevo-alcalde-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Luis-Salvador-nuevo-alcalde-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Luis-Salvador-nuevo-alcalde.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No s\u00e9 si la poes\u00eda que rezuma toda esta explicaci\u00f3n est\u00e1 directamente relacionada con los rigores climatol\u00f3gicos del agosto reci\u00e9n terminado, pero no me digan que no resulta evocadora tanta alusi\u00f3n a las viejas costumbres y a los pactos entre caballeros. S\u00f3lo falt\u00f3 decir que el acuerdo no se sell\u00f3 porque los dos firmantes no se escupieron en las manos antes del apret\u00f3n, como mandan los c\u00e1nones m\u00e1s rancios y machirulos.<\/p>\n<p>Llevo varios d\u00e1ndole vueltas a lo del apret\u00f3n. Sobre todo a primera hora, cuando estoy leyendo el peri\u00f3dico con el primer caf\u00e9 de la ma\u00f1ana, acodado en la barra de mi \u2018cafecina\u2019 oficial, el Nuevo Kaoba del Zaid\u00edn. El apret\u00f3n, en esos momentos, es otra cosa. La met\u00e1fora se hace realidad y se convierte en algo muy f\u00edsico. El ocasiones, hasta perentorio.<\/p>\n<p>Cuando el caf\u00e9 hace su trabajo en el tracto digestivo, el apret\u00f3n deviene en lo \u00fanico realmente importante de tu vida. No hay asunto m\u00e1s urgente que resolver. Dan lo mismo el pago de la hipoteca, los abusos con la VISA, la letra del coche o las recuperaciones de los ni\u00f1os. Cuando el apret\u00f3n se hace fuerte, el resto de la realidad palidece.<\/p>\n<figure id=\"attachment_27428\" aria-describedby=\"caption-attachment-27428\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/ciudad-de-medianias\/0-lojas\/\" rel=\"attachment wp-att-27428\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27428\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Lojas-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Lojas-300x186.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Lojas.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-27428\" class=\"wp-caption-text\">\u00a1Casi!<\/figcaption><\/figure>\n<p>Sostiene Luis Salvador que la cuesti\u00f3n de la alternancia en la alcald\u00eda no preocupa a los granadinos, que estamos a otras cosas. No le falta raz\u00f3n. Posiblemente, los ciudadanos no andamos todo el d\u00eda preocupados por el juego de las sillas que se traen los unos y los otros, pero no es menos cierto que, en ocasiones, el primer caf\u00e9 de la ma\u00f1ana nos obliga a acordarnos del ya famoso apret\u00f3n, entr\u00e1ndonos un sudor fr\u00edo y helador.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es muy po\u00e9tica la explicaci\u00f3n que Luis Salvador ha dado acerca del pacto, acuerdo o compromiso sobre la alternancia en la alcald\u00eda de Granada. El ya famoso 2+2 por el que Salvador y Sebasti\u00e1n P\u00e9rez deber\u00edan repartirse el puesto de alcalde no qued\u00f3 sellado como Dios y la tradici\u00f3n mandan, dado que, en realidad, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[18116,14869,18115,18118,18117],"class_list":["post-27630","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-alcaldia-de-granada","tag-apreton","tag-el-apreton","tag-escupirse-en-las-manos","tag-luis-salvador-apreton"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27630"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27630\/revisions"}],"predecessor-version":[{"id":27631,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27630\/revisions\/27631"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}