{"id":27608,"date":"2019-07-30T09:38:59","date_gmt":"2019-07-30T08:38:59","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27608"},"modified":"2019-07-30T09:39:00","modified_gmt":"2019-07-30T08:39:00","slug":"nuevas-tendencias","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/nuevas-tendencias\/","title":{"rendered":"Nuevas Tendencias"},"content":{"rendered":"<p>Igual que mi verano comienza, sentimentalmente, cuando la pe\u00f1a de los Gastrocafres nos reunimos en la playa de Cabria a comer espetos de sardinas; mi mes de agosto arranca en el festival Tendencias de Salobre\u00f1a. Al menos, desde el a\u00f1o en que el incansable Colin Bertholet coordin\u00f3 aquella magn\u00edfica exposici\u00f3n en homenaje y recuerdo a las viejas cassettes.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/nuevas-tendencias\/0-tendencias\/\" rel=\"attachment wp-att-27609\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27609\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Tendencias-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Tendencias-212x300.jpg 212w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Tendencias-644x912.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Tendencias.jpg 678w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n<p>El Tendencias de este a\u00f1o tiene un neto sabor granadino, con Los Planetas como grandes cabezas de cartel de un festival multidisciplinar que tambi\u00e9n cuenta con los oscuros, pantanosos y fascinantes Guadalupe Plata, de quienes ya les habl\u00e9 hace unas semanas, tras la presentaci\u00f3n de su \u00faltimo disco en el Planta Baja. (Leer <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/guadalupe-plata-david-lynch\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>, su mestizaje con David Lynch)<\/p>\n<p>Pero el Tendencias tambi\u00e9n tiene documentales y conferencias, redondeando una programaci\u00f3n que vincula y marida diferentes disciplinas, algo que cada vez aprecio m\u00e1s en los festivales y citas culturales. Este a\u00f1o, la cantante Annie B. Sweet y el periodista Miguel \u00c1ngel Bargue\u00f1o conversar\u00e1n sobre \u2018El poder de las mujeres en la m\u00fasica rock de ayer y de hoy\u2019 y se proyectar\u00e1 \u2018Mujeres\u2019, de Coque Malla.<\/p>\n<p>Pero lo mejor de que lleguen unas nuevas Tendencias es que nos dan la ocasi\u00f3n de volver a Salobre\u00f1a, uno de los lugares del mundo que m\u00e1s quiero y donde me siento como en casa.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/nuevas-tendencias\/0-ten\/\" rel=\"attachment wp-att-27610\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27610\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Ten-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Ten-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Ten-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Ten-644x362.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Cada vez soy m\u00e1s proclive a la vida knowmad: trabajar en movimiento. Es una de las grandes ventajas de internet y del 4G. En lo que va de a\u00f1o, he andado por Arag\u00f3n, C\u00e1diz, Lyon, Sevilla, Cuenca y nuestra m\u00e1s cercana Costa Tropical, siempre con el port\u00e1til y el m\u00f3vil encima, escribiendo sin parar. Reconozco que, en ocasiones, me cuesta concentrarme cuando trabajo por ah\u00ed fuera, pero tambi\u00e9n me resulta muy inspirador escuchar otras voces y disfrutar de vistas diferentes a las habituales.<\/p>\n<p>El Tendencias marca el pistoletazo de salida, tambi\u00e9n, para mi mes n\u00f3mada por excelencia. Casualidades de la vida: tras a\u00f1os y a\u00f1os haciendo grandes viajes por pa\u00edses lejanos, este verano volver\u00e9 a disfrutar de un gran viaje\u2026 por paisajes cercanos: \u00a1vuelve el verano en bermudas! Ma\u00f1ana les cuento m\u00e1s.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26053\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26053 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Igual que mi verano comienza, sentimentalmente, cuando la pe\u00f1a de los Gastrocafres nos reunimos en la playa de Cabria a comer espetos de sardinas; mi mes de agosto arranca en el festival Tendencias de Salobre\u00f1a. Al menos, desde el a\u00f1o en que el incansable Colin Bertholet coordin\u00f3 aquella magn\u00edfica exposici\u00f3n en homenaje y recuerdo a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17,6],"tags":[1603,17857,17058,18105,3392,3378],"class_list":["post-27608","post","type-post","status-publish","format-standard","hentry","category-musica","category-opinion","tag-colin-bertholet","tag-guadalupe-plata","tag-knowmad","tag-lens-knowmad","tag-nuevas-tendencias","tag-tendencias-salobrena"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27608"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27608\/revisions"}],"predecessor-version":[{"id":27612,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27608\/revisions\/27612"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}