{"id":27587,"date":"2019-07-24T08:52:18","date_gmt":"2019-07-24T07:52:18","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27587"},"modified":"2019-07-24T08:52:18","modified_gmt":"2019-07-24T07:52:18","slug":"el-juez-maltratador","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-juez-maltratador\/","title":{"rendered":"El juez maltratador"},"content":{"rendered":"<p>Lo primero que se ha sabido es que lleva tiempo de baja laboral, aunque no sabemos la causa. Las fuentes gubernamentales insisten en lo de la baja para tranquilizar a la ciudadan\u00eda, no vaya a sospechar de todo togado que le toque en suerte en los juzgados granadinos.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-juez-maltratador\/0-machismo\/\" rel=\"attachment wp-att-27588\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27588\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Machismo-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Machismo-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Machismo.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A estas alturas ya lo habr\u00e1n le\u00eddo\/visto\/o\u00eddo: \u2018Detenido un juez de Granada por presunta violencia de g\u00e9nero contra su mujer y atentado a la Guardia Civil\u2019. Es duro. Muy duro. Constituye buena prueba del arduo camino que nos queda por recorrer contra la violencia machista, que en los \u00faltimos d\u00edas ha habido dos nuevos asesinatos de mujeres a manos de sus parejas, hombres.<\/p>\n<p>No me quito de la cabeza la otra historia que ha copado la actualidad informativa de estos d\u00edas: la prohibici\u00f3n de volar a una chica por la sencilla raz\u00f3n de que vest\u00eda un body. Entre las reacciones que se han podido leer en las redes hay una que me resulta aterradora: \u2018que se hubiera tapado\u2019.<\/p>\n<p>Vivimos en tiempos extra\u00f1os en los que deber\u00edamos tener claras algunas cosas, aunque no resulte f\u00e1cil: la necesidad de blindar el imperio de la ley y de combatir el machismo secular que impregna la sociedad en que vivimos.<\/p>\n<figure id=\"attachment_27589\" aria-describedby=\"caption-attachment-27589\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-juez-maltratador\/0-machista\/\" rel=\"attachment wp-att-27589\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27589\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Machista-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Machista-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-Machista.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-27589\" class=\"wp-caption-text\">Ojito a VOX que quiere derogar la Ley contra la Violencia de G\u00e9nero<\/figcaption><\/figure>\n<p>Recuerdo hace unos meses a un muchacho al que, tomando caf\u00e9, le cay\u00f3 una gota en un pantal\u00f3n inmaculadamente blanco. El chaval, te\u00f1ido de rubio platino y con m\u00e1s piercings en la cara que tornillos hay en una ferreter\u00eda, pidi\u00f3 uno de esos sprays quitamanchas. Cuando la camarera se lo acerc\u00f3, el joven pregunt\u00f3 a voz en grito: \u201c\u00bfY esto c\u00f3mo va? Que no soy una mujer para saber utilizar un quitamanchas\u2026\u201d Sus amigos y amigas rieron a mand\u00edbula batiente y, de hecho, fue una de ellas quien hizo el trabajo sucio.<\/p>\n<p>O aquel taxista, tambi\u00e9n joven, del que les habl\u00e9 hace unos meses. Hombre joven soltando bilis, echando espumarajos por la boca al hablar de unas mujeres que se manifestaban por la causa del feminismo. \u00a1Lo que nos queda por educar, trabajar, formar y luchar!<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo primero que se ha sabido es que lleva tiempo de baja laboral, aunque no sabemos la causa. Las fuentes gubernamentales insisten en lo de la baja para tranquilizar a la ciudadan\u00eda, no vaya a sospechar de todo togado que le toque en suerte en los juzgados granadinos. A estas alturas ya lo habr\u00e1n le\u00eddo\/visto\/o\u00eddo: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[18092,18093,14041,18094,18091],"class_list":["post-27587","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-juez-maltratador","tag-juez-maltratador-granada","tag-machismo-asesino","tag-sociedad-machista","tag-violencia-genero"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27587"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27587\/revisions"}],"predecessor-version":[{"id":27591,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27587\/revisions\/27591"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}