{"id":27486,"date":"2019-07-04T12:36:40","date_gmt":"2019-07-04T11:36:40","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27486"},"modified":"2019-07-04T12:36:40","modified_gmt":"2019-07-04T11:36:40","slug":"si-trabajan-por-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/si-trabajan-por-granada\/","title":{"rendered":"Si trabajan por Granada"},"content":{"rendered":"<p>Perm\u00edtanme una propuesta para comprobar si es cierto que los partidos pol\u00edticos con representaci\u00f3n en el ayuntamiento de Granada trabajan por y para esta tierra o si s\u00f3lo est\u00e1n para la bronca constante y mutuo marraneo.<\/p>\n<p>Repasando los programas electorales de PSOE, PP, Cs e UP, hay algunos temas en los que las cuatro formaciones propon\u00edan actuaciones parecidas. Por ejemplo, la ampliaci\u00f3n del Metro hacia el \u00e1rea metropolitana y la renaturalizaci\u00f3n del r\u00edo Genil a su paso por la ciudad.<\/p>\n<figure id=\"attachment_27487\" aria-describedby=\"caption-attachment-27487\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/si-trabajan-por-granada\/0-0-lec-hombre-3\/\" rel=\"attachment wp-att-27487\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27487\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-0-Lec-Hombre-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-0-Lec-Hombre-1-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-0-Lec-Hombre-1.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-27487\" class=\"wp-caption-text\">Recreaci\u00f3n de c\u00f3mo podr\u00eda quedar el Genil<\/figcaption><\/figure>\n<p>\u00bfQu\u00e9 tal si, al margen de seguir con sus consabidas peleas, los cuatro partidos empiezan a trabajar de forma conjunta en dichos proyectos? \u00bfNo ser\u00eda fant\u00e1stico que, al igual que designan portavoces, tenientes de alcalde y asesores, nombraran a los encargados de reunirse, planificar y avanzar en asuntos capitales para la ciudad en los que todos est\u00e1n de acuerdo?<\/p>\n<p>\u00a1Esa s\u00ed ser\u00eda una prueba de que los ciudadanos importamos! M\u00e1s all\u00e1 de nuestro voto, quiero decir. Dado que hay un consenso generalizado sobre la conveniencia y la trascendencia de acometer dichas actuaciones, \u00bfqu\u00e9 tal si se arremangan y empiezan con ello?<\/p>\n<p>Da igual quien sea el alcalde, el vicealcalde y el n\u00famero de tenencias de alcald\u00eda: estando de acuerdo en la conveniencia de ambas empresas, \u00a1que se pongan en marcha cuanto antes! Son proyectos, adem\u00e1s, que al ir en los programas electorales de los cuatro partidos, han sido abrumadoramente aceptados por la inmensa mayor\u00eda de los votantes. Vox tampoco deber\u00eda ponerles una sola pega, que en nada contradicen a su dec\u00e1logo para apoyar al gobierno municipal.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/si-trabajan-por-granada\/0-0-lec-salvaje-3\/\" rel=\"attachment wp-att-27488\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27488\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-0-Lec-Salvaje-300x194.png\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-0-Lec-Salvaje-300x194.png 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/07\/0-0-Lec-Salvaje.png 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Se\u00f1ores Cuenca, P\u00e9rez, Salvador, Cambril y Miralles, demuestren que les hemos elegido para algo m\u00e1s que para pelearse entre ustedes. Contribuyan a rebajar el nivel de desapego que los granadinos sentimos hacia la pol\u00edtica municipal estos d\u00edas. Ens\u00e9\u00f1ennos que, adem\u00e1s de abroncarse, son capaces de arrimar el hombro para trabajar, juntos, en algunos de los proyectos que m\u00e1s nos preocupan. La ampliaci\u00f3n del Metro y el adecentamiento del Genil son desaf\u00edos de futuro que van a conllevar mucho tiempo y esfuerzo. Cuanto antes empecemos, mejor.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perm\u00edtanme una propuesta para comprobar si es cierto que los partidos pol\u00edticos con representaci\u00f3n en el ayuntamiento de Granada trabajan por y para esta tierra o si s\u00f3lo est\u00e1n para la bronca constante y mutuo marraneo. Repasando los programas electorales de PSOE, PP, Cs e UP, hay algunos temas en los que las cuatro formaciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16920,18020,17488,17828],"class_list":["post-27486","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-ampliacion-metro-granada","tag-ampliar-metro-granada","tag-genil-renaturalizado","tag-renaturalizar-genil"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27486"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27486\/revisions"}],"predecessor-version":[{"id":27490,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27486\/revisions\/27490"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}