{"id":27366,"date":"2019-06-15T12:23:08","date_gmt":"2019-06-15T11:23:08","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27366"},"modified":"2019-06-15T12:23:08","modified_gmt":"2019-06-15T11:23:08","slug":"twitter-en-vena","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/twitter-en-vena\/","title":{"rendered":"Twitter en vena"},"content":{"rendered":"<p>Siguiendo a Bruce Chatwin, a los aficionados y usuarios de las redes sociales nos acaba pasando como a los buenos viajeros: en alg\u00fan momento nos encontraremos parados, inermes y perplejos, pregunt\u00e1ndonos por el c\u00e9lebre \u2018\u00bfqu\u00e9 hago yo aqu\u00ed?\u2019<\/p>\n<p>Disfrutar cada a\u00f1o del #TATGranada, el evento twitter organizado por IDEAL, es una inyecci\u00f3n de moral y autoconfianza que viene a resolver cualquier duda sobre el inter\u00e9s o la utilidad de ser usuarios activos de redes.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/twitter-en-vena\/0-tat-mapfre\/\" rel=\"attachment wp-att-27367\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27367\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-TAT-Mapfre-300x183.jpg\" alt=\"\" width=\"300\" height=\"183\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-TAT-Mapfre-300x183.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-TAT-Mapfre.jpg 621w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>En la edici\u00f3n de este a\u00f1o, por ejemplo, me encant\u00f3 Antonio Huertas, el presidente de Mapfre, que se abri\u00f3 en canal y destac\u00f3 la importancia de que los trabajadores de las empresas accedan a las redes y participen activamente en ellas, dado que son sus mejores portavoces y prescriptores. Siempre que est\u00e9n contentos y satisfechos, por supuesto. De acuerdo con las tendencias de mercado, las marcas y las empresas cada vez tienen menos credibilidad, predicamento e influencia. Los internautas creen a las personas. De ah\u00ed que cuidar las redes personales tenga una importancia creciente.<\/p>\n<p>Ha sido uno de los temas m\u00e1s tratados en este #TATGranada7: la necesidad de cuidar el medioambiente digital. El magistrado Miguel Pasquau dio una clave: sigue a los mejores perfiles de los usuarios que no piensen como t\u00fa. De esa manera tendr\u00e1s acceso a otros puntos de vista\u2026 y te obligar\u00e1s a ser muy cuidadoso con lo que escribes, dado que ellos tambi\u00e9n leer\u00e1n tus tuits y tus posts y te podr\u00e1n replicar. Es una v\u00eda de forzarte a ser respetuoso, riguroso y cuidadoso.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/twitter-en-vena\/0-tatgranada-twitter\/\" rel=\"attachment wp-att-27368\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27368\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-tatgranada-twitter-300x292.jpg\" alt=\"\" width=\"300\" height=\"292\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-tatgranada-twitter-300x292.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-tatgranada-twitter-644x627.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-tatgranada-twitter.jpg 698w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Adem\u00e1s, unos extraordinarios consejos impartidos por el abogado Jos\u00e9 Muelas: si bebes, no tuitees. No es ninguna boutade. Es una regla que deber\u00edamos grabarnos a sangre y fuego. Otra: si tienes dudas sobre si publicar o no un determinado tuit\u2026 \u00a1no lo hagas! B\u00f3rralo o, como m\u00ednimo, d\u00e9jalo en la nevera. Por \u00faltimo: no hace falta tener la \u00faltima palabra. No es necesario eternizar las discusiones. Por grande que sea la tentaci\u00f3n de quedar por encima de un inc\u00f3modo o picajoso interlocutor, no merece la pena. Que tus argumentos hablen por ti.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siguiendo a Bruce Chatwin, a los aficionados y usuarios de las redes sociales nos acaba pasando como a los buenos viajeros: en alg\u00fan momento nos encontraremos parados, inermes y perplejos, pregunt\u00e1ndonos por el c\u00e9lebre \u2018\u00bfqu\u00e9 hago yo aqu\u00ed?\u2019 Disfrutar cada a\u00f1o del #TATGranada, el evento twitter organizado por IDEAL, es una inyecci\u00f3n de moral y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[17938,17940,17941,17939,8666,11390],"class_list":["post-27366","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-tatgranada2020","tag-antonio-huertas","tag-antonio-huertas-mapfre","tag-miguel-pasquau","tag-talking-about-twitter","tag-tat-granada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27366"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27366\/revisions"}],"predecessor-version":[{"id":27370,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27366\/revisions\/27370"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}