{"id":27346,"date":"2019-06-12T08:33:25","date_gmt":"2019-06-12T07:33:25","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27346"},"modified":"2019-06-12T08:33:26","modified_gmt":"2019-06-12T07:33:26","slug":"ciudadanos-empaqueta-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ciudadanos-empaqueta-granada\/","title":{"rendered":"Ciudadanos empaqueta Granada"},"content":{"rendered":"<p>Ellos lo llaman \u2018acuerdo global\u2019, que suena m\u00e1s bonito, pero lo cierto es que Ciudadanos ha incluido a Granada en un paquete negociador de alcald\u00edas y comunidades que veremos por d\u00f3nde les sale.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-menton-ilustrado\/0-luis-salvador-morfopsicologico\/\" rel=\"attachment wp-att-27120\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27120\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/05\/0-Luis-Salvador-morfopsicol\u00f3gico-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/05\/0-Luis-Salvador-morfopsicol\u00f3gico-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/05\/0-Luis-Salvador-morfopsicol\u00f3gico.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Llegados a este punto, y a la espera saber si Onofre Miralles celebra hoy su onom\u00e1stica con tartas o con tortas, conviene recordar que hace muchos, muchos a\u00f1os, los andalucistas del pujante PSA rindieron el ayuntamiento Granada a cambio la alcald\u00eda de Sevilla. Las consecuencias directas de aquel cambalache fueron la pr\u00e1ctica laminaci\u00f3n del andalucismo en nuestra tierra y el comienzo de la partici\u00f3n en dos de una Andaluc\u00eda que nunca volvi\u00f3 a ser una.<\/p>\n<p>Hay palabras que no suenan bien. \u2018Paquete\u2019 es una de ellas. Ser un paquete es ser malo de solemnidad, un bluff, una decepci\u00f3n. Un paquete tur\u00edstico tiene el mismo atractivo que una pieza m\u00e1s de una cadena de montaje y las referencias soeces a la expresi\u00f3n \u2018echarse mano al paquete\u2019 no hay que explicitarlas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/ciudadanos-empaqueta-granada\/0-paquete\/\" rel=\"attachment wp-att-27347\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27347\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Paquete-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Paquete-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Paquete.jpg 623w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Meter a Granada en un paquete no es bonito ni elegante. L\u00f3gicamente, cada ciudad es especial, \u00fanica e irremplazable y tiene su particular idiosincrasia, pero Granada es una ciudad simb\u00f3lica por un buen n\u00famero de razones, tal y como escrib\u00eda hace unos d\u00edas. (Leer <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/porque-tu-lo-valls\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a> Y <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/mesas-de-dos-sin-tres\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd)<\/a> Una ciudad s\u00edmbolo que, en los \u00faltimos lustros, ha ido perdiendo importancia, cualitativa y cuantitativa, abandonada por sus representantes pol\u00edticos. \u00bfQu\u00e9 dos ciudades andaluzas van a estrenar el 5G en nuestra comunidad, sin ir m\u00e1s lejos? Sevilla y M\u00e1laga, faltar\u00eda m\u00e1s. \u00bfAlguien lo dudaba?<\/p>\n<p>El gobierno del PP de Torres Hurtado, adem\u00e1s de mantener a nuestra ciudad en una decadente mediocridad, arruin\u00f3 sus arcas y la dej\u00f3 esquilmada, un detalle que no deber\u00edan olvidar los representantes de Ciudadanos que lo convirtieron en alcalde por \u00faltima vez, meses antes de que saliera detenido por la UDEF.<\/p>\n<figure id=\"attachment_27348\" aria-describedby=\"caption-attachment-27348\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/ciudadanos-empaqueta-granada\/docu_ideal-13\/\" rel=\"attachment wp-att-27348\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-27348\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Torres-Hurtado-300x227.jpg\" alt=\"\" width=\"300\" height=\"227\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Torres-Hurtado-300x227.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/06\/0-Torres-Hurtado.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-27348\" class=\"wp-caption-text\">EL ALCALDE GRANADA SALE DETENIDO DEL AYUNTAMIENTO<br \/>FOTOGRAFIA: ALFREDO AGUILAR<\/figcaption><\/figure>\n<p>\u00bfDe verdad va a meter Ciudadanos a Granada en un paquete negociador global, al margen de las propuestas electorales de populares y socialistas para los pr\u00f3ximos cuatro a\u00f1os? \u00bfEsa es la preocupaci\u00f3n por la Granada del futuro que muestran Luis Salvador y los suyos?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ellos lo llaman \u2018acuerdo global\u2019, que suena m\u00e1s bonito, pero lo cierto es que Ciudadanos ha incluido a Granada en un paquete negociador de alcald\u00edas y comunidades que veremos por d\u00f3nde les sale. Llegados a este punto, y a la espera saber si Onofre Miralles celebra hoy su onom\u00e1stica con tartas o con tortas, conviene [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[12379,17928,17927,17926,12399,17925,17929],"class_list":["post-27346","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-alcalde-granada","tag-ciudadanos-empaqueta-granada","tag-granada-empaquetada","tag-negociaciones-alcalde-granada","tag-paco-cuenca-alcalde-granada","tag-quien-sera-alcalde-granada","tag-san-onofre"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27346"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27346\/revisions"}],"predecessor-version":[{"id":27351,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27346\/revisions\/27351"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}