{"id":27126,"date":"2019-05-05T21:01:15","date_gmt":"2019-05-05T20:01:15","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27126"},"modified":"2019-05-05T21:01:15","modified_gmt":"2019-05-05T20:01:15","slug":"el-menton-ilustrado-2","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-menton-ilustrado-2\/","title":{"rendered":"El ment\u00f3n ilustrado"},"content":{"rendered":"<p>Tendr\u00eda catorce o quince a\u00f1os cuando encargu\u00e9 un estudio astral personalizado. Tard\u00f3 un mes en llegar casa. Lo abr\u00ed alborozado y me lanc\u00e9 a leer medio centenar de folios\u2026 en los que apenas me reconoc\u00eda, m\u00e1s all\u00e1 de lugares comunes y t\u00f3picos varios. Sin embargo, todo lo que me pronosticaban las estrellas era tan sugerente que decid\u00ed esforzarme al m\u00e1ximo en tratar de parecerme al brillante sujeto de luz descrito por mi carta astral.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-menton-ilustrado\/0-luis-salvador-morfopsicologico\/\" rel=\"attachment wp-att-27120\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27120\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/05\/0-Luis-Salvador-morfopsicol\u00f3gico-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/05\/0-Luis-Salvador-morfopsicol\u00f3gico-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/05\/0-Luis-Salvador-morfopsicol\u00f3gico.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Afortunadamente, en los a\u00f1os 80 del pasado siglo hab\u00eda menos reiki y m\u00e1s Reca, el bar de la plaza de Trinidad donde pon\u00edan los mejores vola\u00edllos de Granada. Menos Flores de Bach y m\u00e1s espuma de cerveza. Menos coaches enterados y m\u00e1s camareros sabios. Menos salas de yoga y m\u00e1s canchas de baloncesto. Una vez asumido que, por mucho que lo visualizara y lo deseara, nunca iba a hacer mates como los de Michael Jordan, fui bastante m\u00e1s feliz.<\/p>\n<p>Pienso en todo ello con relajo y desahogo al suponer lo extremadamente duro y complicado que tiene que ser\u2026 ser Luis Salvador. He le\u00eddo los resultados de su ya famoso estudio morfopsicol\u00f3gico y estoy impresionado por la cantidad de talentos y habilidades que atesora el candidato de Ciudadanos a la alcald\u00eda de Granada. Algunos rozan lo fant\u00e1stico, incluso. Y ya se sabe que un gran poder conlleva una gran responsabilidad. Yo ya lo intu\u00eda, que conste: un ment\u00f3n como el de Luis Salvador no puede ser casual o accidental.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-menton-ilustrado\/0-luis-salvador-estudio-morfopsicologico\/\" rel=\"attachment wp-att-27121\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27121\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/05\/0-Luis-Salvador-estudio-morfopsicol\u00f3gico-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" \/><\/a><\/p>\n<p>Juro que jam\u00e1s pens\u00e9 que iba a escribir sobre el f\u00edsico de una persona p\u00fablica. Siempre he deplorado este tipo de chascarrillos, recurso f\u00e1cil para provocar risas m\u00e1s f\u00e1ciles a\u00fan. Pero cuando un posible alcalde de tu ciudad se hace analizar la forma de su cr\u00e1neo y publica los superlativos resultados de dicho \u2018estudio\u2019 en su web personal\u2026<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/bilisto-ciudadano-salvador\/luis-salvador-2\/\" rel=\"attachment wp-att-26847\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-26847\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/Luis-Salvador.jpg\" alt=\"\" width=\"228\" height=\"141\" \/><\/a><\/p>\n<p>Dos dudas: \u00bfobligar\u00e1 el l\u00edder de Cs en Granada a someterse a los dictados de la morfopsicolog\u00eda a su equipo, para detectar sus habilidades ocultas? Porque Luis Salvador defiende dicha pseudociencia con tanto \u00e9nfasis que hace tonta a la mism\u00edsima Inteligencia Artificial. Pero, sobre todo y a la vista de sus portentosos talentos, \u00bfno deber\u00eda Albert Rivera convertirle en su mano derecha y llev\u00e1rselo con \u00e9l a Madrid, ipso facto?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tendr\u00eda catorce o quince a\u00f1os cuando encargu\u00e9 un estudio astral personalizado. Tard\u00f3 un mes en llegar casa. Lo abr\u00ed alborozado y me lanc\u00e9 a leer medio centenar de folios\u2026 en los que apenas me reconoc\u00eda, m\u00e1s all\u00e1 de lugares comunes y t\u00f3picos varios. Sin embargo, todo lo que me pronosticaban las estrellas era tan sugerente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[12338,17782],"class_list":["post-27126","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-luis-salvador","tag-luis-salvador-morfopsicologia"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27126"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27126\/revisions"}],"predecessor-version":[{"id":27127,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27126\/revisions\/27127"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}