{"id":27000,"date":"2019-04-15T05:29:48","date_gmt":"2019-04-15T04:29:48","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27000"},"modified":"2019-04-14T20:35:41","modified_gmt":"2019-04-14T19:35:41","slug":"un-dia-sin-internet","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/un-dia-sin-internet\/","title":{"rendered":"Un d\u00eda sin Internet"},"content":{"rendered":"<p>Ayer se cayeron WhatsApp, Facebook e Instagram durante un par de horas y los efectos fueron, b\u00e1sicamente, divertid\u00edsimos. Para empezar, los viejunos pontificadores volvieron a aprovechar las cada vez m\u00e1s habituales ca\u00eddas masivas de las redes sociales para ironizar con que los j\u00f3venes Millennials descubrir\u00edan que existe una vida real fuera de las pantallas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=27001\" rel=\"attachment wp-att-27001\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27001\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Internet-bluff-300x171.jpg\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Internet-bluff-300x171.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Internet-bluff-768x438.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Internet-bluff-644x367.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Internet-bluff.jpg 810w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Otra gente se vio obligada a hacer algo tan anacr\u00f3nico como hablar por tel\u00e9fono para cuadrar la comida del domingo, confirmar la reserva en el restaurante o explicarle al cu\u00f1ado torpe y despistado c\u00f3mo se llega al garito.<\/p>\n<p>Una inmejorable ocasi\u00f3n, tambi\u00e9n, para recordar el por qu\u00e9 de las leyes antimonopolio: que tres canales de comunicaci\u00f3n de tanta implantaci\u00f3n como Facebook, Instagram y WhatsApp est\u00e9n en las mismas manos y dependan de las mismas redes, tiene sus riesgos.<\/p>\n<p>Lo que me lleva a ir un poco m\u00e1s all\u00e1. \u00bfSe imaginan que, en vez de las redes sociales, se cayera Internet como tal? \u00bfC\u00f3mo ser\u00eda un d\u00eda sin Internet? Para empezar, habr\u00eda que ir al quiosco en busca de la prensa, si quisi\u00e9ramos estar bien informados y no quedarnos en saber lo que pasa.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=27003\" rel=\"attachment wp-att-27003\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27003\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/IDEAL-quioscos-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p>De encontrarnos en una ciudad extra\u00f1a, habr\u00eda que buscar un plano que nos permitiera orientarnos. Eso, y preguntarle a la gente, claro. Al no poder subir fotos a las redes ni interactuar en foros, estar\u00edamos obligados a mirar las cosas que nos rodean. Al natural; sin filtros, marcos o adornos. En vivo y en directo. Es posible que nos saliera tort\u00edcolis por mantener el pescuezo recto durante tanto tiempo, pero ser\u00eda un riesgo asumible.<\/p>\n<p>No funcionar\u00edan las plataformas televisivas y las Smart TV volver\u00edan a ser tontas, aunque ya no fueran cajas. En ese caso, los viejos DVD y Blu-Ray ser\u00edan la tabla de salvaci\u00f3n para cin\u00e9filos compulsivos que no se conformaran con ver lo que echen las cadenas de turno.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=27002\" rel=\"attachment wp-att-27002\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-27002\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Ca\u00edda-Internet-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Ca\u00edda-Internet-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/04\/Ca\u00edda-Internet.jpg 512w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Y quedar\u00edan los libros, claro. Los libros de toda la vida. Los de tinta y papel, invit\u00e1ndonos a una lectura tranquila y sosegada sin que los avisos, alarmas y globitos de colores del m\u00f3vil nos interrumpieran y molestaran continuamente.<\/p>\n<p>\u2014Muy bien, Lens. Todo eso est\u00e1 muy bien. \u00bfPero c\u00f3mo te las ibas a apa\u00f1ar para mandar al peri\u00f3dico esta columna?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26852\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26852 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/03\/0Twitter.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer se cayeron WhatsApp, Facebook e Instagram durante un par de horas y los efectos fueron, b\u00e1sicamente, divertid\u00edsimos. Para empezar, los viejunos pontificadores volvieron a aprovechar las cada vez m\u00e1s habituales ca\u00eddas masivas de las redes sociales para ironizar con que los j\u00f3venes Millennials descubrir\u00edan que existe una vida real fuera de las pantallas. Otra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[17676,17677,17678,17674,13233,17675],"class_list":["post-27000","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-caida-facebook","tag-caida-instagram","tag-caida-whatsapp","tag-dia-sin-internet","tag-quioscos","tag-quioscos-de-prensa"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27000"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27000\/revisions"}],"predecessor-version":[{"id":27004,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27000\/revisions\/27004"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}