{"id":27,"date":"2008-02-07T11:56:00","date_gmt":"2008-02-07T10:56:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=27"},"modified":"2008-02-07T11:56:00","modified_gmt":"2008-02-07T10:56:00","slug":"de-vuelta-en-twin-peaks","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/de-vuelta-en-twin-peaks\/","title":{"rendered":"DE VUELTA EN TWIN PEAKS"},"content":{"rendered":"<div align=\"justify\">Hemos vuelto a <a href=\"http:\/\/es.wikipedia.org\/wiki\/Twin_Peaks\"><span style=\"color:#ff0000;\"><strong>\u201cTwin Peaks\u201d.<\/strong><\/span> <\/a>Deben de haber pasado unos quince a\u00f1os desde nuestra primera visita y, al menos, doce o trece desde que fuimos all\u00e1 por segunda vez. Y, curiosamente, nada ha cambiado en ese maravilloso y atormentado pueblo de la frontera entre los EE.UU y Canad\u00e1.<\/p>\n<p><\/div>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164191041118873858\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R6rkZA4lKQI\/AAAAAAAAANI\/pqvlqboBS8I\/s400\/_25.JPG\" border=\"0\" \/><br \/>A la primea persona que encontramos en esta tercera visita a Twin Peaks fue a la <a href=\"http:\/\/www.youtube.com\/watch?v=jMdCU7qi_FI\"><span style=\"color:#ff0000;\"><strong>Se\u00f1ora del Le\u00f1o,<\/strong><\/span><\/a> esa entra\u00f1able mujer que, metida en canas y en a\u00f1os, acuna permanentemente a un trozo de madera que, en realidad, sabe mucho m\u00e1s de lo que su arb\u00f3rea presencia parece delatar. Lady Le\u00f1o hace una somera introducci\u00f3n de las cosas que van a pasar en el pueblo, a su estilo, entre lo enigm\u00e1tico, lo m\u00edstico y lo que dicta el sentido com\u00fan (V\u00e9ase el v\u00eddeo, pinchando un poco a Lady Le\u00f1o).<\/p>\n<p>En Twin Peaks fue donde, todos lo sab\u00e9is, asesinaron a <a href=\"http:\/\/es.wikipedia.org\/wiki\/Laura_Palmer\"><span style=\"color:#ff0000;\"><strong>Laura Palmer<\/strong><\/span><\/a>. \u00bfOs acord\u00e1is? El caso hizo derramar litros de tinta en la prensa de todo el mundo. Las portadas de los peri\u00f3dicos m\u00e1s importantes abr\u00edan con aquella pregunta que, por desgracia, hizo famoso al simp\u00e1tico pueblo maderero: \u00bfQui\u00e9n mat\u00f3 a Laura Palmer? <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164191054003775778\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R6rkZw4lKSI\/AAAAAAAAANY\/x2LQrrxl1J4\/s400\/_8.jpg\" border=\"0\" \/><br \/>Es curioso. A la vuelta de tanto tiempo, la pregunta sigue viva en Twin Peaks. Nadie ha podido olvidar a Laura y, en cuanto llegas a la localidad, es como si todo volviera a ocurrir. Un cierta sensaci\u00f3n de deja v\u00fa que, parad\u00f3jicamente, no se hace en absoluto reiterativa. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164191255867238738\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R6rklg4lKVI\/AAAAAAAAANw\/7sZk3Bej1jY\/s400\/_26.jpg\" border=\"0\" \/><br \/>Porque, al ser m\u00e1s mayores, caemos en detalles que se nos pasaron en las ocasiones anteriores. Y miramos las cosas y a las personas con otros ojos. Por ejemplo, recuerdo que, antes, lo que m\u00e1s me interes\u00f3 de aquella historia fue, precisamente, encontrara una respuesta satisfactoria a la pregunta dichosa: \u00bfqui\u00e9n mat\u00f3 a Laura Palmer?<\/p>\n<p>Ahora no. Porque, en realidad, el qui\u00e9n-lo-hizo era secundario en la historia. Y por eso, si anta\u00f1o me dio un enorme baj\u00f3n la resoluci\u00f3n de dicho enigma, esta vez, descubrir tal extremo no ha hecho sino espolear la curiosidad y el inter\u00e9s por el resto de subtramas y de personajes que habitan el pueblo, y que ten\u00eda grande e injustamente olvidados, dicho sea de paso. Y es que <a href=\"http:\/\/es.wikipedia.org\/wiki\/David_Lynch\"><span style=\"color:#ff0000;\"><strong>David Lynch<\/strong><\/span><\/a>, el fundador de Twin Peaks, aunque rarito, es todo un genio. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164191049708808466\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R6rkZg4lKRI\/AAAAAAAAANQ\/56ZDbisgqJY\/s400\/_11.jpg\" border=\"0\" \/><br \/>Ser\u00e1 la herencia de haber visto tanto \u201c24\u201d, \u201cPerdidos\u201d, \u201cPrison break\u201d o \u201cMujeres desesperadas\u201d. Que nos dejamos atrapar por las tramas complejas y complicadas, con toques entre lo humor\u00edstico y lo surrealista, protagonizadas por personajes raros, peculiares y singulares. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164191260162206050\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R6rklw4lKWI\/AAAAAAAAAN4\/yrBGFIAeBCo\/s400\/__1.jpg\" border=\"0\" \/><br \/>De Twin Peaks, como del cerdo, nos gusta todo. Hasta los chulescos andares del capullo de Bobby Briggs. Nos gusta el agente Cooper y nos encanta la p\u00e9rfida candidez de Audrey. Donna sigue siendo un poco idiota y James, cargante. Pero es que la gente no cambia y la vida necesita de esos diferentes caracteres. Que en la variedad est\u00e1 el gusto. Le coges cari\u00f1o a la pobre Nadine y te solidarizas con Norma. \u00a1Si hasta la modosita mosquita muerta Jocelyn, que es una arp\u00eda, se deja querer! O al mam\u00f3n de Benjamin Horne, convertido en chiflado general Lee. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164191062593710402\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/R6rkaQ4lKUI\/AAAAAAAAANo\/iAefPq1FqwI\/s400\/_31.jpg\" border=\"0\" \/><br \/>Pero, en esta (pen)\u00faltima visita al pueblo, el nombre por excelencia es el de Windom Earle, uno de esos villanos malos, mal\u00edsimos, al que Cooper compara con un diamante: duro, fr\u00edo y brillante. Uno de esos archienemigos que pondr\u00e1n a pruebo el talento de nuestro agente favorito del FBI, con permiso de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Fox_Mulder\"><span style=\"color:#ff0000;\"><strong>Mulder<\/strong><\/span><\/a>. Por cierto, impagable el personaje de Denis-Denise, interpretado por el mism\u00edsimo David Duchovny. Y no olvidemos al agente Albert, un aut\u00e9ntico grano en el culo que, cuando revienta, produce un intenso bienestar. Porque&#8230; \u00a1las lechuzas no son lo que parecen!<\/p>\n<p>Twin Peaks est\u00e1 lleno de personajes maravillosos, de los que no se olvidan, a los que coges cari\u00f1o y cuyo recuerdo te acompa\u00f1a toda la vida. <\/p>\n<p><\/p>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164191058298743090\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R6rkaA4lKTI\/AAAAAAAAANg\/aft6T7TokO0\/s400\/_023.jpg\" border=\"0\" \/><br \/>As\u00ed, noche tras noche, Sacai y yo nos citamos en la Doble R y nos sentamos en la mesa de todos estos seres parasimp\u00e1ticos, dejando que nos cuenten sus historias. Ahora, el protagonismo es para Windom Earl. \u00a1Qu\u00e9 nervios! Y, adem\u00e1s, nos han dicho que como fin de fiesta, antes de que nos vayamos, en esta ocasi\u00f3n nos vamos a encontrar nutridos y golosos extras que nos permitir\u00e1n profundizar, un poco m\u00e1s, en el fascinante universo de Twin Peaks, un destino vacacional que viene envuelto en una seductora Caja Dorada, pero que nada tiene que ver con Marina D\u2019Or, afortunadamente. <\/p>\n<p align=\"justify\">\n<p>Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n<p align=\"justify\">PD.- \u00bfY que me dicen de esa musiquilla de <a href=\"http:\/\/es.wikipedia.org\/wiki\/Angelo_Badalamenti\"><span style=\"color:#ff0000;\"><strong>Angelo Badalamenti<\/strong><\/span> <\/a>que, en cuanto pones los pies en el pueblo, ya no deja de sonar en cada rinc\u00f3n, en cada calle, en cada casa, en cada habitaci\u00f3n del Gran Hotel del Norte&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos vuelto a \u201cTwin Peaks\u201d. Deben de haber pasado unos quince a\u00f1os desde nuestra primera visita y, al menos, doce o trece desde que fuimos all\u00e1 por segunda vez. Y, curiosamente, nada ha cambiado en ese maravilloso y atormentado pueblo de la frontera entre los EE.UU y Canad\u00e1. A la primea persona que encontramos en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-27","post","type-post","status-publish","format-standard","hentry","category-television"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/27\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=27"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=27"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}