{"id":26634,"date":"2019-02-20T06:08:06","date_gmt":"2019-02-20T05:08:06","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=26634"},"modified":"2019-02-19T14:20:23","modified_gmt":"2019-02-19T13:20:23","slug":"el-adios-de-carbo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-adios-de-carbo\/","title":{"rendered":"El adi\u00f3s de Carb\u00f3"},"content":{"rendered":"<p>Por razones personales anunciaron que se las piran, en menos de 24 horas, Santiago Carb\u00f3, Jemi S\u00e1nchez y Baldomero Oliver. Por razones estrictamente personales, insisten, pero\u2026<\/p>\n<figure id=\"attachment_26635\" aria-describedby=\"caption-attachment-26635\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=26635\" rel=\"attachment wp-att-26635\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-26635\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Santiago-carb\u00f3-Consejo-Social-300x193.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Santiago-carb\u00f3-Consejo-Social-300x193.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Santiago-carb\u00f3-Consejo-Social.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-26635\" class=\"wp-caption-text\">El d\u00eda que Santiago Carb\u00f3 se incorporaba al Consejo Social<\/figcaption><\/figure>\n<p>Son situaciones diferentes, pero que dos de los mejores concejales del gobierno de Francisco Cuenca decidan bajarse del barco resulta de lo m\u00e1s elocuente. Ambos tienen puesto de trabajo fuera de la pol\u00edtica y, tras estos a\u00f1os dedicados al municipalismo, no les duele en prendas dar un paso lateral y volver a sus carreras profesionales. Un gesto que les honra, sin duda, pero que deja tocado a un PSOE que pierde a dos de sus referentes m\u00e1s y mejor valorados.<\/p>\n<p>Lo de Carb\u00f3 es m\u00e1s doloroso. Santiago Carb\u00f3 es un economista de reconocido prestigio internacional que asumi\u00f3 una tarea complicada, pero muy necesaria en esta tierra. Menos de dos a\u00f1os despu\u00e9s de acceder a la presidencia del Consejo Social, se va. Cansado, aburrido, harto y mareado.<\/p>\n<p>Lo escrib\u00ed en este mismo espacio el 22 de abril de 2017: \u201cQuerido Santiago, llegas al Consejo Social en un momento muy complicado para Granada. Y, precisamente por eso, tu concurso va a ser m\u00e1s necesario que nunca. \u00a1Bienvenido!\u201d. No fue la misma bienvenida la dispensada por los representantes de los partidos pol\u00edticos, siempre celosos de sus roalillos, familias, parcelas, \u00e1reas de influencia y cuotas de poder. (<a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/bienvenido-santiago\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>, aquella columna)<\/p>\n<p>A la vista de su despedida, no parece que Carb\u00f3 haya contado con demasiada colaboraci\u00f3n en este par de a\u00f1os: critica los enfrentamientos partidistas, denuncia la falta de recursos -escasos, casi inexistentes- y concluye que el Consejo Social deber\u00eda ser un lugar de encuentro y no de enfrentamiento. (Leer <a href=\"https:\/\/www.ideal.es\/granada\/disputas-partidistas-sacan-20190219213323-nt.html\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>)<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=26636\" rel=\"attachment wp-att-26636\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26636\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Santiago-Carb\u00f3-foto-Ram\u00f3n-L.-P\u00e9rez-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Santiago-Carb\u00f3-foto-Ram\u00f3n-L.-P\u00e9rez-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Santiago-Carb\u00f3-foto-Ram\u00f3n-L.-P\u00e9rez.jpg 623w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Mal vamos en Granada. Un PSOE err\u00e1tico trata de vendernos una ciudad nueva y diferente, que funciona. Seg\u00fan ellos. Un amn\u00e9sico PP, que parece haber olvidado que ocup\u00f3 la Plaza del Carmen durante trece a\u00f1os seguidos, promete quim\u00e9ricos telef\u00e9ricos e imposibles pistas de esqu\u00ed. Podemos se desangra en sus luchas intestinas y Cs, de perfil.<\/p>\n<p>En precampa\u00f1a electoral, nos hartaremos de o\u00edr promesas, planes y propuestas. Convendr\u00e1 no olvidar lo \u00fanico cierto e incontestable: que una persona independiente, del prestigio y la solidez intelectual de Santiago Carb\u00f3, se ha visto obligado a dejar el Consejo Social por la cortedad de miras, la inoperancia y la falta de ambici\u00f3n de una clase pol\u00edtica granadina que no est\u00e1 a la altura de las circunstancias.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por razones personales anunciaron que se las piran, en menos de 24 horas, Santiago Carb\u00f3, Jemi S\u00e1nchez y Baldomero Oliver. Por razones estrictamente personales, insisten, pero\u2026 Son situaciones diferentes, pero que dos de los mejores concejales del gobierno de Francisco Cuenca decidan bajarse del barco resulta de lo m\u00e1s elocuente. Ambos tienen puesto de trabajo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[17431,17430,17428,14369,17429],"class_list":["post-26634","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-adios-baldomero-oliver","tag-adios-jemi-sanchez","tag-adios-santiago-carbo","tag-consejo-social-granada","tag-dimision-santiago-carbo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=26634"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26634\/revisions"}],"predecessor-version":[{"id":26639,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26634\/revisions\/26639"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=26634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=26634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=26634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}