{"id":26550,"date":"2019-02-05T11:33:58","date_gmt":"2019-02-05T10:33:58","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=26550"},"modified":"2019-02-06T11:37:50","modified_gmt":"2019-02-06T10:37:50","slug":"sociedad-civil-vs-politica-profesional","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/sociedad-civil-vs-politica-profesional\/","title":{"rendered":"Sociedad civil vs. Pol\u00edtica profesional"},"content":{"rendered":"<p>\u00bfEn qu\u00e9 quedamos? \u00bfQueremos que la sociedad civil se incorpore a la vida p\u00fablica o seguimos defendiendo la pol\u00edtica como una carrera profesional? Menuda se ha liado con lo de Pepu Hern\u00e1ndez, antiguo seleccionador nacional de baloncesto, como candidato a la Alcald\u00eda de Madrid.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/sociedad-civil-vs-politica-profesional\/sociedad-civil\/\" rel=\"attachment wp-att-26551\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26551\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Sociedad-civil-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Sociedad-civil-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Sociedad-civil.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No tiene que ver -al menos, no solo- con lo de la facturaci\u00f3n de charlas y conferencias: muchas de las cr\u00edticas m\u00e1s furibundas vienen de los propios militantes del PSOE, que no entienden por qu\u00e9 Pedro S\u00e1nchez les ha puesto un tap\u00f3n de semejante calibre. En su lenguaje, pol\u00edticamente correcto, lo llaman malestar. La realidad: que est\u00e1n jodidos. Mucho.<\/p>\n<p>Insisto: \u00bfen qu\u00e9 quedamos? \u00bfQueremos que gente de fuera de los partidos de el salto a la pol\u00edtica? En ese caso, \u00bfqu\u00e9 se les va a pedir? \u00bfQue empiecen de meritorios y calienten banquillo, curti\u00e9ndose en los entrenamientos antes de salir a jugar a la cancha? Evidentemente, no. M\u00e1s que nada porque, en ese caso, pocas personas se animar\u00edan a interrumpir sus carreras profesionales, en aras del bien com\u00fan.<\/p>\n<p>La de los partidos con la sociedad civil es una relaci\u00f3n problem\u00e1tica y un tanto esquizofr\u00e9nica: la interpelan continuamente, aluden a ella, la rondan, la requiebran y la tientan, pero cuando se acerca demasiado; sospechan. Y, en muchos casos, reniegan.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/sociedad-civil-vs-politica-profesional\/sociedad-civil-politica\/\" rel=\"attachment wp-att-26552\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26552\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Sociedad-civil-pol\u00edtica-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Sociedad-civil-pol\u00edtica-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Sociedad-civil-pol\u00edtica.jpg 638w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los partidos pol\u00edticos, m\u00e1s all\u00e1 de ideolog\u00eda y creencias, son empresas. Empresas que contratan a cientos de miles de trabajadores, de forma directa o indirecta. Empresas de las que comen, literalmente, infinidad de trabajadores a quienes la llegada de uno de esos de fuera, adem\u00e1s de quitarles un puesto, les descoloca y altera su statu quo.<\/p>\n<p>En cualquier formaci\u00f3n pol\u00edtica hay m\u00e1s c\u00f3digos internos y normas no escritas que en una multinacional de alcance planetario. Hay jerarqu\u00edas. Y familias, lealtades, grupos y \u2018roalillos\u2019 de toda laya.<\/p>\n<p>Entonces aparece \u00e9l. O ella. El que viene de fuera. El ungido. O ungida. Al que han presentado para cambiarlo todo. Solo que los de dentro, en su inmensa mayor\u00eda, tampoco creen que deba ser para tanto. \u00bfToda una vida dedicada al partido, en cuerpo y alma, para que llegue un advenedizo y ponga en solfa su trayectoria? \u00bfQu\u00e9 sabr\u00e1n ellos? No, gracias.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/sociedad-civil-vs-politica-profesional\/imbroda-consejero\/\" rel=\"attachment wp-att-26553\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26553\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Imbroda-consejero-300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Imbroda-consejero-300x150.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/02\/Imbroda-consejero.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Lo de Pepu en Madrid. Lo de Imbroda en Andaluc\u00eda. Lo de Duque en el gobierno de S\u00e1nchez. Ejemplos de que algo puede estar cambiando\u2026 \u00bfpara seguir todo igual?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26053\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26053 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEn qu\u00e9 quedamos? \u00bfQueremos que la sociedad civil se incorpore a la vida p\u00fablica o seguimos defendiendo la pol\u00edtica como una carrera profesional? Menuda se ha liado con lo de Pepu Hern\u00e1ndez, antiguo seleccionador nacional de baloncesto, como candidato a la Alcald\u00eda de Madrid. No tiene que ver -al menos, no solo- con lo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[14612,17370,17369,17368,17366,17367],"class_list":["post-26550","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-candidatos-independientes","tag-duque-ministro","tag-imbroda-consejero","tag-malestar-en-el-partido","tag-pepu-candidato","tag-politica-profesional"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=26550"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26550\/revisions"}],"predecessor-version":[{"id":26555,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26550\/revisions\/26555"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=26550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=26550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=26550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}