{"id":26412,"date":"2019-01-16T10:23:21","date_gmt":"2019-01-16T09:23:21","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=26412"},"modified":"2019-01-16T10:23:21","modified_gmt":"2019-01-16T09:23:21","slug":"el-discurso-del-presidente","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-discurso-del-presidente\/","title":{"rendered":"El discurso del presidente"},"content":{"rendered":"<p>Escucharlo, no lo escuch\u00e9. Pero lo le\u00ed. Con calma, tiempo y detenimiento. Al discurso de Moreno Bonilla, me refiero. El pr\u00f3ximo presidente de la Junta de Andaluc\u00eda, cuyo nombre sigue sonando a \u00e1rbitro que anula un gol en Las Gaunas, ha desgranado una amplia serie de propuestas\u2026 sobre las que no voy a comentar nada, a la espera de ver cu\u00e1ndo y, sobre todo, c\u00f3mo se materializan. Si llegan a concretarse, por supuesto.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-discurso-del-presidente\/moreno-bonilla-pulseras\/\" rel=\"attachment wp-att-26413\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26413\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-pulseras-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-pulseras-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-pulseras-768x512.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-pulseras-644x429.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-pulseras.jpg 1134w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El buenismo que rezuman, como no podr\u00eda ser de otra manera, obliga a tomarlas con toda la precauci\u00f3n del mundo. A fin de cuentas, \u00bfqui\u00e9n no firmar\u00eda por m\u00e1s y mejor empleo, menos impuestos, mejor sanidad, educaci\u00f3n y servicios sociales, etc\u00e9tera, etc\u00e9tera?<\/p>\n<p>Voy a quedarme con otras variables del discurso presidencial. Por ejemplo, el cambio, una de las palabras m\u00e1s repetidas. Lo de que los andaluces han votado por el cambio es un eufemismo, que un alt\u00edsimo porcentaje no vot\u00f3 nada. Un eufemismo bastante acertado, cierto es, que hablas con socialistas y muy socialistas y, en privado, la mayor\u00eda comprende que la gente estuviera hasta el copet\u00edn.<\/p>\n<figure id=\"attachment_26414\" aria-describedby=\"caption-attachment-26414\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-discurso-del-presidente\/moreno-bonilla-soraya\/\" rel=\"attachment wp-att-26414\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-26414\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-Soraya-300x196.jpg\" alt=\"\" width=\"300\" height=\"196\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-Soraya-300x196.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-Soraya-644x422.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-Soraya.jpg 660w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-26414\" class=\"wp-caption-text\">\u00a1Qu\u00e9 lejos quedan estos tiempos!<\/figcaption><\/figure>\n<p>Los riesgos, con lo del cambio, son dos. El primero, lampedusiano: cambiarlo todo para que todo siga igual. Moreno Bonilla lo descarta espec\u00edficamente. El segundo: cambiar por cambiar, a tontas y a locas; r\u00e1pido y corriendo. Moreno Bonilla anuncia reformas, austeridad y racionalizaci\u00f3n. Palabras que, nuevamente sobre el papel, suenan bien. O no. Que ya sabemos a lo que conduce el austerecidio radical que tanto le gusta a la derecha.<\/p>\n<p>Eficiencia. Otro de los conceptos esgrimidos por Moreno Bonilla. Ojito, a ver si con lo del cambio y la austeridad, el nuevo equipo de gobierno empieza por tomar medidas que, a medio o largo plazo, acaben resultando ineficientes y empobrecedoras. Que lo de cortar cabezas a diestro y siniestro -algo que mucha gente espera, frot\u00e1ndose las manos- es una tentaci\u00f3n muy peligrosa. En ese sentido, recomendar mesura y sentido com\u00fan. El respeto al que tambi\u00e9n aludi\u00f3 el presidente.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-discurso-del-presidente\/moreno-bonilla\/\" rel=\"attachment wp-att-26415\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26415\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla-644x428.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2019\/01\/Moreno-Bonilla.jpg 660w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Di\u00e1logo. No le queda otra, con su gobierno a tras bandas. Esperemos que no sea sin\u00f3nimo de sumisi\u00f3n a los postulados m\u00e1s radicales de ya saben ustedes qui\u00e9nes.<\/p>\n<p>Y alternancia. Palabra que suena preciosa cuando se inicia una nueva andadura, pero que ya le recordaremos al nuevo presidente de la Junta de Andaluc\u00eda a la vuelta de los a\u00f1os, con maliciosa iron\u00eda.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26053\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26053 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escucharlo, no lo escuch\u00e9. Pero lo le\u00ed. Con calma, tiempo y detenimiento. Al discurso de Moreno Bonilla, me refiero. El pr\u00f3ximo presidente de la Junta de Andaluc\u00eda, cuyo nombre sigue sonando a \u00e1rbitro que anula un gol en Las Gaunas, ha desgranado una amplia serie de propuestas\u2026 sobre las que no voy a comentar nada, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[17294,17295,17296],"class_list":["post-26412","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-el-discurso-del-presidente","tag-moreno-bonilla-presidente","tag-pactos-moreno-bonilla"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=26412"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26412\/revisions"}],"predecessor-version":[{"id":26417,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26412\/revisions\/26417"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=26412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=26412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=26412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}