{"id":26115,"date":"2018-11-23T20:22:08","date_gmt":"2018-11-23T19:22:08","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=26115"},"modified":"2018-11-27T20:33:27","modified_gmt":"2018-11-27T19:33:27","slug":"casa-piolas","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/casa-piolas\/","title":{"rendered":"Casa Piolas"},"content":{"rendered":"<p><b>Casa Piolas: renovada cocina de vanguardia con productos de temporada<\/b><\/p>\n<p><b>Situado en Algarinejo, el restaurante Casa Piolas colabora esta temporada con Diego Gallegos, el \u201cChef del caviar\u201d de Sollo, establecimiento distinguido con una Estrella Michel\u00edn \u00a0<\/b><b>(<a href=\"https:\/\/gourmet.ideal.es\/restaurantes\/renovada-cocina-vanguardia-20181123192654-ntvo.html\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a> la edici\u00f3n online en el Gourmet de IDEAL) \u00a0<\/b><\/p>\n<p><b><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/casa-piolas\/casa-piolas-jesus-lens\/\" rel=\"attachment wp-att-26116\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26116\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-232x300.jpg\" alt=\"\" width=\"232\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-232x300.jpg 232w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-768x993.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-644x833.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens.jpg 792w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/a>\u00a0<\/b><\/p>\n<p><b><i>Direcci\u00f3n: <\/i><\/b><i>C\/ Calle Ram\u00f3n y Cajal, 1. Algarinejo (Granada) <\/i><b><i>Tfno. Reservas: <\/i><\/b><i>958 312 251 <\/i><b><i>Jefe de cocina<\/i><\/b><i>: Jos\u00e9 Caracuel G\u00e1mez. <\/i><b><i>Jefe de sala<\/i><\/b><i>: Luc\u00eda Caracuel C\u00e1liz. <\/i><b><i>Estilo de cocina: <\/i><\/b><i>Producto de temporada con el sello personal de Jos\u00e9 Caracuel. <\/i><b><i>Precio medio<\/i><\/b><i>: A la carta: 35 euros. Men\u00fa degustaci\u00f3n: 55 euros. <\/i><b><i>Men\u00fa del d\u00eda<\/i><\/b><i>: No. <\/i><b><i>Imprescindible<\/i><\/b><i>: Aceitunas, choto y chuletillas Piolas. <\/i><b><i>Capacidad:<\/i><\/b><i> 40 comensales. <\/i><b><i>Cierra<\/i><\/b><i>: Lunes y martes. <\/i><b><i>Cerveza<\/i><\/b><i>: Damm. <\/i><b><i>Caf\u00e9<\/i><\/b><i>: Candela. <\/i><b><i>Wifi<\/i><\/b><i>: S\u00ed. <\/i><b><i>Aparcamiento<\/i><\/b><i>: Aleda\u00f1os.<\/i><\/p>\n<p>El pasado mes de agosto sal\u00edamos de Casa Piolas tras una larga conversaci\u00f3n con su chef, Jos\u00e9 Caracuel, en la que nos contaba las ideas que ten\u00eda para la nueva temporada. Su prop\u00f3sito era tomarse unas semanas de reflexi\u00f3n y, a la vuelta, ofrecer una renovada propuesta gastron\u00f3mica que, sin renunciar a sus principios, fuera nueva y diferente. (Leer <a href=\"https:\/\/www.ideal.es\/granada\/casa-piolas-viaje-20180823234053-nt.html\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>)<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/casa-piolas\/casa-piolas-jesus-lens-gourmet\/\" rel=\"attachment wp-att-26117\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26117\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-Gourmet-229x300.jpg\" alt=\"\" width=\"229\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-Gourmet-229x300.jpg 229w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-Gourmet-644x843.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-Gourmet.jpg 733w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/a><\/p>\n<p>Efectivamente, as\u00ed ha sido. Casa Piolas se ha reinventado para seguir ofreciendo una cocina de vanguardia que parte de los productos de temporada y de cercan\u00eda, siempre interpretados a trav\u00e9s del personal sello de Caracuel, impulsor en Granada de la filosof\u00eda slow food.<\/p>\n<p>De esta manera, Casa Piolas cambiar\u00e1 su men\u00fa cuatro veces al a\u00f1o, adapt\u00e1ndolo a las estaciones, jugando en cada una de ellas con los productos de cada temporada y aprovechando sus caracter\u00edsticas m\u00e1s singulares.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/casa-piolas\/casa-piolas-jesus-lens-rock\/\" rel=\"attachment wp-att-26118\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26118\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-rock-231x300.jpg\" alt=\"\" width=\"231\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-rock-231x300.jpg 231w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-rock-644x837.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-Jes\u00fas-Lens-rock.jpg 739w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><\/a><\/p>\n<p>As\u00ed por ejemplo, en la brillante y espectacular propuesta gastron\u00f3mica de Casa Piolas para este oto\u00f1o se puede disfrutar de un sensacional Ajoverde, pimiento dulce y gallina escabechada; un sorprendente y crom\u00e1tico Tartar de salchich\u00f3n y betabel; unas tiern\u00edsimas, sabrosas y juguetonas Ancas de rana zarandeadas y un suculento bocado de Foie, chocolate y naranja que explota en la boca con toda la intensidad de sabor.<\/p>\n<p>En esta nueva andadura, Jos\u00e9 Caracuel cuenta con la colaboraci\u00f3n de un viejo conocido: el chef Diego Gallegos, cuya andadura profesional arranc\u00f3 en Casa Piolas y que actualmente goza de una Estrella Michel\u00edn en su restaurante Sollo de Fuengirola. Una alianza que resulta perceptible en platos como el Esturi\u00f3n, patata y su jugo o en las incre\u00edbles Mollejas y caviar; dos gui\u00f1os a ese Riofr\u00edo tan vinculado a Caracuel y Gallegos, al que no en vano se conoce popularmente como \u201cel chef del caviar\u201d.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/casa-piolas\/casa-piolas\/\" rel=\"attachment wp-att-26121\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26121\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Comer en Casa Piolas es hacer un viaje. Un viaje que nos conduce por todos y cada uno de los rincones de nuestra Granada gastron\u00f3mica, no en vano, el 80% de lo que comemos es de procedencia granadina y otro 15%, andaluza, que el movimiento slow food apela, adem\u00e1s de a la calma y a la lentitud, a la relaci\u00f3n de proximidad con los proveedores, ese Km. 0 que tanto favorece la econom\u00eda circular.<\/p>\n<p>En ese sentido, es una alegr\u00eda constatar que el sensacional men\u00fa degustaci\u00f3n de Casa Piolas sigue arrancando con una encendida reivindicaci\u00f3n de la aceituna, un producto al que estamos tan acostumbrados que, en demasiadas ocasiones, no le concedemos la importancia que tiene.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/casa-piolas\/casa-piolas-aceitunas\/\" rel=\"attachment wp-att-26120\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26120\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-aceitunas-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-aceitunas-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-aceitunas-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Piolas-aceitunas-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00a1Es flipante el muestrario de aceitunas con que comienza la comida! Todas diferentes, presentadas sobre un racial tronco de olivo, cada una de ellas portadora de una historia, de un sentido, de una explicaci\u00f3n. Porque en Casa Piolas, cada bocado cuenta. Sin olvidar a la Gilda, otro de esos bocados a reivindicar y que se presenta en su doble vertiente: con la anchoa ahumada y al natural.<\/p>\n<p>Dec\u00edamos que el men\u00fa degustaci\u00f3n de Casa Piolas es una invitaci\u00f3n al viaje que, partiendo de los productos m\u00e1s cercanos, nos conduce lejos. Por ejemplo, a M\u00e9xico, con la Ternera de palancal, camote y curry; un plato enormemente evocador gracias a sus sabores de ultramar.<\/p>\n<p>Y de vuelta al terru\u00f1o, el plato de Lentejas y chuletas al estilo piolas, un homenaje de Jos\u00e9 Caracuel a su abuela y a la cocina casera que recupera los sabores de toda la vida. Un plato que demuestra que tradici\u00f3n y modernidad no est\u00e1n re\u00f1idas.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/casa-piolas\/casa-pilas-lentejas-y-chuletillas\/\" rel=\"attachment wp-att-26122\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-26122\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Pilas-lentejas-y-chuletillas-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Pilas-lentejas-y-chuletillas-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Pilas-lentejas-y-chuletillas-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/Casa-Pilas-lentejas-y-chuletillas-644x859.jpg 644w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Una generosa selecci\u00f3n de los premiad\u00edsimos quesos de la comarca sirven de transici\u00f3n al postre, un cremoso de Miel, polen y flores que se deshace en la boca, seguido de un Chocolate, almendra y granada repleto de matices y texturas.<\/p>\n<p>Otro detalle del men\u00fa degustaci\u00f3n de Casa Piolas: el exquisito cuidado de los vinos, por supuesto, con un trato muy cari\u00f1oso a las bodegas granadinas que mejor trabajo est\u00e1n haciendo. Porque el compromiso con la proximidad tambi\u00e9n es esto.<\/p>\n<p>Resulta sorprendente c\u00f3mo Jos\u00e9 Caracuel ha renovado por completo su men\u00fa degustaci\u00f3n, aprovechando las sinergias de su colaboraci\u00f3n con Diego Gallegos y utilizando Sollo Experience, su taller de I+D+i. Una reinvenci\u00f3n que se apoya en la consolidada filosof\u00eda y s\u00f3lidos principios de Casa Piolas para seguir avanzando en la senda de la excelencia, al punto de ofrecer ahora mismo una de las propuestas gastron\u00f3micas m\u00e1s excitantes de la provincia de Granada.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-26053\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-26053 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/11\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casa Piolas: renovada cocina de vanguardia con productos de temporada Situado en Algarinejo, el restaurante Casa Piolas colabora esta temporada con Diego Gallegos, el \u201cChef del caviar\u201d de Sollo, establecimiento distinguido con una Estrella Michel\u00edn \u00a0(AQU\u00cd la edici\u00f3n online en el Gourmet de IDEAL) \u00a0 \u00a0 Direcci\u00f3n: C\/ Calle Ram\u00f3n y Cajal, 1. Algarinejo (Granada) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[30,16338],"tags":[17109,17115,17114,17110,17112,17119,17118,17116,17113,17111,17117],"class_list":["post-26115","post","type-post","status-publish","format-standard","hentry","category-gastronomadas","category-gourmet","tag-casa-piolas","tag-casa-piolas-ideal","tag-casa-piolas-jesus-lens","tag-casa-piolas-menu-degustacion","tag-casa-piolas-y-la-estrella-pa-cuando","tag-diego-gallegos","tag-diego-gallegos-casa-piolas","tag-jose-caracuel","tag-joseillo-casa-piolas","tag-precio-menu-degustacion-casa-piolas","tag-sollo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=26115"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26115\/revisions"}],"predecessor-version":[{"id":26127,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26115\/revisions\/26127"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=26115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=26115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=26115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}