{"id":26,"date":"2008-02-06T23:55:00","date_gmt":"2008-02-06T22:55:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=26"},"modified":"2008-02-06T23:55:00","modified_gmt":"2008-02-06T22:55:00","slug":"en-el-valle-de-elah","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/en-el-valle-de-elah\/","title":{"rendered":"EN EL VALLE DE ELAH"},"content":{"rendered":"<table id=\"HB_Mail_Container\" height=\"100%\" cellspacing=\"0\" cellpadding=\"0\" width=\"100%\" border=\"0\" unselectable=\"on\">\n<div align=\"justify\"><\/div>\n<tbody>\n<div align=\"justify\"><\/div>\n<tr height=\"100%\" width=\"100%\" unselectable=\"on\">\n<div align=\"justify\"><\/div>\n<td id=\"HB_Focus_Element\" valign=\"top\" width=\"100%\" background=\"\" height=\"250\" unselectable=\"off\">\n<div align=\"justify\">Dos eran las razones fundamentales por las que ten\u00eda apuntada \u201cEn el valle de Elah\u201d entre las pel\u00edculas imprescindibles para ver en el cine a lo largo de estas semanas. La primera, su director. Porque yo fui un gran defensor de aquella \u201cCrash\u201d que, como algunas tardes de toros, provoc\u00f3 divisi\u00f3n de opiniones en cr\u00edtica y p\u00fablico. S\u00ed. A m\u00ed s\u00ed me emocion\u00f3 la oscarizada pel\u00edcula de Paul Haggis que, adem\u00e1s, ahora va a ser convertida en serie televisiva. Me gust\u00f3 c\u00f3mo trazaba los v\u00ednculos entre los personajes y c\u00f3mo ligaba las diferentes historias, basadas en unas relaciones de causa-efecto muy mediatizadas por unas casualidades que jugaban un importante papel. <\/div>\n<div align=\"justify\"><\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164005331027962034\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/R6o7fQ4lKLI\/AAAAAAAAAMc\/NlMBoqwuuoA\/s400\/_06.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">La segunda raz\u00f3n es que \u201cEn el valle de Elah\u201d es la \u00fanica pel\u00edcula que nuestro querido, le\u00eddo y respetado Carlos Boyero ha considerado como extraordinaria, sin peros ni matizaciones, desde que se ha instalado en El Pa\u00eds. Que est\u00e1 el hombre como m\u00e1s pesimista, la verdad.<\/p>\n<p>Y all\u00e1 que nos fuimos, Sacai y yo. A una de las salas m\u00e1s peque\u00f1as de Neptuno. Coincidimos, martes a las 21.15, con otras veinte personas. Lo que no est\u00e1 mal. Y comienza la pel\u00edcula. Y la angulosa cara de Tommy Lee Jones, m\u00e1s llena de arrugas que nunca, se apodera de la pantalla. <\/p>\n<div align=\"justify\"><\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164005335322929378\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R6o7fg4lKOI\/AAAAAAAAAM0\/EKVUR6S39AI\/s400\/_017.jpg\" border=\"0\" \/><br \/>\u00a1Qu\u00e9 rostro, el de este hombre! Se podr\u00eda dar una clase de geograf\u00eda f\u00edsica sobre \u00e9l. Pesadumbre, tristeza, rigor, compromiso, seriedad&#8230; todo eso transmite el personaje, en el arranque de la pel\u00edcula. E inquietud. Porque su hijo, a la vuelta de Irak, a\u00fan no le ha llamado. \u00bfC\u00f3mo es posible? \u00bfTantas ganas de juerga ten\u00eda el chaval, que ni siquiera llam\u00f3 a sus padres para confirmarles que hab\u00eda llegado bien y hab\u00eda tenido un buen viaje?<\/p>\n<p>Pero, cuando termina el permiso de 72 horas y el chico sigue sin volver a la base, su padre, antiguo sargento de la polic\u00eda militar, viaja hasta all\u00ed para saber qu\u00e9 ha pasado. Denuncia su desaparici\u00f3n y, a partir de ah\u00ed, inicia un descenso a los infiernos que nos recuerda, mucho, al de George C. Scott en \u201cHardcore. Un mundo oculto\u201d. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164005339617896690\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R6o7fw4lKPI\/AAAAAAAAAM8\/lpYdg112PdQ\/s400\/_016.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">La pel\u00edcula es morosa y premiosa, sin estridencias. Como el car\u00e1cter del padre, impresionante y terriblemente caracterizado por un Lee Jones que se adapta al papel como un guante. S\u00f3lo hay un momento en que, comprensiblemente, pierde los papeles. El contrapunto emotivo, sin embargo, lo pone el cort\u00edsimo papel de la madre, una Susan Sarandon m\u00e1s envejecida que nunca.<\/p>\n<p>Se desarrolla un conflicto de jurisdicciones, civil y militar, que introduce en escena a una polic\u00eda joven y algo amargada, pesimista, pero a\u00fan no excesivamente maleada por la vida. Y ya est\u00e1n todos los protagonistas en pantalla, interactuando en una pel\u00edcula que transmite una amargura y una desaz\u00f3n de lo m\u00e1s triste y pesarosa. A medida que los protagonistas van descubriendo la verdad de lo que pas\u00f3 con el hijo de Tommy Lee Jones, a medida que \u00e9ste va adquiriendo lucidez sobre la vida de su hijo, la pel\u00edcula se va haciendo cada vez m\u00e1s ominosa y dura, espesa, densa. Siempre se ha dicho que la verdad jode, pero curte. La pregunta es, \u00bfnecesitaba Tommy Lee, a las alturas de vida en que se encuentra, curtirse m\u00e1s a\u00fan? Por como termina la pel\u00edcula, con el famoso y archicomentado fotograma de la bandera, est\u00e1 claro que s\u00ed. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164005335322929346\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R6o7fg4lKMI\/AAAAAAAAAMk\/jQr4F8L2JpA\/s400\/_09.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Una pel\u00edcula fr\u00eda, dura y espesa. Sin acci\u00f3n. Sin sangre. Sin sentimentalismos. Una investigaci\u00f3n que transcurre de forma serena, cient\u00edfica, met\u00f3dica, hasta que la verdad se abre paso. Un bocado de realidad que muerde las tripas del espectador. Un trago de hiel para quienes a\u00fan creen que algo positivo puede salir de la invasi\u00f3n de Irak. Una pel\u00edcula tan dura como necesaria.<\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5164005335322929362\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R6o7fg4lKNI\/AAAAAAAAAMs\/7BFbeOWrHUs\/s400\/_013.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\"><strong>Lo mejor:<\/strong> los actores y sus p\u00e9treas expresiones. La aparente falta de emoci\u00f3n de cada uno de sus fotogramas.<\/p>\n<p><strong>Lo peor:<\/strong> la innecesaria historia de la mujer y el perro. No aporta nada y distrae la atenci\u00f3n.<\/p>\n<p><strong><em>Valoraci\u00f3n: ****<\/em><\/strong> <\/p>\n<\/td>\n<\/tr>\n<div align=\"justify\"><\/div>\n<tr hb_tag=\"1\" unselectable=\"on\">\n<div align=\"justify\"><\/div>\n<td style=\"FONT-SIZE: 1pt\" height=\"1\" unselectable=\"on\">\n<p align=\"justify\"> <\/p>\n<div id=\"hotbar_promo\" align=\"justify\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Dos eran las razones fundamentales por las que ten\u00eda apuntada \u201cEn el valle de Elah\u201d entre las pel\u00edculas imprescindibles para ver en el cine a lo largo de estas semanas. La primera, su director. Porque yo fui un gran defensor de aquella \u201cCrash\u201d que, como algunas tardes de toros, provoc\u00f3 divisi\u00f3n de opiniones en cr\u00edtica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-26","post","type-post","status-publish","format-standard","hentry","category-cine"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=26"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=26"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}