{"id":25891,"date":"2018-10-25T08:49:03","date_gmt":"2018-10-25T07:49:03","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25891"},"modified":"2018-10-25T09:07:28","modified_gmt":"2018-10-25T08:07:28","slug":"historias-sobre-el-narco-en-mexico","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/historias-sobre-el-narco-en-mexico\/","title":{"rendered":"Historias sobre el Narco en M\u00e9xico"},"content":{"rendered":"<p>Este verano me pas\u00f3 una cosa curiosa. Dos buenos amigos -y ambos enormes escritores- me recomendaron la lectura del mismo libro: \u201cAlacr\u00e1n\u201d, de Salva Alemany. Me lo pusieron tan, tan, tan bien que no tard\u00e9 un chispo en hacerme con \u00e9l.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/historias-sobre-el-narco-en-mexico\/salva-alemany-y-el-narco-en-mexico\/\" rel=\"attachment wp-att-25892\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25892\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-y-el-Narco-en-M\u00e9xico-300x180.jpg\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-y-el-Narco-en-M\u00e9xico-300x180.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-y-el-Narco-en-M\u00e9xico-644x386.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-y-el-Narco-en-M\u00e9xico.jpg 745w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Les confieso que, al principio, desconfi\u00e9. \u00bfPor qu\u00e9 escribe un tipo de Valencia sobre el tr\u00e1fico de drogas en M\u00e9xico? Sobre todo, teniendo en cuenta que el del narco mexicano es un g\u00e9nero en s\u00ed mismo, con novelas como <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-poder-del-perro\/\" target=\"_blank\" rel=\"noopener\">\u201cEl poder del perro\u201d<\/a>, de Don Winslow; las de Elmer Mendoza, Barry Gifford o la mism\u00edsima Reina del Sur de P\u00e9rez Reverte.<\/p>\n<p>Si hablamos de referentes cinematogr\u00e1ficos, ah\u00ed est\u00e1n \u201cSicario\u201d o \u201cEl infierno\u201d de Luis Estrada. Y series televisivas tenemos desde \u201cEl puente\u201d hasta \u201cBreaking Bad\u201d o su estratosf\u00e9rica precuela: \u201cBetter Call Saul\u201d.<\/p>\n<p>Fi\u00e1ndome del criterio de Toni Hill y Carlos Bassas, empec\u00e9 la lectura de \u201cAlacr\u00e1n\u201d y no tard\u00e9 m\u00e1s de 24 horas en acabarla. De hecho, la historia de Santos, Lupe y Don Dimas me arrebat\u00f3 de tal manera que, al terminar sus 250 p\u00e1ginas, ten\u00eda mono. Quer\u00eda m\u00e1s. Y aprovech\u00e9 para hincarle el diente a \u201cEl C\u00e1rtel\u201d, la continuaci\u00f3n de la magistral e impactante \u201cEl poder del perro\u201d, de la que escrib\u00ed <a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-poder-del-perro\/\" target=\"_blank\" rel=\"noopener\">AQU\u00cd<\/a>. Don Winslow la public\u00f3 en 2015 y hab\u00eda ido postergando su lectura. Hasta ahora, que sufr\u00ed la picadura del alacr\u00e1n\u2026<\/p>\n<figure id=\"attachment_25893\" aria-describedby=\"caption-attachment-25893\" style=\"width: 247px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/historias-sobre-el-narco-en-mexico\/salva-alemany-en-granada-noir-foto-laura-munoz\/\" rel=\"attachment wp-att-25893\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25893\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-en-Granada-Noir.-Foto-Laura-Mu\u00f1oz-247x300.jpg\" alt=\"\" width=\"247\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-en-Granada-Noir.-Foto-Laura-Mu\u00f1oz-247x300.jpg 247w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-en-Granada-Noir.-Foto-Laura-Mu\u00f1oz-768x932.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-en-Granada-Noir.-Foto-Laura-Mu\u00f1oz-644x782.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Salva-Alemany-en-Granada-Noir.-Foto-Laura-Mu\u00f1oz.jpg 791w\" sizes=\"auto, (max-width: 247px) 100vw, 247px\" \/><\/a><figcaption id=\"caption-attachment-25893\" class=\"wp-caption-text\">Salva Alemany en Granada Noir. Foto: Laura Mu\u00f1oz<\/figcaption><\/figure>\n<p>\u00bfSaben qu\u00e9 les digo? Que siendo \u201cEl C\u00e1rtel\u201d una gran novela, \u201cAlacr\u00e1n\u201d no le va a la zaga ni tiene nada que envidiarle, dada la contundencia de su propuesta, la enjundia de sus personajes, la hilaz\u00f3n de una s\u00f3lida trama y el gran conocimiento del medio mostrado por Salva Alemany, parafraseando a la asignatura de la ESO.<\/p>\n<p>No les voy a contar de qu\u00e9 van ninguna de las dos novelas. Radicadas en la frontera entre M\u00e9xico y los Estados Unidos, ustedes se pueden hacer una idea. Aunque en \u201cAlacr\u00e1n\u201d, el narcotr\u00e1fico no es el tema central de la narraci\u00f3n, est\u00e1 presente a lo largo de la historia, condicionando las vidas de los protagonistas.<\/p>\n<p>Salva Alemany estuvo en Granada Noir, pero no tuve el tiempo necesario como para sentarme a hablar largo y tendido con \u00e9l sobre \u201cAlacr\u00e1n\u201d, la g\u00e9nesis de la novela, la labor de documentaci\u00f3n y, en general, por su forma de afrontar la escritura y su concepci\u00f3n de la literatura.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/historias-sobre-el-narco-en-mexico\/alacran-alemany\/\" rel=\"attachment wp-att-25894\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25894\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Alacr\u00e1n-Alemany-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Alacr\u00e1n-Alemany-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Alacr\u00e1n-Alemany-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Alacr\u00e1n-Alemany-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Alacr\u00e1n-Alemany.jpg 1140w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Salva es un viajero impenitente que, antes de venir a Granada, anduvo recorriendo Canad\u00e1, uno de mis pa\u00edses no visitados favorito. Tanto que, desde ni\u00f1o, nunca falta en mi armario una camisa de cuadros, rojos y negros, por si surge de improviso la oportunidad de visitar el pa\u00eds de la hoja de arce. Adem\u00e1s, otra de las novelas de Salva, \u201c\u00c9ire\u201d, transcurre en Irlanda, otro de mis pa\u00edses favoritos, este s\u00ed visitado en varias ocasiones.<\/p>\n<p>Lean \u201cAlacr\u00e1n\u201d, publicado por la editorial Amarante. Van a descubrir a dos personajazos. De los que enamoran. Y a un villano de los que no se olvidan. p\u00f3nganse en manos de Salva y d\u00e9jense guiar por una de las zonas m\u00e1s peligrosas del mundo\u2026 sin riesgos para su integridad f\u00edsica. Lo m\u00e1s, algunas palpitaciones producto de la intensidad narrativa.<\/p>\n<p>\u00bfY qu\u00e9 decir de \u201cEl C\u00e1rtel\u201d? Pues que es una extraordinaria continuaci\u00f3n de \u201cEl poder del perro\u201d, aunque parte con una desventaja: haber perdido el efecto sorpresa de la relaci\u00f3n entre Keller y Ad\u00e1n Barrera.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/historias-sobre-el-narco-en-mexico\/el-cartel-rba\/\" rel=\"attachment wp-att-25895\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25895\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-RBA-201x300.jpg\" alt=\"\" width=\"201\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-RBA-201x300.jpg 201w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-RBA.jpg 450w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/p>\n<p>Aunque, bien pensado, \u201cEl C\u00e1rtel\u201d no parece una continuaci\u00f3n al uso. Da la sensaci\u00f3n, m\u00e1s bien, de que Don Winslow dividi\u00f3 en dos partes su monumental obra sobre el narco mexicano, que ambas novelas forman un corpus tot\u00e9mico; \u201cEl Padrino\u201d del siglo XXI, podr\u00edamos decir.<\/p>\n<p>La narrativa de Winslow es dura y sin concesiones. Algunos de los momentos descritos en \u201cEl poder del perro\u201d resultaban especialmente estremecedores. Pero la realidad el narco es as\u00ed de dura.<\/p>\n<p>La continuaci\u00f3n de la historia de Barrera y Keller, ganadora del Premio RBA de Novela Negra del 2015, es buena muestra de lo que supone eso que tan pomposamente se ha dado en llamar La Guerra contra las Drogas. Una guerra que parece perdida de antemano. Porque, mientras exista una demanda tan brutal de coca\u00edna, hero\u00edna, metanfetamina o marihuana a nivel global, siempre habr\u00e1 proveedores encargados de suministrarla. Da lo mismo cu\u00e1ntos capos vayan cayendo: siempre corre el escalaf\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/historias-sobre-el-narco-en-mexico\/el-cartel-winslow\/\" rel=\"attachment wp-att-25896\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25896\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-Winslow-300x127.jpg\" alt=\"\" width=\"300\" height=\"127\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-Winslow-300x127.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-Winslow-768x326.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-Winslow-644x274.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-C\u00e1rtel-Winslow.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u201cEl C\u00e1rtel\u201d va m\u00e1s all\u00e1 de M\u00e9xico. Habla de los Estados Unidos, por supuesto. Pero tambi\u00e9n del resto de Centroam\u00e9rica. Del papel de la CIA en todo este tinglado. De las bases operativas de los c\u00e1rteles en Guatemala.<\/p>\n<p>De hecho, he tenido que leer a Winslow para entender lo que me dijo una amiga mexicana cuando se enter\u00f3 de que hab\u00eda estado viajando por carretera, entre Guatemala y la ciudad M\u00e9rida, en el Yucat\u00e1n mexicano, atravesando Chiapas: \u201cte has arriesgado a que te maten. No eres consciente de la barbaridad que has hecho\u201d. En su momento pens\u00e9 que exageraba. Despu\u00e9s de leer \u201cEl C\u00e1rtel\u201d, no lo tengo ya tan claro. Y es que la literatura, la buena literatura negra y policial, tambi\u00e9n sirve para comprender el mundo que nos rodea.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este verano me pas\u00f3 una cosa curiosa. Dos buenos amigos -y ambos enormes escritores- me recomendaron la lectura del mismo libro: \u201cAlacr\u00e1n\u201d, de Salva Alemany. Me lo pusieron tan, tan, tan bien que no tard\u00e9 un chispo en hacerme con \u00e9l. Les confieso que, al principio, desconfi\u00e9. \u00bfPor qu\u00e9 escribe un tipo de Valencia sobre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11774],"tags":[16948,16950,16949,2374,2092,16951,11487,15196,15698,5361],"class_list":["post-25891","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-rincon-oscuro","tag-alacran","tag-alacran-amarante","tag-alacran-salva-alemany","tag-cervezas-alhambra","tag-don-winslow","tag-el-cartel","tag-el-cartel-winslow","tag-fotos-laura-munoz","tag-granada-noir-4","tag-narco-mexicano"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25891"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25891\/revisions"}],"predecessor-version":[{"id":25901,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25891\/revisions\/25901"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}