{"id":25800,"date":"2018-10-14T12:00:35","date_gmt":"2018-10-14T11:00:35","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25800"},"modified":"2018-10-14T12:00:35","modified_gmt":"2018-10-14T11:00:35","slug":"el-hombre-del-traje-gris","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-hombre-del-traje-gris\/","title":{"rendered":"El hombre del traje gris"},"content":{"rendered":"<p>Sobre el anecd\u00f3tico episodio de la paradi\u00f1a en falso de Pedro S\u00e1nchez en el besamanos, no se est\u00e1 hablando lo suficiente del aut\u00e9ntico protagonista, del h\u00e9roe de la historia: el hombre del traje gris.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-hombre-del-traje-gris\/el-hombre-del-traje-gris\/\" rel=\"attachment wp-att-25801\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25801\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-hombre-del-traje-gris-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-hombre-del-traje-gris-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-hombre-del-traje-gris-644x363.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/El-hombre-del-traje-gris.jpg 755w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El hombre del traje gris es un funcionario que, al comprobar el error en que incurren el presidente del gobierno y su esposa qued\u00e1ndose junto a los Reyes, acude raudo y veloz y, con un sencillo gesto, les saca de escena. \u00a1Ni el m\u00e1s duro y amenazante personaje del Noir hubiera sido capaz de conseguir un resultado tan eficaz con esa econom\u00eda de medios, verbales y gestuales!<\/p>\n<p>Resulta especialmente relevante la autoridad del hombre del traje gris teniendo en cuenta que, con su gesto, es capaz de sacar de escena nada menos que a Pedro S\u00e1nchez, un tipo rocoso y cori\u00e1ceo, fajado en mil y una reyertas y cuya legendaria fama de ultrarresistente le precede all\u00e1 por d\u00f3nde va.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-hombre-del-traje-gris\/susana-diaz-vision\/\" rel=\"attachment wp-att-25802\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25802\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Susana-D\u00edaz-visi\u00f3n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Susana-D\u00edaz-visi\u00f3n-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Susana-D\u00edaz-visi\u00f3n.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Sosten\u00eda el coronel Kurtz en uno de sus demenciales parlamentos de \u201cApocalypse Now\u201d, hablando sobre la espartana e incuestionable disciplina de los vietnamitas de la jungla profunda, que si hubiera tenido bajo su mando a 10 divisiones formadas por esos hombres, habr\u00eda ganado aquella guerra sin dificultad alguna.<\/p>\n<p>No ser\u00eda de extra\u00f1ar que el PP de Casado le haga una oferta imposible de rechazar al hombre del traje gris, a ver si consigue sacar a S\u00e1nchez de la Moncloa. Tambi\u00e9n me imagino a Susana D\u00edaz en San Telmo, mirando acusadoramente a la gente que la ayud\u00f3 a fracasar en su asalto a Ferraz y pensando: \u201csi hubiera tenido de mi lado al hombre del traje gris\u2026\u201d.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-hombre-del-traje-gris\/pablo-casado\/\" rel=\"attachment wp-att-25803\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25803\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Pablo-Casado-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Pablo-Casado-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/10\/Pablo-Casado.jpg 643w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pensando jocosamente en todas estas historias me acord\u00e9 de una m\u00e1xima incuestionable que, sin embargo, nunca aparecer\u00e1 impresa en los sobres de az\u00facar que endulzan -e ilustran- nuestros caf\u00e9s: \u201cLos papas pasan, pero las curias permanecen\u201d.<\/p>\n<p>\u00a1Qu\u00e9 importante, para el correcto funcionamiento de cualquier instituci\u00f3n, empresa o colectivo que se precie, contar con personas como el hombre del traje gris! Gente conocedora de su oficio, discreta y silenciosa que, cuando es menester, solo necesita una mirada y un gesto con la cabeza para resolver un entuerto, por complicado que pueda parecer.<\/p>\n<p>\u00bfSabremos algo m\u00e1s sobre el hombre del traje gris en los pr\u00f3ximos d\u00edas? Porque si yo fuera un headhunter profesional, no dudar\u00eda en ir en busca de su cabeza.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sobre el anecd\u00f3tico episodio de la paradi\u00f1a en falso de Pedro S\u00e1nchez en el besamanos, no se est\u00e1 hablando lo suficiente del aut\u00e9ntico protagonista, del h\u00e9roe de la historia: el hombre del traje gris. El hombre del traje gris es un funcionario que, al comprobar el error en que incurren el presidente del gobierno y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16889,16888,16890],"class_list":["post-25800","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-besamanos","tag-el-hombre-del-traje-gris","tag-rancias-costumbres"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25800"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25800\/revisions"}],"predecessor-version":[{"id":25805,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25800\/revisions\/25805"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}