{"id":25654,"date":"2018-09-15T11:37:21","date_gmt":"2018-09-15T10:37:21","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25654"},"modified":"2018-09-15T11:37:21","modified_gmt":"2018-09-15T10:37:21","slug":"los-origenes-del-cine","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/los-origenes-del-cine\/","title":{"rendered":"Los or\u00edgenes del cine"},"content":{"rendered":"<p>\u00bfSe imaginan la historia de la literatura sin Homero, Shakespeare, Cervantes o Chandler? \u00bfLa historia de m\u00fasica sin Bach, Mozart, Beethoven o Louis Armstrong? \u00bfLa historia de la pintura sin Vel\u00e1zquez, Picasso o Warhol? \u00bfC\u00f3mo se puede entender, entonces, la historia del cine sin Ren\u00e9 Clair, Charles Vidor, Jean Renoir o G.W. Pabst?<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/los-origenes-del-cine\/granada-paradiso-2\/\" rel=\"attachment wp-att-25655\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25655\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-300x183.jpg\" alt=\"\" width=\"300\" height=\"183\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-300x183.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-768x469.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-644x394.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No s\u00e9 en los planes de estudios de colegios e institutos -aunque apostar\u00eda a que los grandes cl\u00e1sicos del cine no se encuentran entre las prioridades de la mayor\u00eda de ellos- pero en el d\u00eda a d\u00eda no veo yo a la gente muy atenta a la Historia del Cine. Lo que no deja de ser curioso, dado que vivimos en una sociedad cada vez m\u00e1s audiovisual\u2026<\/p>\n<p>En Granada tenemos la inmensa suerte de contar con una persona cuyos ojos han visto todo el cine que deber\u00edamos haber visto los dem\u00e1s, una aut\u00e9ntica enciclopedia del s\u00e9ptimo arte que, para m\u00e1s inri, sabe c\u00f3mo ense\u00f1arnos a mirar las pel\u00edculas, m\u00e1s all\u00e1 de simplemente verlas.<\/p>\n<p>Lo he escrito otras veces: Juan de Dios Salas es un lujo y el festival que ha puesto en marcha por encargo del Ayuntamiento, Granada Paradiso, viene a satisfacer las demandas de la cinefilia granadina: el cine mudo y el cine cl\u00e1sico. Su trabajo al frente del Cine Club Universitario es mod\u00e9lico y, m\u00e1s all\u00e1 de que podamos ir o no al Espacio V Centenario de la UGR, no debemos dejar de coleccionar los descargables que Juande prepara para cada uno de sus ciclos. \u00a1Son un tesoro!<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/los-origenes-del-cine\/granada-paradiso-presentacion\/\" rel=\"attachment wp-att-25656\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25656\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-presentaci\u00f3n-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-presentaci\u00f3n-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-presentaci\u00f3n.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Como los buenos festivales, Granada Paradiso no se limita a programar un pu\u00f1ado de pel\u00edculas durante una semana y, despu\u00e9s, si te he visto no me acuerdo. Tiene continuidad todo el a\u00f1o. Por ejemplo, hoy y ma\u00f1ana, en el Centro Lorca, tendremos la oportunidad de disfrutar de cl\u00e1sicos como \u201cGilda\u201d, \u201cLa gran ilusi\u00f3n\u201d o la \u201cSangre y arena\u201d de 1922, adem\u00e1s de cortos y mediometrajes franceses de a\u00f1os tan improbables como 1916 o 1918, filmados durante la I Guerra Mundial, que vienen de la mano de otra instituci\u00f3n imprescindible en nuestra ciudad: la Alianza Francesa de Granada.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/los-origenes-del-cine\/granada-paradiso-centro-lorca\/\" rel=\"attachment wp-att-25657\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25657\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-Centro-Lorca-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-Centro-Lorca-212x300.jpg 212w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-Centro-Lorca-644x913.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Granada-Paradiso-Centro-Lorca.jpg 677w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n<p>No le tengan miedo al desaf\u00edo. D\u00e9jense seducir por los cl\u00e1sicos. Entren en la sociedad secreta de los amantes del cine silente. Cada sesi\u00f3n ser\u00e1 presentada por Juande y ya ver\u00e1n que, adem\u00e1s de aprender, lo pasamos en grande.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSe imaginan la historia de la literatura sin Homero, Shakespeare, Cervantes o Chandler? \u00bfLa historia de m\u00fasica sin Bach, Mozart, Beethoven o Louis Armstrong? \u00bfLa historia de la pintura sin Vel\u00e1zquez, Picasso o Warhol? \u00bfC\u00f3mo se puede entender, entonces, la historia del cine sin Ren\u00e9 Clair, Charles Vidor, Jean Renoir o G.W. Pabst? No s\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,6],"tags":[15266,13939,10681,16799,14365,16800,7513,13777,3986],"class_list":["post-25654","post","type-post","status-publish","format-standard","hentry","category-cine","category-opinion","tag-alianza-francesa","tag-alianza-francesa-granada","tag-cine-club-universitario","tag-cine-club-universitario-granada","tag-granada-paradiso","tag-granada-paradiso-2018","tag-historia-del-cine","tag-juan-de-dios-salas","tag-origenes-del-cine"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25654"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25654\/revisions"}],"predecessor-version":[{"id":25659,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25654\/revisions\/25659"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}