{"id":25627,"date":"2018-09-11T20:41:06","date_gmt":"2018-09-11T19:41:06","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25627"},"modified":"2018-09-11T20:41:06","modified_gmt":"2018-09-11T19:41:06","slug":"esta-nerviosa-la-tierra","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/esta-nerviosa-la-tierra\/","title":{"rendered":"Est\u00e1 nerviosa la tierra"},"content":{"rendered":"<p>Ser\u00e1 por ello que viene temblando estos d\u00edas, casi sin parar. Caminaba ayer de vuelta a casa mientras pensaba sobre qu\u00e9 escribir esta columna. Dudaba entre el au revoir de Soraya y el m\u00e1ster de la Mont\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/esta-nerviosa-la-tierra\/master-monton\/\" rel=\"attachment wp-att-25628\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25628\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Master-Mont\u00f3n-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Master-Mont\u00f3n-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Master-Mont\u00f3n.jpg 643w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Tienen que ser curiosas, de un tiempo a esta parte, las reuniones y entrevistas con cualquier candidato a un puesto de responsabilidad institucional.<\/p>\n<p>\u2014\u00bfFormaci\u00f3n?<\/p>\n<p>\u2014Ense\u00f1anza superior y posgrado.<\/p>\n<p>\u2014\u00bfPero posgrado o master?<\/p>\n<p>\u2014Posgrado, posgrado.<\/p>\n<p>\u2014\u00bfDe verdad?J\u00farame por lo m\u00e1s sagrado que no tienes un master. Y queremos una declaraci\u00f3n jurada de que no has puesto un pie en la Universidad Juan Carlos I en toda tu vida. Nunca jam\u00e1s. \u00a1Es que ni para decir hola a un colega!<\/p>\n<p>El dicho \u201cTienes m\u00e1s peligro que un master de la Juan Carlos I\u201d ya se ha convertido en un cl\u00e1sico de tabernas, barras y mentideros y el tema se merec\u00eda una dosis de atenci\u00f3n.<\/p>\n<p>En esas estaba cuando un terremoto vino a sacudirnos el esqueleto. De hecho, parece que fue la r\u00e9plica de uno anterior que me hab\u00eda perdido. \u00a1Una r\u00e9plica bien contundente, pardiez!<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/esta-nerviosa-la-tierra\/terremotos\/\" rel=\"attachment wp-att-25629\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25629\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Terremotos-300x261.jpg\" alt=\"\" width=\"300\" height=\"261\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Terremotos-300x261.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Terremotos.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Yo le pronostiqu\u00e9 un 3,25, pero el bote que pegu\u00e9 fue de un 4,5, por lo menos. Con decirles que hasta me plante\u00e9 lo de situarme bajo el vano de una puerta\u2026 Que hay que elegir bien qu\u00e9 puerta, ojo. Que no todas valen. De hecho, lo m\u00e1s seguro es situarse bajo una mesa de despacho con armaz\u00f3n de acero -Isidro Mart\u00edn dixi- y esperar a que escampe.<\/p>\n<p>Est\u00e1 nerviosa la tierra, en Granada. Enjambre s\u00edsmico es como llaman los expertos en la materia a este tembloroso sindi\u00f3s. De hecho, es posible que sigan produci\u00e9ndose mene\u00edllos en los pr\u00f3ximos d\u00edas. As\u00ed que, no se asusten. Esos movimientos de la corteza terrestre no los provocan los pensionistas, que vuelven a las calles. Ni la Marea Amarilla -tan apaciguada en los \u00faltimos tiempos -por el bochorno del tren. Ni las bases del PP granadino, espoleadas por el varapalo judicial al Congreso del pasado mayo. Ni la gente de la Costa, indignada por la merma de pasajeros a\/de Melilla. Ni los usuarios de Vueling, iracundos por la sistem\u00e1tica cancelaci\u00f3n o desv\u00edos de vuelos al aeropuerto de Granada.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/esta-nerviosa-la-tierra\/vueling-reclamaciones\/\" rel=\"attachment wp-att-25630\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25630\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Vueling-reclamaciones-300x184.jpg\" alt=\"\" width=\"300\" height=\"184\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Vueling-reclamaciones-300x184.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Vueling-reclamaciones.jpg 623w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El enjambre s\u00edsmico, como la Gota Fr\u00eda, son formas que tiene la naturaleza de quitarnos importancia y recordarnos que, en realidad, no somos para tanto.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 por ello que viene temblando estos d\u00edas, casi sin parar. Caminaba ayer de vuelta a casa mientras pensaba sobre qu\u00e9 escribir esta columna. Dudaba entre el au revoir de Soraya y el m\u00e1ster de la Mont\u00f3n. Tienen que ser curiosas, de un tiempo a esta parte, las reuniones y entrevistas con cualquier candidato a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16775,16777,16776],"class_list":["post-25627","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-enjambre-de-terremotos","tag-epicentro-en-armilla","tag-terremotos-granada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25627"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25627\/revisions"}],"predecessor-version":[{"id":25632,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25627\/revisions\/25632"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}