{"id":25589,"date":"2018-09-05T13:16:59","date_gmt":"2018-09-05T12:16:59","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25589"},"modified":"2018-09-05T13:17:00","modified_gmt":"2018-09-05T12:17:00","slug":"desigualdad-y-precariedad","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/desigualdad-y-precariedad\/","title":{"rendered":"Desigualdad y precariedad"},"content":{"rendered":"<p>Cuando volv\u00ed a Carchuna, el 27 de agosto, el chiringuito que hac\u00eda espetos de sardinas y pulpo al estilo tradicional hab\u00eda dado por terminada la temporada estival: la barca estaba cubierta con piedras, puertas y ventanas chapadas, rejas cerradas con candado\u2026 y un enorme cartel de Se Vende en la fachada.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/desigualdad-y-precariedad\/espetos-sardinas\/\" rel=\"attachment wp-att-25590\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25590\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Espetos-sardinas-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Espetos-sardinas-300x199.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Espetos-sardinas-644x428.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Espetos-sardinas.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Durante el mes de julio vino a Espa\u00f1a un 5% menos de turistas extranjeros que el a\u00f1o pasado. Dicho descenso se explica de dos maneras: la ola de calor que asol\u00f3 el norte de Europa no hac\u00eda tan apetecible el viaje al c\u00e1lido sur y se empiezan a recuperar destinos de sol y playa del norte de \u00c1frica, mucho m\u00e1s baratos que Espa\u00f1a.<\/p>\n<p>Sumemos a estas cifras un dato ignominioso: el pasado 31 de agosto se destruyeron 300.000 puestos de trabajo en nuestro pa\u00eds, r\u00e9cord absoluto en la historia de Espa\u00f1a.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/desigualdad-y-precariedad\/ola-calor-rusia\/\" rel=\"attachment wp-att-25591\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25591\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Ola-calor-Rusia-300x154.jpg\" alt=\"\" width=\"300\" height=\"154\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Ola-calor-Rusia-300x154.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Ola-calor-Rusia.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los gur\u00fas de la econom\u00eda no dudan en dar por finiquitada la Crisis, m\u00e1s de diez a\u00f1os despu\u00e9s, hablando con total descaro y tranquilidad de la recuperaci\u00f3n econ\u00f3mica. Y, si bien es cierto que las cifras macro avalar\u00edan dicha tesis, hay que descender a lo micro para constatar que, de haberla, la tal recuperaci\u00f3n se basa en dos conceptos fundamentales: la desigualdad y la precariedad.<\/p>\n<p>\u00bfSe puede hablar de generaci\u00f3n perdida, en Espa\u00f1a? Posiblemente. Son cientos de miles los j\u00f3venes que, o tuvieron que emigrar, o apenas consiguen sobrevivir con sueldos de miseria por jornadas maratonianas, echando horas y horas -sin cotizar la mitad de ellas- y cobrando en negro.<\/p>\n<p>El gobierno de Pedro S\u00e1nchez ha hecho bandera de la lucha contra la explotaci\u00f3n laboral. \u00bfQu\u00e9 plazo se ha dado para comprobar si funcionan? Porque 300.000 puestos de trabajo destruidos el 31 de agosto son una buena prueba de que el mercado est\u00e1 intoxicado y de que la contrataci\u00f3n temporal se utiliza con fines fraudulentos.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/desigualdad-y-precariedad\/precariedad-laboral-espana\/\" rel=\"attachment wp-att-25592\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25592\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/09\/Precariedad-laboral-Espa\u00f1a-300x210.gif\" alt=\"\" width=\"300\" height=\"210\" \/><\/a><\/p>\n<p>Mientras, las previsiones sobre el verano tur\u00edstico en Granada son halag\u00fce\u00f1as. Parece que la capital ha tirado del carro en una estaci\u00f3n habitualmente poco propicia para ello, que el est\u00edo es temporada baja entre calles y asfalto. Ojal\u00e1 se confirmen esas cifras y, por una vez, vayamos a la contra del resto de Espa\u00f1a\u2026 en clave positiva.<\/p>\n<p>Cifras, datos, tendencias\u2026 Es importante atender a lo macro, pero resulta b\u00e1sico escrutar minuciosamente lo micro: es lo que nos da de comer a una inmensa mayor\u00eda.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando volv\u00ed a Carchuna, el 27 de agosto, el chiringuito que hac\u00eda espetos de sardinas y pulpo al estilo tradicional hab\u00eda dado por terminada la temporada estival: la barca estaba cubierta con piedras, puertas y ventanas chapadas, rejas cerradas con candado\u2026 y un enorme cartel de Se Vende en la fachada. Durante el mes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16749,16746,16747,16748,16745],"class_list":["post-25589","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-300000-despidos-31-agosto","tag-desigualdad-espana","tag-generacion-perdida-espana","tag-lucha-fraude-laboral","tag-precariedad-laboral-espana"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25589"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25589\/revisions"}],"predecessor-version":[{"id":25594,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25589\/revisions\/25594"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}