{"id":25488,"date":"2018-07-20T09:21:37","date_gmt":"2018-07-20T08:21:37","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25488"},"modified":"2018-07-20T09:21:37","modified_gmt":"2018-07-20T08:21:37","slug":"racion-de-buenas-noticias","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/racion-de-buenas-noticias\/","title":{"rendered":"Raci\u00f3n de buenas noticias"},"content":{"rendered":"<p>No es lo habitual. Por eso, ayer fue un d\u00eda grande, con el servicio de alertas de IDEAL avisando de una buena noticia detr\u00e1s de otra. El primer caf\u00e9 de la ma\u00f1ana nos lo tomamos con la portada del peri\u00f3dico anunciando, por primer vez en lustros, algo parecido a una buena noticia en relaci\u00f3n al AVE, que empezamos a ver luz al final del t\u00fanel. Esperemos que no sea la luz del propio tren, desbocado y a toda m\u00e1quina, amenazando con llevarnos por delante.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/racion-de-buenas-noticias\/ave-granada-2\/\" rel=\"attachment wp-att-25489\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25489\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Ave-Granada-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Ave-Granada-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Ave-Granada.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Al rato lleg\u00f3 la buena nueva de que Luis Garc\u00eda Montero ha sido elegido como nuevo director del Instituto Cervantes. Es m\u00fasica para mis o\u00eddos escuchar a la derecha m\u00e1s recalcitrante poner el grito en el cielo porque Luis fue candidato a la Comunidad de Madrid por IU, hace unos a\u00f1os. Lo que no dicen estos corifeos del conservadurismo m\u00e1s rancio es que, adem\u00e1s de ser catedr\u00e1tico de la UGR, ha ganado multitud de premios y galardones, incluyendo el Nacional de la Cr\u00edtica y el Nacional de Poes\u00eda.<\/p>\n<p>Una de esas personalidades de reconocido prestigio y amplia y s\u00f3lida trayectoria art\u00edstica y profesional que honran a la instituci\u00f3n que se apresta a dirigir. Que entre Mar\u00eda Jos\u00e9 Rienda, Jos\u00e9 Guirao y Jos\u00e9 Antonio Montilla; Granada y nuestra Universidad est\u00e1n quedando muy bien situadas en las esferas de poder y la gesti\u00f3n del Estado.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/racion-de-buenas-noticias\/luis-garcia-montero-2\/\" rel=\"attachment wp-att-25490\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25490\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Luis-Garc\u00eda-Montero-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Luis-Garc\u00eda-Montero-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Luis-Garc\u00eda-Montero.jpg 573w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Y hablando de la UGR\u2026 \u00a1han salido las notas! Las de verdad. Las oficiales. Las que no vienen patrocinadas por oscuras Fundaciones de corte nacionalista pagadas por entidades financieras con intereses esp\u00fareos.<\/p>\n<p>Ha llegado el ranking de Shanghai y la UGR es la segunda de Espa\u00f1a, solo por detr\u00e1s de la Universidad de Barcelona, y una de las primeras 100 del mundo. Los datos del informe son muchos y muy variados, por lo que quiero desbrozarlos y leerlos despacio. Lo m\u00e1s importante: la UGR ocupa posiciones destacadas en 34 especialidades y, en 5 de ellas, est\u00e1 en la \u00e9lite cient\u00edfica mundial.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/racion-de-buenas-noticias\/ugr-lider\/\" rel=\"attachment wp-att-25491\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25491\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/UGR-l\u00edder-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/UGR-l\u00edder-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/UGR-l\u00edder.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Excelentes noticias que nos sirven para encarar el mes de agosto con una cierta sensaci\u00f3n de satisfacci\u00f3n y relajo, a ver si olvidamos durante unas semanas el amargo llorar y crujir de dientes y ese autoflagelo que nos infligimos con demasiada frecuencia.<\/p>\n<p>Buenas noticias que nos alegran a una inmensa mayor\u00eda de granadinos, aunque alguno habr\u00e1 con un pero en la mano.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No es lo habitual. Por eso, ayer fue un d\u00eda grande, con el servicio de alertas de IDEAL avisando de una buena noticia detr\u00e1s de otra. El primer caf\u00e9 de la ma\u00f1ana nos lo tomamos con la portada del peri\u00f3dico anunciando, por primer vez en lustros, algo parecido a una buena noticia en relaci\u00f3n al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16679,16680,92,16681,16678,16682],"class_list":["post-25488","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-ave-a-granada","tag-llegara-el-ave-a-granada","tag-luis-garcia-montero","tag-ranking-universidades-shanghai","tag-ugr-lider","tag-ugr-shanghai"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25488"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25488\/revisions"}],"predecessor-version":[{"id":25493,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25488\/revisions\/25493"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}