{"id":25442,"date":"2018-07-15T10:10:19","date_gmt":"2018-07-15T09:10:19","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25442"},"modified":"2018-07-15T10:10:51","modified_gmt":"2018-07-15T09:10:51","slug":"a-una-hora-de-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/a-una-hora-de-granada\/","title":{"rendered":"A una hora de Granada"},"content":{"rendered":"<p>\u00a1Magn\u00edfico d\u00eda, el de ayer, descubriendo los secretos de tres pueblos cercanos como son Alhama, Padul y La Malaha, gracias a la iniciativa \u201cA una hora de&#8230;\u201d puesta en marcha por la Red Guadalinfo. La idea es llevar a influencers, bloggers y periodistas de toda Andaluc\u00eda a conocer localidades que est\u00e1n fuera de las rutas tur\u00edsticas m\u00e1s conocidas.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/a-una-hora-de-granada\/a-una-hora-de-granada\/\" rel=\"attachment wp-att-25444\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25444\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Granada-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Granada-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Granada-644x858.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Granada.jpg 751w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Empezamos por Alhama de Granada, villa que conozco de la \u00e9poca en que corr\u00eda el Gran Premio de Fondo de Diputaci\u00f3n, pero no es ni parecido descubrir cada uno de sus rincones con la compa\u00f1\u00eda de un gu\u00eda tan entusiasta como Alejandro. Entre las visitas a sus Iglesias barroca y g\u00f3tica, en la que se encuentra el misterioso cuadro de Alonso Cano del Cristo sin rostro, pasamos por las mazmorras, la c\u00e1rcel y dem\u00e1s edificios medievales de una de las ciudades m\u00edticas de Al \u00c1ndalus y la Reconquista.<\/p>\n<p>Sin dejarnos arrugar por el sol y el calor, nos lanzamos por el Camino de los \u00c1ngeles y disfrutamos de las impresionantes vistas de los Tajos y las (otras) Casas Colgadas. Recorrimos las acequias y vimos los f\u00f3siles acreditativos de que todo esto, antes, fue mar.<\/p>\n<p>De seguido, a La Malaha, villa que se ha especializado en el turismo termal. Tan solo recordar que, para los griegos, era Malka, Valle Templado. Para los romanos, Misarza: Alivio de dolientes. Y para los \u00e1rabes, Al-Mallah\u00e1; la salina. \u00bfQuedan claros, solo por la toponimia, los puntos fuertes de la villa? Un pueblo que est\u00e1 a un salto de Granada y a la que jurar\u00eda que no hab\u00eda venido nunca. Ahora, bien que lo siento, que el ba\u00f1o en las piscinas termales, viendo las altas cumbres de Sierra Nevada te\u00f1idas de blanco; tiene que ser una experiencia alucinante. Ojal\u00e1 salga adelante el proyecto para agrandar las piscinas y albercones y poner en uso las antiguas termas. Mi consejo: la piscina larga de m\u00e1s arriba.<\/p>\n<figure id=\"attachment_25443\" aria-describedby=\"caption-attachment-25443\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/a-una-hora-de-granada\/a-una-hora-de\/\" rel=\"attachment wp-att-25443\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25443\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de--300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de--300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de--768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de--644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-.jpg 1333w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-25443\" class=\"wp-caption-text\">Aguas termales de La Malaha<\/figcaption><\/figure>\n<p>Escribo estas l\u00edneas camino de Padul, en cuyas lagunas termina la jornada de hoy de \u201cA una hora de Granada\u201d. Una experiencia que naci\u00f3 de la bulliciosa cabeza de David, responsable de la Red Guadalinfo de Lora del R\u00edo y que comenzamos con un fest\u00edn de tapas y birras en los restaurantes de Carmela, siempre buenos aliados de estas iniciativas.<\/p>\n<figure id=\"attachment_25445\" aria-describedby=\"caption-attachment-25445\" style=\"width: 225px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/a-una-hora-de-granada\/a-una-hora-de-guadalinfo\/\" rel=\"attachment wp-att-25445\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25445\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo.jpg 750w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-25445\" class=\"wp-caption-text\">Antiguo Lavadero del Padul<\/figcaption><\/figure>\n<p>\u00bfY hoy domingo? \u00a1Castril! Que la provincia granadina es larga y pr\u00f3diga.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Magn\u00edfico d\u00eda, el de ayer, descubriendo los secretos de tres pueblos cercanos como son Alhama, Padul y La Malaha, gracias a la iniciativa \u201cA una hora de&#8230;\u201d puesta en marcha por la Red Guadalinfo. La idea es llevar a influencers, bloggers y periodistas de toda Andaluc\u00eda a conocer localidades que est\u00e1n fuera de las rutas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,24],"tags":[16630,16631,16642,16640,16638,16635,16639,16641,16632,16633,16637,16644,16634,16646,16645,16643,16636],"class_list":["post-25442","post","type-post","status-publish","format-standard","hentry","category-opinion","category-viajes","tag-a-una-hora-de","tag-a-una-hora-de-granada","tag-alhama-de-granada","tag-banos-termales-la-malaha","tag-blogs-de-viajes","tag-conocer-andalucia","tag-conocer-la-malaha","tag-descubrir-alhama-de-granada","tag-guadalinfo","tag-guadalinfo-lora-del-rio","tag-influencers-viajes","tag-mamut-padul","tag-red-guadalinfo","tag-restaurantes-carmela-granada","tag-rutal-del-mamut-padul","tag-turismo-padul","tag-viajar-andalucia"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25442"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25442\/revisions"}],"predecessor-version":[{"id":25447,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25442\/revisions\/25447"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}