{"id":25426,"date":"2018-07-12T12:17:33","date_gmt":"2018-07-12T11:17:33","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25426"},"modified":"2018-07-12T12:17:34","modified_gmt":"2018-07-12T11:17:34","slug":"maillot-noir-en-el-tour-de-francia","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/","title":{"rendered":"Maillot Noir en el Tour de Francia"},"content":{"rendered":"<p>La 105 edici\u00f3n de Tour de Francia ha comenzado de forma accidentada. Chris Froome, aspirante a ganar su quinto maillot amarillo, rod\u00f3 por los suelos en la primera jornada y perdi\u00f3 cerca de un minuto con respecto a sus rivales.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/muerte-contrarreloj-jesus-lens\/\" rel=\"attachment wp-att-25427\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25427\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Jes\u00fas-Lens-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Jes\u00fas-Lens-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Jes\u00fas-Lens-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Jes\u00fas-Lens.jpg 750w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Al d\u00eda siguiente, el espa\u00f1ol Luis Le\u00f3n, con varias costillas rotas tras otra ca\u00edda en la prueba ciclista m\u00e1s famosa e importante del mundo, tuvo que retirarse. Ca\u00eddas provocadas por circunstancias accidentales, por supuesto. Pero\u2026 \u00bfy si hubiera algo m\u00e1s; algo turbio, algo sucio y oscuro detr\u00e1s de esas ca\u00eddas?<\/p>\n<figure id=\"attachment_25428\" aria-describedby=\"caption-attachment-25428\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/aptopix-france-cycling-tour-de-france\/\" rel=\"attachment wp-att-25428\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25428\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrerreloj-Froome-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrerreloj-Froome-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrerreloj-Froome-768x472.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrerreloj-Froome-644x396.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrerreloj-Froome.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-25428\" class=\"wp-caption-text\">Froome, aspirante a ganar su quinto Tour, por los suelos<\/figcaption><\/figure>\n<p>De esa premisa parte la novela \u201cMuerte contrarreloj\u201d, del novelista mexicano Jorge Zepeda Patterson, reci\u00e9n publicada por la editorial Destino. Se trata de una novela negra que transcurre durante un Tour de Francia en el que dos amigos y compa\u00f1eros de equipo se enfrentan a un desaf\u00edo muy complicado: subir al p\u00f3dium, ambos. Un desaf\u00edo que se torna mucho m\u00e1s dif\u00edcil cuando unos extra\u00f1os accidentes empiezan a afectar a diferentes corredores del pelot\u00f3n. Un reto que se convierte en decididamente peligroso cuando un ciclista ingl\u00e9s aparece muerto en su habituaci\u00f3n, en extra\u00f1as circunstancias\u2026<\/p>\n<p>Cuesta creer que haya un asesino en el Tour de Francia. Y m\u00e1s a\u00fan, que no se suspenda la carrera si los ciclistas son amenazados de muerte. Pero el mundo del deporte profesional se rige por reglas especiales y por c\u00f3digos muchas veces incomprensibles. Basta con recordar lo ocurrido en los Juegos Ol\u00edmpicos de Munich, que continuaron celebr\u00e1ndose a pesar de un atentado terrorista contra el equipo israel\u00ed, que se cobr\u00f3 once muertos, o la disputa de la Final de la Copa de Europa de f\u00fatbol en el estadio Heysel, en 1985, a pesar de la avalancha de p\u00fablico que provoc\u00f3 el fallecimiento de 39 aficionados.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/muerte-contrarreloj-portada\/\" rel=\"attachment wp-att-25429\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25429\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-portada-175x300.jpg\" alt=\"\" width=\"175\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-portada-175x300.jpg 175w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-portada.jpg 249w\" sizes=\"auto, (max-width: 175px) 100vw, 175px\" \/><\/a><\/p>\n<p>Son de tal magnitud los intereses comerciales, econ\u00f3micos y hasta pol\u00edticos que entran en juego en un evento deportivo como el Tour de Francia que, plantearse su suspensi\u00f3n, no resulta concebible. As\u00ed lo expresa uno de los personajes de la novela de Zepeda Patterson: \u201cun maillot amarillo resuelto por la intervenci\u00f3n de un asesino pod\u00eda ser el golpe de gracia contra el Tour; apenas ahora el mundo comenzaba a sacudirse la idea de que detr\u00e1s de cada ganador hab\u00eda una nueva droga por descubrir\u201d.<\/p>\n<p>De ah\u00ed que el polic\u00eda encargado de la investigaci\u00f3n en \u201cMuerte contrarreloj\u201d actu\u00e9 de forma discreta y decida involucrar en las pesquisas a Marc Moreau, uno de los ciclistas en liza y el mejor escudero del gran l\u00edder del equipo, el norteamericano Steve Panata, ganador de cuatro Tours y aspirante a igualar el registro de Indurain, Merckx, Anquetil e Hinault.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/muerte-contrarreloj-destino\/\" rel=\"attachment wp-att-25431\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25431\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Destino-300x236.jpg\" alt=\"\" width=\"300\" height=\"236\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Destino-300x236.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Destino-768x603.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Destino-644x506.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Destino.jpg 770w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A trav\u00e9s del personaje de Moreau, un antiguo soldado con dotes detectivescas y mezcla de sangre francesa y colombiana, el lector vivir\u00e1 el desarrollo de las diferentes etapas del Tour desde dentro, sintiendo el v\u00e9rtigo de la carrera y acompa\u00f1ando a los ciclistas en su d\u00eda a d\u00eda al margen del asfalto, en las reuniones de equipo o en los desayunos y las cenas.<\/p>\n<p>Jorge Zepeda Patterson, economista y soci\u00f3logo, colaborador habitual de medios de comunicaci\u00f3n especializados en an\u00e1lisis pol\u00edticos y sociales, debut\u00f3 en el g\u00e9nero negro con su novela \u201cLos corruptores\u201d y gan\u00f3 el Premio Planeta de 2014 con \u201cMilena o el f\u00e9mur m\u00e1s bello del mundo\u201d. A lo largo de 2017 sigui\u00f3 varias carreras ciclistas como cronista deportivo, incluido el Tour, por lo que tuvo acceso a las interioridades de una de las competiciones m\u00e1s duras, \u00e9picas y sufridas del mundo.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/muerte-contrarreloj-zepeda-patterson\/\" rel=\"attachment wp-att-25430\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25430\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Zepeda-Patterson-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Zepeda-Patterson-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Zepeda-Patterson-768x512.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Zepeda-Patterson-644x429.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Muerte-contrarreloj-Zepeda-Patterson.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ese conocimiento cercano del ciclismo lo pone al servicio de una trama en la que lo policial convive con lo deportivo y, sobre todo, con el factor humano, que la relaci\u00f3n entre l\u00edderes y gregarios es lo m\u00e1s interesante de una novela por la que veremos desfilar a directores deportivos muy ambiciosos, fieles masajistas, sufridos mec\u00e1nicos, entusiastas periodistas, jueces inapelables y forofos desbocados.<\/p>\n<p>Con esta novela, Zepeda Patterson sigue los pasos de Eugenio Fuentes, novelista espa\u00f1ol que, en 2009, public\u00f3 \u201cContrarreloj\u201d en la editorial Tusquets, en la que se cuenta el asesinato de Tobias Gros, gran favorito para ganar el Tour\u2026 por quinto a\u00f1o consecutivo. En este caso, ser\u00e1 el detective Ricardo Cupido, un gran aficionado al ciclismo, el encargado de investigar el caso de forma igualmente discreta y silenciosa.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/contrarreloj-fuentes\/\" rel=\"attachment wp-att-25432\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25432\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Contrarreloj-Fuentes-199x300.jpg\" alt=\"\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Contrarreloj-Fuentes-199x300.jpg 199w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/Contrarreloj-Fuentes.jpg 252w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p>Una tradici\u00f3n literario-ciclista que arranc\u00f3, en Espa\u00f1a, con la novela \u201cEl Alpe d\u2019Huez\u201d, de Javier Garc\u00eda S\u00e1nchez. En este caso no se trata de una historia de g\u00e9nero negro, sino que el autor concentra en el desarrollo de la etapa reina del Tour toda su pasi\u00f3n por un deporte desmesurado y hom\u00e9rico. En este caso, el protagonista es Jabato, un veterano ciclista con el que nadie cuenta, pero que se empe\u00f1a en demostrar que todav\u00eda tiene mucho que decir.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/maillot-noir-en-el-tour-de-francia\/el-alpe-dhuez-novela\/\" rel=\"attachment wp-att-25433\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25433\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/El-Alpe-dHuez-novela-182x300.jpg\" alt=\"\" width=\"182\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/El-Alpe-dHuez-novela-182x300.jpg 182w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/El-Alpe-dHuez-novela-768x1266.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/El-Alpe-dHuez-novela-644x1061.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/El-Alpe-dHuez-novela.jpg 889w\" sizes=\"auto, (max-width: 182px) 100vw, 182px\" \/><\/a><\/p>\n<p>Los dos deportes literarios por excelencia son el ciclismo y el boxeo, habiendo dejado para la historia cr\u00f3nicas period\u00edsticas memorables\u2026 y un buen n\u00famero de expresiones acu\u00f1adas por el lenguaje popular. Ahora que termina el Mundial de f\u00fatbol y el Tour ocupar\u00e1 buena parte de la informaci\u00f3n deportiva es buen momento para disfrutar, tambi\u00e9n, de excelentes novelas que lo toman como referente literario.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 105 edici\u00f3n de Tour de Francia ha comenzado de forma accidentada. Chris Froome, aspirante a ganar su quinto maillot amarillo, rod\u00f3 por los suelos en la primera jornada y perdi\u00f3 cerca de un minuto con respecto a sus rivales. Al d\u00eda siguiente, el espa\u00f1ol Luis Le\u00f3n, con varias costillas rotas tras otra ca\u00edda en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,21,11774],"tags":[16620,16622,11776,12043,10787,16623,16619,16621],"class_list":["post-25426","post","type-post","status-publish","format-standard","hentry","category-deportes","category-negra-y-criminal","category-rincon-oscuro","tag-contrarreloj-novela","tag-el-alpe-dhuez-novela","tag-el-rincon-oscuro","tag-el-rincon-oscuro-lens","tag-jorge-zepeda-patterson","tag-literatura-tour-francia","tag-muerte-contrarreloj","tag-muerte-contrarreloj-patterson"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25426"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25426\/revisions"}],"predecessor-version":[{"id":25435,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25426\/revisions\/25435"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}