{"id":25321,"date":"2018-06-28T09:31:02","date_gmt":"2018-06-28T08:31:02","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25321"},"modified":"2018-06-28T09:31:03","modified_gmt":"2018-06-28T08:31:03","slug":"lejos-del-corazon-el-noir-mas-radicalmente-actual","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/lejos-del-corazon-el-noir-mas-radicalmente-actual\/","title":{"rendered":"Lejos del coraz\u00f3n: el Noir m\u00e1s radicalmente actual"},"content":{"rendered":"<p>Cuando le\u00ed que la acci\u00f3n de la nueva y reci\u00e9n publicada novela de Lorenzo Silva transcurr\u00eda entre La L\u00ednea y el Estrecho de Gibraltar, autom\u00e1ticamente pens\u00e9 en una trama con el tr\u00e1fico de drogas como tema principal. Y es que, efectivamente, \u201cLejos del coraz\u00f3n\u201d, reci\u00e9n publicada por la editorial Destino, nos devuelve a Bevilacqua y Chamorro, dos guardias civiles convertidos en icono del noir espa\u00f1ol contempor\u00e1neo.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/lejos-del-corazon-el-noir-mas-radicalmente-actual\/lorenzo-silva-el-rincon-oscuro\/\" rel=\"attachment wp-att-25322\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25322\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-El-Rinc\u00f3n-Oscuro-261x300.jpg\" alt=\"\" width=\"261\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-El-Rinc\u00f3n-Oscuro-261x300.jpg 261w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-El-Rinc\u00f3n-Oscuro.jpg 607w\" sizes=\"auto, (max-width: 261px) 100vw, 261px\" \/><\/a><\/p>\n<p>Vuelven 20 a\u00f1os despu\u00e9s de su primera aparici\u00f3n en el mercado editorial, cuando protagonizaron \u201cEl lejano pa\u00eds de los estantes\u201d, reeditada en Booket en formato de bolsillo, en una edici\u00f3n conmemorativa con pr\u00f3logo de Paul Preston, en el que podemos leer toda una declaraci\u00f3n de principios: \u201cDesde hace mucho tiempo creo que un historiador puede aprender cosas en las buenas novelas que no se encuentran en los documentos pol\u00edticos ni en los peri\u00f3dicos\u201d.<\/p>\n<p>Vuelven, Vila y Chamorro, cuando empiezan a tener m\u00e1s pasado que futuro. Vuelven, para m\u00e1s inri, para enfrentarse a un caso muy complicado, con un pu\u00f1ado de millenials de por medio. \u00a1Ay, los millenials, esa evoluci\u00f3n tan compleja del ser humano, incomprensible para quienes todav\u00eda andamos en plena transici\u00f3n entre lo anal\u00f3gico a lo digital!<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/lejos-del-corazon-el-noir-mas-radicalmente-actual\/lorenzo-silva-foto-ramon-l-perez\/\" rel=\"attachment wp-att-25323\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25323\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-Foto-Ram\u00f3n-L.-P\u00e9rez-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-Foto-Ram\u00f3n-L.-P\u00e9rez-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-Foto-Ram\u00f3n-L.-P\u00e9rez.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u201cLejos del coraz\u00f3n\u201d comienza con el secuestro de un joven inform\u00e1tico en el sur de Espa\u00f1a, a donde se traslada todo el equipo de Vila: su inseparable Virginia Chamorro, el joven y voluntarioso Arnau y la intr\u00e9pida y arrojada Salgado. Junto con el equipo local, comenzar\u00e1n una investigaci\u00f3n que les adentrar\u00e1 en el laber\u00edntico universo del c\u00edbercrimen, donde los bitcoins y la criptomonedas desempe\u00f1an un papel vital.<\/p>\n<p>No existe ahora mismo una novela negra m\u00e1s actual y actualizada, m\u00e1s rabiosamente contempor\u00e1nea, que la de Lorenzo Silva. Ni un procedural m\u00e1s concienzudo y detallista que el suyo: si ustedes quieren saber c\u00f3mo se conduce una investigaci\u00f3n policial de las de verdad, sin casualidades, intuiciones, voluntos, premoniciones o sextos sentidos; lean a Lorenzo Silva.<\/p>\n<p>Hace unos d\u00edas, durante su paso por el Talking About Twitter organizado por IDEAL, tuve ocasi\u00f3n de hablar largo y tendido con Lorenzo. Parte de lo que me cont\u00f3 lo pudieron leer ustedes <a href=\"http:\/\/www.ideal.es\/culturas\/droga-cruza-estrecho-20180618005708-ntvo.html\" target=\"_blank\" rel=\"noopener\">en esta larga y completa entrevista que public\u00f3 este peri\u00f3dico<\/a>, pero es buen momento para insistir en determinados aspectos de aquella conversaci\u00f3n. Por ejemplo, en lo complicado de introducir en la novela la informaci\u00f3n tecnol\u00f3gica necesaria para seguir la trama\u2026 de una manera literaria y atractiva al lector.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/lejos-del-corazon-el-noir-mas-radicalmente-actual\/lorenzo-silva-entrevista-jesus-lens\/\" rel=\"attachment wp-att-25324\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25324\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-entrevista-Jes\u00fas-Lens-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-entrevista-Jes\u00fas-Lens-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-entrevista-Jes\u00fas-Lens-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-entrevista-Jes\u00fas-Lens.jpg 750w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Para ello, el autor utiliza un recurso aparentemente sencillo, pero lleno de posibilidades: la entrada en escena del capit\u00e1n \u00c1lamo, un secundario de lujo al que Silva saca todo el partido. Leandro \u00c1lamo y Rub\u00e9n Bevilacqua se conocieron cuando ambos eran guardias rasos destinados en la comandancia de Guip\u00fazcoa, en los a\u00f1os m\u00e1s duros del terrorismo etarra. \u00c1lamo es un guardia veterano que no se ha actualizado tanto como Vila, por lo que, a la hora de explicarle los tecnicismos cibern\u00e9ticos a los que se enfrentan durante la investigaci\u00f3n, \u00c1lamo se convierte en los ojos y los o\u00eddos del lector.<\/p>\n<p>Adem\u00e1s, al ser un antiguo compa\u00f1ero de Bevilacqua y haber compartido un destino tan complicado como el del Pa\u00eds Vasco, las conversaciones entre \u00c1lamo y Rub\u00e9n permiten a Silva reflexionar sobre el paso del tiempo y los cambios operados en la sociedad espa\u00f1ola en las \u00faltimas d\u00e9cadas, dos de los temas sobre los que tambi\u00e9n versa \u201cLejos del coraz\u00f3n\u201d.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/lejos-del-corazon-el-noir-mas-radicalmente-actual\/lorenzo-silva-y-jesus-lens\/\" rel=\"attachment wp-att-25325\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25325\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-y-Jes\u00fas-Lens-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-y-Jes\u00fas-Lens-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-y-Jes\u00fas-Lens-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-y-Jes\u00fas-Lens-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Lorenzo-Silva-y-Jes\u00fas-Lens.jpg 1333w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Otra cuesti\u00f3n sobre la que es necesario incidir: el acceso de Lorenzo Silva a las mejores fuentes posibles de informaci\u00f3n, conseguido con gran esfuerzo, mucho tiempo y, por supuesto, gracias a su excepcional y riguroso trabajo como novelista. Ese acceso a la m\u00e1s actualizada informaci\u00f3n es lo que permite a Silva no solo escribir unos magn\u00edficos procedurales, sino clavar los di\u00e1logos y hacer que los interrogatorios, tan importantes en una investigaci\u00f3n policial -como acreditan los recientes casos de Diana Quer o el Pececito de Almer\u00eda- resulten perfectamente cre\u00edbles y generen tensi\u00f3n, nervios y adicci\u00f3n.<\/p>\n<p>Y est\u00e1 la acci\u00f3n. Porque, en un momento dado de la novela, los investigadores montan un complejo operativo en el Estrecho con barcos, lanchas y hasta helic\u00f3pteros. Lorenzo Silva tuvo la ocasi\u00f3n de participar en uno de ellos, en primera persona. De ah\u00ed que la adrenalina corra a raudales en todas y cada una de las p\u00e1ginas en las que se cuentan las vertiginosas persecuciones y las cabalgadas n\u00e1uticas de los guardias civiles.<\/p>\n<p>Y est\u00e1 la dimensi\u00f3n humana de los personajes que, enfrentada al despliegue tecnol\u00f3gico de la narraci\u00f3n, tiene m\u00e1s hondura, si cabe. Porque, como bien alerta Silva, mientras que la droga cruza el Estrecho en superplaneadoras dotadas de las m\u00e1s modernas tecnolog\u00edas, las personas que tratan de buscar una vida mejor en Europa, lo hacen en precarias pateras, aut\u00e9nticas c\u00e1scaras de nuez que, cuando naufragan, dejan un enorme caudal de muerte a su paso, como estamos ya tan a acostumbrados a ver, por desgracia.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-25214\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25214 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/0Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando le\u00ed que la acci\u00f3n de la nueva y reci\u00e9n publicada novela de Lorenzo Silva transcurr\u00eda entre La L\u00ednea y el Estrecho de Gibraltar, autom\u00e1ticamente pens\u00e9 en una trama con el tr\u00e1fico de drogas como tema principal. Y es que, efectivamente, \u201cLejos del coraz\u00f3n\u201d, reci\u00e9n publicada por la editorial Destino, nos devuelve a Bevilacqua y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11774],"tags":[16555,16551,16553,16554,16552,16550],"class_list":["post-25321","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-rincon-oscuro","tag-entrevista-lorenzo-silva","tag-fotos-ramon-l-perez","tag-lejos-del-corazon","tag-lejos-del-corazon-lorenzo-silva","tag-lorenzo-silva-en-granada","tag-lorenzo-silva-jesus-lens"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25321"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25321\/revisions"}],"predecessor-version":[{"id":25327,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25321\/revisions\/25327"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}