{"id":25202,"date":"2018-06-14T13:54:18","date_gmt":"2018-06-14T12:54:18","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=25202"},"modified":"2018-06-14T13:54:18","modified_gmt":"2018-06-14T12:54:18","slug":"la-jauria-humana","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-jauria-humana\/","title":{"rendered":"La jaur\u00eda humana"},"content":{"rendered":"<p>El director Arthur Penn dirigi\u00f3 en 1966 una pel\u00edcula capital de la historia del cine, \u201cLa jaur\u00eda humana\u201d, protagonizada por Robert Redford y Marlon Brando, en la que se mostraba la profunda degradaci\u00f3n de la sociedad estadounidense, un fin de ciclo que el m\u00edtico 1968 se encarg\u00f3 de certificar.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-jauria-humana\/liberado-y-feliz\/\" rel=\"attachment wp-att-25203\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25203\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz-279x300.jpg\" alt=\"\" width=\"279\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz-279x300.jpg 279w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz.jpg 405w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/><\/a><\/p>\n<p>Dimite el reci\u00e9n nombrado Ministro de Cultura por sus problemas con el fisco y lo hace, seg\u00fan \u00e9l, para evitar que una jaur\u00eda destroce el proyecto de Pedro S\u00e1nchez. \u00a1Cu\u00e1nto despecho, cu\u00e1nta soberbia, en su despedida! Lo que me provoca una pregunta: \u00bfen qu\u00e9 tipo de realidad paralela viven personas como M\u00e0xim Huerta? \u00bfDe verdad no se le ocurri\u00f3 pensar que un contencioso con Hacienda, zanjado con una sanci\u00f3n de m\u00e1s de 200.000 euros, era un tema relevante? Porque no resulta cre\u00edble que S\u00e1nchez lo nombrara Ministro a sabiendas de sus \u201cproblemillas\u201d con el erario p\u00fablico\u2026<\/p>\n<p>Y luego est\u00e1 lo de Lopetegui, Rubiales y Florentino P\u00e9rez, el impresentable presidente del Real Madrid, otro individuo que se cree con patente de corso, m\u00e1s all\u00e1 del bien y del mal.<\/p>\n<p>Me da igual qu\u00e9 motiv\u00f3 a Rubiales a tomar la fulgurante decisi\u00f3n de devolver a Lopetegui a Espa\u00f1a, compuesto y sin Mundial, pero su llegada a la Federaci\u00f3n ya es s\u00edntoma de que los tiempos est\u00e1n cambiando y su denuncia de la contrataci\u00f3n multimillonaria de un viaje a Rusia para el entorno federativo, realizada por el anterior presidente, buena prueba de que las cosas no van a seguir siendo como antes.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-jauria-humana\/liberado-lopetegui\/\" rel=\"attachment wp-att-25204\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25204\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-Lopetegui-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-Lopetegui-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-Lopetegui-768x433.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-Lopetegui-644x363.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-Lopetegui.jpg 990w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No s\u00e9 si se podr\u00eda haber gestionado de otra manera el contencioso con Lopetegui, pero el pu\u00f1etazo que Rubiales ha dado encima de la mesa, tirando las Copas de Europa de Florentino y haci\u00e9ndolas rodar por el suelo, me parece de una enorme valent\u00eda, por mucho que, para algunos, sea cuesti\u00f3n de ego.<\/p>\n<p>Me gustar\u00eda que lo de Huerta, Lopetegui y Urdangar\u00edn sea una muestra del refuerzo de las instituciones p\u00fablicas frente a los intereses personalistas de esa gente que se considera tocada por la varita de los dioses y al margen del respeto a la res p\u00fablica.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-jauria-humana\/liberado-y-feliz-urdangarin\/\" rel=\"attachment wp-att-25205\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-25205\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz-urdangar\u00edn-300x192.jpg\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz-urdangar\u00edn-300x192.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz-urdangar\u00edn-768x492.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz-urdangar\u00edn-644x412.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Liberado-y-feliz-urdangar\u00edn.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No me cabe duda de que los palcos de los grandes equipos de f\u00fatbol seguir\u00e1n siendo cotos privados de caza mayor y pesca de altura, pero actuaciones como la de Rubiales sirven, al menos, para congelarles el rictus en la cara a sus todopoderosos anfitriones.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment noopener wp-att-24444\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24444 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director Arthur Penn dirigi\u00f3 en 1966 una pel\u00edcula capital de la historia del cine, \u201cLa jaur\u00eda humana\u201d, protagonizada por Robert Redford y Marlon Brando, en la que se mostraba la profunda degradaci\u00f3n de la sociedad estadounidense, un fin de ciclo que el m\u00edtico 1968 se encarg\u00f3 de certificar. Dimite el reci\u00e9n nombrado Ministro de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16483,16480,16476,16479,16482,16481,16477,16478],"class_list":["post-25202","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-dimision-maxim","tag-jose-guirao","tag-lopetegui","tag-maxim-huerta","tag-no-a-lo-personalismos","tag-reforzar-las-instituciones","tag-rubiales","tag-urdangarin"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25202"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25202\/revisions"}],"predecessor-version":[{"id":25207,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25202\/revisions\/25207"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=25202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=25202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=25202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}