{"id":24780,"date":"2018-04-26T07:35:58","date_gmt":"2018-04-26T06:35:58","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24780"},"modified":"2018-04-26T07:35:58","modified_gmt":"2018-04-26T06:35:58","slug":"la-inmortalidad-era-esto","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-inmortalidad-era-esto\/","title":{"rendered":"La inmortalidad era esto"},"content":{"rendered":"<p>Ayer me despert\u00e9 con molestias en la garganta, mareado, con flojera y escalofr\u00edos. Ten\u00eda fiebre y no hab\u00eda pegado ojo, con el viento salvaje golpe\u00e1ndolo todo. Me encontraba hecho un gui\u00f1apo, sin cuerpo para nada.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-inmortalidad-era-esto\/autonomo-caos-creativo\/\" rel=\"attachment wp-att-24781\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24781\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos-creativo-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos-creativo-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos-creativo.jpg 490w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Entonces me acord\u00e9 de que aquello no era posible. No pod\u00eda estar pasando. No pod\u00eda encontrarme mal&#8230; \u00a1por que ya era aut\u00f3nomo! En ese momento se me vinieron a la cabeza las citas y reuniones que ten\u00eda esa ma\u00f1ana, los compromisos, los art\u00edculos por escribir, los mails por contestar y las llamadas por hacer.<\/p>\n<p>Me aclar\u00e9 la garganta, tragu\u00e9 y comprob\u00e9 que, milagrosamente, ya no me dol\u00eda. La cabeza volv\u00eda a estar en su sitio, la temperatura corporal hab\u00eda bajado, los escalofr\u00edos hab\u00edan cesado y me levant\u00e9 de un salto de la cama, fresco como una lechuga.<\/p>\n<p>Hice unas flexiones de brazos, di unos en\u00e9rgicos saltos, hice varias series de sentadillas, dominadas y abdominales y, tras unos concienzudos estiramientos, me duch\u00e9 con agua fr\u00eda. Tom\u00e9 caf\u00e9, mucho caf\u00e9, mientras le\u00eda la prensa, y a la calle, que ten\u00eda que proveer.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-inmortalidad-era-esto\/autonomo-caos\/\" rel=\"attachment wp-att-24782\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24782\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos-300x133.jpg\" alt=\"\" width=\"300\" height=\"133\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos-300x133.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos-768x341.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos-644x286.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-caos.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Despu\u00e9s de toda una vida cobrando una n\u00f3mina, se me hace extra\u00f1o esto de estar a la intemperie, ah\u00ed fuera, como los polis de Hill Street. Ojo: es bonito e ilusionante, no se lo voy a negar, pero duro y complicado.<\/p>\n<p>Eso s\u00ed: lo alucinante de verdad es el apoyo, la ayuda y el acompa\u00f1amiento que he encontrado en las diferentes instancias administrativas con las que me he ido relacionando a lo largo de estas semanas, del SEPE al CADE.<\/p>\n<p>En el servicio de empleo, adem\u00e1s de atenderme con una puntualidad prusiana y con un trato exquisito, me pusieron los pies en la tierra, que llegu\u00e9 cargado de fantas\u00edas y leyendas urbanas sobre el emprendimiento. Ni internet ni conversaciones de barra de bar: quienes saben, son los funcionarios.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-inmortalidad-era-esto\/autonomo\/\" rel=\"attachment wp-att-24783\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24783\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Aut\u00f3nomo.jpg 300w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Y despu\u00e9s, en el Centro de Emprendimiento de la Junta de Andaluc\u00eda, lo mismo: m\u00e1xima colaboraci\u00f3n, precisos -y preciosos- consejos y todas las facilidades para convertirme en aut\u00f3nomo.<\/p>\n<p>No se lo van a creer, pero me gusta esta sensaci\u00f3n. Como si todo estuviera por hacer. Semanas vertiginosas en las que mi vida ha dado un giro de 180 grados, atisbando un futuro repleto de ideas, proyectos y posibilidades. No s\u00e9 c\u00f3mo terminar\u00e1 esta aventura, pero aburrida no es. Gracias a todos los que est\u00e1n ah\u00ed, apoyando. \u00a1Seguimos!<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-24444 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24444 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer me despert\u00e9 con molestias en la garganta, mareado, con flojera y escalofr\u00edos. Ten\u00eda fiebre y no hab\u00eda pegado ojo, con el viento salvaje golpe\u00e1ndolo todo. Me encontraba hecho un gui\u00f1apo, sin cuerpo para nada. Entonces me acord\u00e9 de que aquello no era posible. No pod\u00eda estar pasando. No pod\u00eda encontrarme mal&#8230; \u00a1por que ya [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16223,16224,16222,16225,16221,16226],"class_list":["post-24780","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-autonomos-enfermos","tag-cade","tag-caos-creativo","tag-sepe","tag-ser-autonomo","tag-vivan-los-funcionarios"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24780"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24780\/revisions"}],"predecessor-version":[{"id":24785,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24780\/revisions\/24785"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}