{"id":24743,"date":"2018-04-17T08:06:27","date_gmt":"2018-04-17T07:06:27","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24743"},"modified":"2018-04-17T08:06:27","modified_gmt":"2018-04-17T07:06:27","slug":"nuestro-propio-lorca","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/nuestro-propio-lorca\/","title":{"rendered":"Nuestro propio Lorca"},"content":{"rendered":"<p>Me emocion\u00e9 visitando la exposici\u00f3n \u201cUna habitaci\u00f3n propia\u201d, a trav\u00e9s de la que, \u00a1por fin!, empieza a desembarcar el Legado de Lorca en su Centro. \u00a1Qu\u00e9 cantidad de sensaciones genera! La disfrut\u00e9 hace ya varios d\u00edas, pero he querido esperar a ver c\u00f3mo se aposentaba su recuerdo, antes de escribir sobre ella.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/nuestro-propio-lorca\/una-habitacion-propia-lens\/\" rel=\"attachment wp-att-24744\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24744\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Lens-300x152.jpg\" alt=\"\" width=\"300\" height=\"152\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Lens-300x152.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Lens-768x389.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Lens-644x327.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Lens.jpg 1858w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ustedes saben que he sido muy beligerante con la opacidad existente en torno al Legado y muy cr\u00edtico con que el Centro Lorca estuviera m\u00e1s bien cerrado durante de la Semana Santa, por ejemplo.<\/p>\n<p>Con todos los problemas burocr\u00e1ticos, financieros, legales, judiciales y operativos que envuelven al Legado como concepto; es muy f\u00e1cil olvidarnos de lo realmente importante: el esp\u00edritu de Federico Garc\u00eda Lorca, que est\u00e1 presente e impregna cada cent\u00edmetro cuadrado de \u201cUna habitaci\u00f3n propia\u201d.<\/p>\n<p>Enhorabuena a los responsables de traer esta exposici\u00f3n a Granada, paso previo a la llegada \u00bfdefinitiva? del Legado lorquiano. Una muestra que tiende puentes entre su hogar en la Residencia de Estudiantes de Madrid y su morada definitiva, en nuestra Plaza de la Romanilla.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/nuestro-propio-lorca\/una-habitacion-propia-granada\/\" rel=\"attachment wp-att-24745\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24745\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Granada-268x300.jpg\" alt=\"\" width=\"268\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Granada-268x300.jpg 268w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Granada-768x861.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Granada-644x722.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-Granada.jpg 1161w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" \/><\/a><\/p>\n<p>Ustedes tambi\u00e9n saben que he defendido, a capa y espada, la actividad que el Centro Lorca ha ido desarrollando a lo largo de estos dos complicados a\u00f1os. Ha sido ahora, paseando entre las cartas y los papeles, los libros, los cuadros y el resto de piezas que componen \u201cUna habitaci\u00f3n propia\u201d, cuando he sentido el h\u00e1lito, el esp\u00edritu del poeta, inundando su nueva casa.<\/p>\n<p>No es s\u00edndrome de Stendhal, creo, dado que la exposici\u00f3n no tiene piezas deslumbrantes de belleza cautivadora. A ver, no me malinterpreten: los Dal\u00eds son extraordinarios. Pero el h\u00e1lito vital que se respira en la sala de exposiciones del Centro Lorca viene dado por detalles peque\u00f1os, como los borrones en las cartas que un joven y entusiasta Federico enviaba a sus padres desde una Residencia bloqueada por la nieve, las cachondas im\u00e1genes de los Caballeros de la Orden de Toledo, las cr\u00edticas literarias de Ayala, etc\u00e9tera.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/nuestro-propio-lorca\/una-habitacion-propia-centro-lorca\/\" rel=\"attachment wp-att-24747\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24747\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-centro-lorca-237x300.jpg\" alt=\"\" width=\"237\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-centro-lorca-237x300.jpg 237w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-centro-lorca-768x971.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-centro-lorca-644x814.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Una-habitaci\u00f3n-propia-centro-lorca.jpg 1369w\" sizes=\"auto, (max-width: 237px) 100vw, 237px\" \/><\/a><\/p>\n<p>Sostienen algunos estudiosos que, estando todo el Legado de Lorca digitalizado y accesible a trav\u00e9s de internet, en realidad da igual d\u00f3nde se encuentre almacenado o depositado. Perm\u00edtanme que disienta calurosamente de dicha aseveraci\u00f3n.<\/p>\n<p>A m\u00ed, ll\u00e1menme fetichista, nost\u00e1lgico, rom\u00e1ntico, viejuno o lo que ustedes quieran, pero sigo emocionado por el contenido, f\u00edsico y anal\u00f3gico, de \u201cUna habitaci\u00f3n propia\u201d. Tanto que, ahora, siento a Lorca un poco m\u00e1s m\u00edo.<\/p>\n<p>Jes\u00fas Lens.<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-24444 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24444 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me emocion\u00e9 visitando la exposici\u00f3n \u201cUna habitaci\u00f3n propia\u201d, a trav\u00e9s de la que, \u00a1por fin!, empieza a desembarcar el Legado de Lorca en su Centro. \u00a1Qu\u00e9 cantidad de sensaciones genera! La disfrut\u00e9 hace ya varios d\u00edas, pero he querido esperar a ver c\u00f3mo se aposentaba su recuerdo, antes de escribir sobre ella. Ustedes saben que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16199,8500,16200,14621,16198,16197],"class_list":["post-24743","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-caballeros-de-la-orden-de-toledo","tag-centro-lorca","tag-dali-centro-lorca","tag-legado-lorquiano","tag-nuestro-propio-lorca","tag-una-habitacion-propia"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24743"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24743\/revisions"}],"predecessor-version":[{"id":24749,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24743\/revisions\/24749"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}