{"id":24665,"date":"2018-04-06T14:22:34","date_gmt":"2018-04-06T13:22:34","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24665"},"modified":"2018-04-06T14:22:34","modified_gmt":"2018-04-06T13:22:34","slug":"la-rae-como-panacea","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-rae-como-panacea\/","title":{"rendered":"La RAE como panacea"},"content":{"rendered":"<p>De un tiempo a esta parte, la RAE parece tener la soluci\u00f3n para los problemas que aquejan a la sociedad: unos cambios en las definiciones del diccionario y en los sentidos de determinadas palabras y expresiones y aqu\u00ed paz y despu\u00e9s gloria.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-rae-como-panacea\/rae\/\" rel=\"attachment wp-att-24666\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24666\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/RAE-300x140.jpg\" alt=\"\" width=\"300\" height=\"140\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/RAE-300x140.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/RAE.jpg 580w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Por ejemplo, \u201clujo\u201d, concepto al que ya se le busca una definici\u00f3n positiva. Lo curioso es que, mientras acabar con determinadas expresiones denigratorias para la etnia gitana o para las mujeres cuesta un potos\u00ed, blanquear el lujo va a resultar mucho m\u00e1s sencillo. \u00a1Como la vida misma, oiga!<\/p>\n<p>El gremio de panaderos tambi\u00e9n se suma al carro y pide a la RAE y al Instituto Cervantes que eliminen el refr\u00e1n \u201cpan con pan, comida de tontos\u201d, claramente atentatorio contra sus intereses. Y raz\u00f3n no les falta: cada vez que entro a la panader\u00eda y me debato entre la chapata, el r\u00fastico o el de Alfacar, pienso que no debo hacer moja\u00edllas en el salmorejo, no sea que me vea alguien y me diga tontaco\u2026 sin siquiera haberme dado un chusco de pan.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-rae-como-panacea\/pan-con-pan\/\" rel=\"attachment wp-att-24667\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24667\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Pan-con-pan.png\" alt=\"\" width=\"229\" height=\"220\" \/><\/a><\/p>\n<p>El caso es que, ya puestos, yo tambi\u00e9n voy a iniciar una recogida de firmas en <a href=\"http:\/\/change.org\">change.org<\/a> para exigir a la RAE que elimine todas las connotaciones negativas de la palabra \u201cflaco\u201d. Y espero que gimnasios, m\u00e9dicos y nutricionistas se unan a mi causa.<\/p>\n<p>\u00c9poca de vacas flacas, a perro flaco todo son pulgas, hacer un flaco favor, flaqueza como sin\u00f3nimo de debilidad o falta de vigor, fuerza o resistencia\u2026 \u00bfestamos locos? Como persona gorda en perpetuo r\u00e9gimen de adelgazamiento y cuyo horizonte ideal ser\u00eda ser flaco, exijo la retirada y eliminaci\u00f3n de estos refranes por ser claramente desmotivadores en mi cruzada alimenticia y deportiva, empe\u00f1ado como estoy en bajar de peso.<\/p>\n<p>\u00bfQu\u00e9 sentido tiene empe\u00f1arme en perder kilos si, cuando sea flaco, me van a ver como a una vaca escu\u00e1lida o a un perro pulgoso? \u00bfC\u00f3mo pueden decirle a quien pierde 15 kilos que carece de vigor, fuerza o resistencia? \u00a1Intenta perderlos t\u00fa, refranero bonico, y vas a ver lo que es el tes\u00f3n, el esfuerzo y la voluntad!<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-rae-como-panacea\/vaca-flaca\/\" rel=\"attachment wp-att-24668\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24668\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/04\/Vaca-flaca.jpg\" alt=\"\" width=\"259\" height=\"195\" \/><\/a><\/p>\n<p>Tambi\u00e9n voy a exigir la retirada del Quijote de las librer\u00edas y de los planes de estudio: resulta inadmisible que el viejo loco y perturbado sea un flaco costillar mientras el personaje l\u00facido y sensato es un gordito tragaldabas. \u00bfNo les parece inadmisible?<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-24444 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24444 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De un tiempo a esta parte, la RAE parece tener la soluci\u00f3n para los problemas que aquejan a la sociedad: unos cambios en las definiciones del diccionario y en los sentidos de determinadas palabras y expresiones y aqu\u00ed paz y despu\u00e9s gloria. Por ejemplo, \u201clujo\u201d, concepto al que ya se le busca una definici\u00f3n positiva. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16152,16149,16148,16147,16151,16146,16150],"class_list":["post-24665","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-adelgazar","tag-definir-el-lujo","tag-lujo-rae","tag-pan-con-pan","tag-perro-flaco","tag-rae","tag-vacas-flacas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24665"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24665\/revisions"}],"predecessor-version":[{"id":24671,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24665\/revisions\/24671"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}