{"id":24589,"date":"2018-03-30T12:52:19","date_gmt":"2018-03-30T11:52:19","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24589"},"modified":"2018-03-30T21:19:37","modified_gmt":"2018-03-30T20:19:37","slug":"desde-el-corazon-de-tanger","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/desde-el-corazon-de-tanger\/","title":{"rendered":"Desde el coraz\u00f3n de T\u00e1nger"},"content":{"rendered":"<p>Hoy les escribo sentado en la terraza del Caf\u00e9 Roxy, antes un cine donde Antonio y Saljo vieron los spaghetti western de Sergio Leone. Interrumpo la escritura para ver a la gente pasar o leer algunas p\u00e1ginas de \u201cZoco Chico\u201d, de Mohamed Chukri, comprado hace un par de d\u00edas en la Librairie des Colonnes y muchas de cuyas p\u00e1ginas salvajes fueron escritas en diferentes caf\u00e9s de T\u00e1nger por los que tambi\u00e9n vamos parando: el Gran Caf\u00e9 de Par\u00eds, el Fuentes, el Central, el Tingis&#8230; (<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/camino-de-tanger\/\" target=\"_blank\" rel=\"noopener noreferrer\">AQU\u00cd<\/a> os contaba que me iba y, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/por-que-tanger\/\" target=\"_blank\" rel=\"noopener noreferrer\">AQU\u00cd<\/a>, el porqu\u00e9)<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/desde-el-corazon-de-tanger\/cafe-tingis-tanger\/\" rel=\"attachment wp-att-24592\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24592\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Tingis-T\u00e1nger-300x219.jpg\" alt=\"\" width=\"300\" height=\"219\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Tingis-T\u00e1nger-300x219.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Tingis-T\u00e1nger-768x560.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Tingis-T\u00e1nger-644x470.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Tingis-T\u00e1nger.jpg 1975w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Situada en el Boulevard Pasteur, la Librairie des Colonnes es una gozada para los amantes de los libros, presidida por dos grandes fotograf\u00edas, una del propio Chukri y otra de Federico Garc\u00eda Lorca, lo que me recuerda la conversaci\u00f3n surgida al calor del cusc\u00fas y los tagine de kefta, escuchando a un grupo interpretar \u201cLa Tarara\u201d. Conformamos un grupo variopinto comandado por Antonio Lozano y Salvador Bellver, tangerinos de pro que nos conducen por los rincones \u00edntimos de una T\u00e1nger memor\u00edstica y emocional, pero sin nostalgias ni tristezas. Y vienen el escritor Carlos Zan\u00f3n y Olga Cuadrado, de la Fundaci\u00f3n Tres Culturas, en cuya compa\u00f1\u00eda surgi\u00f3 la idea de este viaje, hace unos meses, en mitad de la A92, entre Sevilla y Granada.<\/p>\n<p>Vienen, tambi\u00e9n, m\u00e1s personas del entorno de Antonio: su mujer, Clari, y sus hijos, Carlos y Javier. Su primo Jos\u00e9 Luis e Ingrid. Las familias de Olga, con Merchi, Pepe y el gran Mart\u00edn; y Zan\u00f3n y Mari Luz, y Rosa, Pepe y su hija Olga. Un grupo extraordinario.<\/p>\n<p>Paseamos por la Medina y la Kasbah, al amanecer, cuando una T\u00e1nger perezosa empieza a despertar. Caminamos guiados por Al\u00ed, amigo \u00edntimo de Antonio, al que no le importa abrir algo m\u00e1s tarde su tienda, mientras nos cuenta historias de esta ciudad milenaria.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/desde-el-corazon-de-tanger\/habitacion-matisse-tanger\/\" rel=\"attachment wp-att-24594\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24594\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Habitaci\u00f3n-Matisse-T\u00e1nger-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Habitaci\u00f3n-Matisse-T\u00e1nger-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Habitaci\u00f3n-Matisse-T\u00e1nger-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Habitaci\u00f3n-Matisse-T\u00e1nger-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Habitaci\u00f3n-Matisse-T\u00e1nger.jpg 2016w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Entramos en el Hotel Continental para disfrutar de su ambiente internacional y en el que recalaron luminarias como Bogart, cuya maltrecha foto nos saluda desde un oscuro sal\u00f3n. Fotos, tambi\u00e9n, del equipo que film\u00f3 \u201cEl cielo protector\u201d, la obra maestra de Bertolucci. M\u00e1s tarde pasaremos por el Caf\u00e9 Mamounia donde se filmaron algunas de sus secuencias. Tambi\u00e9n haremos parada en el Ville de France, que mantiene intacta la habitaci\u00f3n 35 donde se aloj\u00f3 Matisse. Resulta toda una experiencia, ver la reproducci\u00f3n del cuadro que pint\u00f3 justo all\u00ed, reproduciendo la vista que contemplaba desde su ventana, y comparar c\u00f3mo ha cambiando el paisaje, atisbando la realidad actual.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/desde-el-corazon-de-tanger\/cafe-mamounia-tanger\/\" rel=\"attachment wp-att-24593\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24593\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Mamounia-T\u00e1nger-300x257.jpg\" alt=\"\" width=\"300\" height=\"257\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Mamounia-T\u00e1nger-300x257.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Mamounia-T\u00e1nger-768x657.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Mamounia-T\u00e1nger-644x551.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Caf\u00e9-Mamounia-T\u00e1nger.jpg 1698w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Visitamos los barrios en los que transcurri\u00f3 la infancia y la juventud de nuestros cicerones, recordando, imaginando, so\u00f1ando. Y hablamos de literatura, cine, pintura, pol\u00edtica, comidas, m\u00fasica&#8230; y de futuros viajes compartidos, por supuesto.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-24444 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24444 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy les escribo sentado en la terraza del Caf\u00e9 Roxy, antes un cine donde Antonio y Saljo vieron los spaghetti western de Sergio Leone. Interrumpo la escritura para ver a la gente pasar o leer algunas p\u00e1ginas de \u201cZoco Chico\u201d, de Mohamed Chukri, comprado hace un par de d\u00edas en la Librairie des Colonnes y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24,16],"tags":[16113,16112,16114,16111,16115],"class_list":["post-24589","post","type-post","status-publish","format-standard","hentry","category-viajes","category-viajes-africa","tag-biajes-jesus-lens","tag-cafe-mamounia-tanger","tag-jesus-lebs-en-tanger","tag-matisse-en-tanger","tag-viajar-tanger"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24589"}],"version-history":[{"count":6,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24589\/revisions"}],"predecessor-version":[{"id":24619,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24589\/revisions\/24619"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}