{"id":24565,"date":"2018-03-24T07:19:54","date_gmt":"2018-03-24T06:19:54","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24565"},"modified":"2018-03-24T07:19:54","modified_gmt":"2018-03-24T06:19:54","slug":"consenso-ultramarino","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/consenso-ultramarino\/","title":{"rendered":"Consenso ultramarino"},"content":{"rendered":"<p>Ustedes saben que en esta columna me gusta tocar temas de actualidad que, en la medida de lo posible, est\u00e9n relacionados con Granada. Ayer por la tarde, andaba flojo de inspiraci\u00f3n, que pas\u00e9 el jueves de jarana con los Gastrocafres, d\u00e1ndonos un homenaje en la imprescindible Bodega Teba, y estaba espeso tras una larga ma\u00f1ana de trabajo y reuniones.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/consenso-ultramarino\/665035ea-6e79-46ef-9565-d564c3fecab9\/\" rel=\"attachment wp-att-24566\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24566\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/665035ea-6e79-46ef-9565-d564c3fecab9-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/665035ea-6e79-46ef-9565-d564c3fecab9-300x168.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/665035ea-6e79-46ef-9565-d564c3fecab9-768x431.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/665035ea-6e79-46ef-9565-d564c3fecab9-644x361.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/665035ea-6e79-46ef-9565-d564c3fecab9.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Por cierto\u2026 \u00a1qu\u00e9 quesos, qu\u00e9 carnes retintas a la brasa y qu\u00e9 alcachofas con langostinos pudimos degustar en Teba! Pero vuelvo al tema, que me distraigo con una mosca.<\/p>\n<p>Aunque estoy suscrito al nuevo servicio de notificaciones de IDEAL y me constaba que no hab\u00eda pasado nada especialmente llamativo en nuestro entorno, entr\u00e9 en la web para ver qu\u00e9 hab\u00eda de nuevo. Y lo que hab\u00eda, ustedes ya lo saben: el Proc\u00e9s y una iniciativa compartida por el PSOE, el PP y Cs de Granada\u2026 sobre Venezuela.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/consenso-ultramarino\/ayuntamiento-granada-venezuela\/\" rel=\"attachment wp-att-24567\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24567\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Ayuntamiento-Granada-Venezuela-300x185.jpg\" alt=\"\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Ayuntamiento-Granada-Venezuela-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Ayuntamiento-Granada-Venezuela.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Que no digo yo que lo de Venezuela no sea importante, pero manda huevos que nuestros pr\u00f3ceres solo sean capaces de ponerse de acuerdo\u2026 en pedir libertad y democracia para el pa\u00eds sudamericano. Con la abstenci\u00f3n de Vamos Granada y el voto en contra de IU. Que tambi\u00e9n tiene lo suyo.<\/p>\n<p>Espero que, para el pleno del mes que viene, alg\u00fan partido proponga una moci\u00f3n para favorecer el desarrollo econ\u00f3mico del Chad, la lucha contra la ablaci\u00f3n en Mauritania, la mejora de las libertades en Libia o algo sobre las barriadas marginales de El Salvador, por ejemplo. Son pa\u00edses que, \u00a1oh sorpresa! tambi\u00e9n existen. Para su desgracia -o no- est\u00e1n fuera del foco medi\u00e1tico y nadie se acuerda de ellos, excepto cuando entra en erupci\u00f3n un volc\u00e1n o fen\u00f3menos por el estilo.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/consenso-ultramarino\/ayuntamiento-granada-chad\/\" rel=\"attachment wp-att-24568\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24568\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Ayuntamiento-Granada-Chad-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Ayuntamiento-Granada-Chad-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Ayuntamiento-Granada-Chad.jpg 470w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Tambi\u00e9n ser\u00eda importante que los partidos pol\u00edticos locales traten de encontrar espacios de consenso m\u00e1s cercanos que Caracas, que nos pilla a 7.000 kil\u00f3metros de distancia y sobre cuya situaci\u00f3n pol\u00edtica, Fernando Egea, Paco Cuenca y Manuel Olivares van a tener poco ascendiente, me temo.<\/p>\n<p>Est\u00e1 muy bien la vocaci\u00f3n internacionalista de nuestro Ayuntamiento y la preocupaci\u00f3n de nuestros ediles por los asuntos de allende los mares y los paisajes ultramarinos. Demuestra sensibilidad, solidaridad y amplitud de miras.<\/p>\n<p>Sin embargo, echo de menos esta voluntad de consenso y este buenrollismo institucional en temas m\u00e1s cercanos, igualmente sensibles y necesarios. Ahora ya s\u00ed. Les dejo tranquilos, que seguro que est\u00e1n deseando leer sobre el Proc\u00e9s\u2026<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-24444 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24444 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ustedes saben que en esta columna me gusta tocar temas de actualidad que, en la medida de lo posible, est\u00e9n relacionados con Granada. Ayer por la tarde, andaba flojo de inspiraci\u00f3n, que pas\u00e9 el jueves de jarana con los Gastrocafres, d\u00e1ndonos un homenaje en la imprescindible Bodega Teba, y estaba espeso tras una larga ma\u00f1ana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16097,16100,16101,16099,16098,15070],"class_list":["post-24565","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-ayuntamiento-granada-venezuela","tag-bodega-teba","tag-bodega-tema-granada","tag-chad","tag-el-chad-tambien-existe","tag-proces"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24565"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24565\/revisions"}],"predecessor-version":[{"id":24570,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24565\/revisions\/24570"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}