{"id":24545,"date":"2018-03-22T09:32:00","date_gmt":"2018-03-22T08:32:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24545"},"modified":"2018-03-22T09:32:00","modified_gmt":"2018-03-22T08:32:00","slug":"privacidad-volatilizada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/privacidad-volatilizada\/","title":{"rendered":"Privacidad volatilizada"},"content":{"rendered":"<p>\u201cSi es privado, no lo pongas on line\u201d. Perd\u00f3nenme que vuelva a mis batallitas docentes a cuenta de la Comunicaci\u00f3n (lean esta otra <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/profesores-felizmente-raros\/\" target=\"_blank\" rel=\"noopener noreferrer\">AQU\u00cd<\/a>, igualmente en IDEAL), pero es una de las discusiones que suelo tener con los estudiantes: los l\u00edmites de la privacidad. Sobre todo, porque siempre he defendido que, en Internet, no existen.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/privacidad-volatilizada\/publico-privado-2\/\" rel=\"attachment wp-att-24546\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24546\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/P\u00fablico-privado-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/P\u00fablico-privado-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/P\u00fablico-privado-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/P\u00fablico-privado-768x768.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/P\u00fablico-privado-644x644.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/P\u00fablico-privado.jpg 860w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Da lo mismo la red social que utilices, los filtros y restricciones que pongas, los grupos privados de los que formes parte\u2026 todo lo que subas a la Red, sea a la Nube, sea al nublo; es susceptible de ser de dominio p\u00fablico y, por tanto, difundido, compartido, usado, pirateado o robado.<\/p>\n<p>Si no quieres que la gente lo vea, no lo compartas en la Red. Y, ni mucho menos, en las redes. Sociales o sin socializar. No lo compartas en grupos privados, ni en chats personales, ni en ning\u00fan formato on line.<\/p>\n<p>Por desgracia, las filtraciones de Facebook y su uso pol\u00edtico, me dan la raz\u00f3n. Parad\u00f3jicamente, he necesitado dos d\u00edas y ver la informaci\u00f3n impresa en las portadas de los peri\u00f3dicos tradicionales para ser consciente de la magnitud de la tragedia: cuando le\u00ed la noticia en internet, no le prest\u00e9 excesiva atenci\u00f3n, despachando el tema con displicencia, como si de otra fuga de datos cualquiera se tratara.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/privacidad-volatilizada\/facebook-leak\/\" rel=\"attachment wp-att-24547\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24547\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Facebook-Leak-300x147.jpg\" alt=\"\" width=\"300\" height=\"147\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Facebook-Leak-300x147.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Facebook-Leak.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pero no. Lo ocurrido con los datos de Facebook y Cambrigde Analytica es tan sumamente grave que me huele a manipulaci\u00f3n electoral y a golpe de estado. Habr\u00e1 que estar muy atentos a todo lo que vaya surgiendo de las investigaciones iniciadas, pero me temo que estamos ante una grav\u00edsima amenaza hacia los sistemas democr\u00e1ticos de todo el mundo.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/privacidad-volatilizada\/facebook-trump\/\" rel=\"attachment wp-att-24548\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24548\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Facebook-Trump-300x175.jpg\" alt=\"\" width=\"300\" height=\"175\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Facebook-Trump-300x175.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Facebook-Trump-644x375.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Facebook-Trump.jpg 760w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>No tengo pensado irme de Facebook, pero s\u00ed que me voy a tomar m\u00e1s en serio lo de publicar enlaces con noticias contradictorias para tratar de despistar a los robots perfiladores y al algoritmo. Jugar con ir\u00f3nicos mensajes de apoyo a Cifuentes por su manera de completar el curr\u00edculum y loas a Luis Salvador por su coherencia pol\u00edtica. Hablar\u00e9 m\u00e1s de barcos y menos de trenes. Y mucho del tiempo, celebrities y f\u00fatbol. Para todo lo dem\u00e1s\u2026 \u00a1compren el peri\u00f3dico!<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-24444 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24444 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSi es privado, no lo pongas on line\u201d. Perd\u00f3nenme que vuelva a mis batallitas docentes a cuenta de la Comunicaci\u00f3n (lean esta otra AQU\u00cd, igualmente en IDEAL), pero es una de las discusiones que suelo tener con los estudiantes: los l\u00edmites de la privacidad. Sobre todo, porque siempre he defendido que, en Internet, no existen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[16086,16084,16085,14254],"class_list":["post-24545","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-enganar-al-algoritmo","tag-facebook-leaks","tag-filtraciones-facebook","tag-jesus-lens-comunicacion"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24545"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24545\/revisions"}],"predecessor-version":[{"id":24550,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24545\/revisions\/24550"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}