{"id":24505,"date":"2018-03-15T20:02:16","date_gmt":"2018-03-15T19:02:16","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24505"},"modified":"2018-03-17T20:16:17","modified_gmt":"2018-03-17T19:16:17","slug":"el-sacromonte-como-falsificacion","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-sacromonte-como-falsificacion\/","title":{"rendered":"El Sacromonte como falsificaci\u00f3n"},"content":{"rendered":"<p>No hay ruta m\u00e1s bonita en Granada, para correr, que salir muy temprano desde el Puente Verde y dejar la vera del r\u00edo Genil para subir al Cerro del Sol por las antiguas minas romanas de oro, asom\u00e1ndonos a las blancas cumbres de Sierra Nevada. La vuelta a la ciudad la haremos por el lado contrario, atravesando Valpara\u00edso con el r\u00edo Darro a nuestros pies. Recorreremos la Acequia Real de la Alhambra mientras, al otro lado del valle, se despereza la Abad\u00eda del Sacromonte y, al fondo, el Albayc\u00edn nos da la bienvenida.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-sacromonte-como-falsificacion\/abadia-del-sacromonte\/\" rel=\"attachment wp-att-24506\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24506\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Abad\u00eda-del-Sacromonte-300x196.jpg\" alt=\"\" width=\"300\" height=\"196\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Abad\u00eda-del-Sacromonte-300x196.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Abad\u00eda-del-Sacromonte-768x501.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Abad\u00eda-del-Sacromonte-644x420.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Abad\u00eda-del-Sacromonte.jpg 2041w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Un recorrido hermoso, hist\u00f3rico, m\u00edstico y repleto de vistas espectaculares que, adem\u00e1s, reserva una intrigante sorpresa a los amantes de los misterios y los enigmas. Porque, \u00bfy si les digo que Valpara\u00edso es el escenario de una de las m\u00e1s grandes falsificaciones de la historia de Espa\u00f1a? <a href=\"http:\/\/www.ideal.es\/on-extra\/evasion\/nueva-revista\/sacromonte-falsificacion-20180315202945-nt.html\" target=\"_blank\" rel=\"noopener noreferrer\">AQU\u00cd<\/a>, en IDEAL, el texto completo.<\/p>\n<p>Es posible que ustedes hayan escuchado hablar de los Libros Pl\u00fambeos del Sacromonte. Que suenan a algo grande y monumental. Y lo son, pero no en el sentido f\u00edsico de la expresi\u00f3n. Se trata de 21 libros conformados por 223 planchas circulares de plomo, de unos 10 cent\u00edmetros nada m\u00e1s, en los que hay grabados peque\u00f1os dibujos indescifrables, textos en lat\u00edn y tambi\u00e9n en un \u00e1rabe extra\u00f1o. Tanto que se dieron a conocer como textos salom\u00f3nicos que supuestamente contendr\u00edan un quinto evangelio, necesariamente ap\u00f3crifo, y que la mism\u00edsima Virgen Mar\u00eda habr\u00eda revelado, en \u00e1rabe, para que fuera divulgado en Espa\u00f1a.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-sacromonte-como-falsificacion\/libros-plumbeos-del-sacromonte\/\" rel=\"attachment wp-att-24507\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24507\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Libros-Pl\u00fambeos-del-Sacromonte-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Libros-Pl\u00fambeos-del-Sacromonte-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Libros-Pl\u00fambeos-del-Sacromonte.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>El descubrimiento de los Libros Pl\u00fambeos data de finales del siglo XVI y se encontraron junto a unos restos humanos, supuestamente de San Cecilio, un \u00e1rabe cristiano que acompa\u00f1\u00f3 al ap\u00f3stol Santiago en sus periplos por el mundo hasta acabar en Granada, ciudad de la que es patr\u00f3n y de cuya di\u00f3cesis fue el primer obispo.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/9RZlOSWlTzg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Mi primer acercamiento literario al enigma de los libros de plomo del Sacromonte lleg\u00f3 de la mano de un libro excepcional que, en Granada, es leyenda: \u201cEl segundo hijo del mercader de sedas\u201d, de Felipe Romero, publicado en 1995 y convertido en uno de los grandes long-sellers del mercado editorial local. Un libro prodigioso que es a la vez una historia de amor y una trama sobre las complejas relaciones entre los cristianos y los moriscos, cada vez m\u00e1s apartados, recluidos y reprimidos en una Espa\u00f1a demasiado intolerante.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-sacromonte-como-falsificacion\/el-segundo-hijo-del-mercader-de-sedas\/\" rel=\"attachment wp-att-24508\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24508\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/El-segundo-hijo-del-mercader-de-sedas-202x300.jpg\" alt=\"\" width=\"202\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/El-segundo-hijo-del-mercader-de-sedas-202x300.jpg 202w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/El-segundo-hijo-del-mercader-de-sedas.jpg 336w\" sizes=\"auto, (max-width: 202px) 100vw, 202px\" \/><\/a><\/p>\n<p>Pero la novela que convierte al misterio de los Libros Pl\u00fambeos en materia para esta secci\u00f3n dedicada al g\u00e9nero negro y criminal viene firmada por otro autor granadino, Fernando de Villena, y su vibrante y brillante \u201cValpara\u00edso. El secreto del Sacromonte\u201d, publicada en 2015 por la editorial Port Royal.<\/p>\n<p>Les recomiendo que se hagan con ella a la mayor brevedad, pero que no la empiecen hasta un viernes que anticipe un fin de semana tranquilo y relajado. Porque, una vez que empiecen a leer la primera parte del libro, titulada \u201cEl archivo de las cuatro llaves\u201d y que transcurre en 1969, les costar\u00e1 dejar el libro.<\/p>\n<p>\u00bfSe acuerdan del arranque de la pel\u00edcula \u201cEl nombre de la rosa\u201d, cuando Adso de Melk confesaba su desasosiego al escuchar c\u00f3mo se cerraban a sus espaldas las puertas de la Abad\u00eda benedictina a la que acababa de llegar junto a su maestro, Guillermo de Baskerville? Pues una sensaci\u00f3n parecida atenazar\u00e1 al protagonista de \u201cValpara\u00edso. El secreto del Sacromonte\u201d cuando entre en la Abad\u00eda del Sacromonte que, por entonces, era centro escolar y admit\u00eda a alumnos internos, y descubra esas Estrellas de David esculpidas en la piedra.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-sacromonte-como-falsificacion\/valparaiso-fernando-de-villena\/\" rel=\"attachment wp-att-24509\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24509\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Valpara\u00edso-Fernando-de-Villena-213x300.jpg\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Valpara\u00edso-Fernando-de-Villena-213x300.jpg 213w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/03\/Valpara\u00edso-Fernando-de-Villena.jpg 381w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/a><\/p>\n<p>No les voy a contar nada sobre una trama que, con varios pliegues en el tiempo, recorre el origen m\u00e1s lejano de la Abad\u00eda del Sacromonte y habla del incre\u00edble secreto que alberga en su interior. Un secreto que, conectando con los Libros Pl\u00fambeos, retrocede a la \u00e9poca de los godos y los romanos, hasta convertir a nuestra Abad\u00eda en uno de los grandes enigmas de la historia.<\/p>\n<p>Le pregunto a Bego\u00f1a Gonz\u00e1lez, experta en falsedad documental y grafolog\u00eda de <a href=\"http:\/\/peibegrafia.com\" target=\"_blank\" rel=\"noopener noreferrer\">Pericia Caligr\u00e1fica PB<\/a>, por lo que suponen los Libros Pl\u00fambeos como gran falsificaci\u00f3n hist\u00f3rica. Y esto es lo que nos cuenta:<\/p>\n<p>\u201cToda manipulaci\u00f3n tiene un objetivo\u2026 Nunca olvidemos\u00a0que en toda falsificaci\u00f3n existe autenticidad. Lo interesante seria justificar cient\u00edficamente por expertos de diferentes \u00e1reas el enigma de los Libros Pl\u00fambeos, remont\u00e1ndonos desde su hallazgo en el siglo XVI, y desde 1631 guardados durante 400 a\u00f1os en los \u00a0archivos secretos del Vaticano, devueltos a su lugar de origen en el a\u00f1o 2000.<\/p>\n<p>\u00bfCu\u00e1l es el misterio?\u00a0\u00bfEstudiar las placas de plomo? \u00bfSon los aut\u00e9nticos? \u00bfCopias? \u00bfExisten\u00a0originales? \u00bfFueron destruidos?<\/p>\n<p>&nbsp;<\/p>\n<p>El enigma de los libros pl\u00fambeos es un tema que me apasiona, sin perjuicio de su dif\u00edcil acceso. No obstante, muchas de las preguntas que surgen en relaci\u00f3n a estos libros \u00a0sobre placas de plomo, su falsificaci\u00f3n, su transposici\u00f3n\u2026 se contestar\u00edan con\u00a0un profundo estudio con los medios actuales.\u00a0Nos referimos al an\u00e1lisis multiespectral , t\u00e9cnicas que van desde la fotograf\u00eda del campo no visible, por medio de Reflectograf\u00eda Ultravioleta o\u00a0Infrarroja, e incluso t\u00e9cnicas de fluorescencia.\u00a0Asimismo, son una excelente estrategia para extraer informaci\u00f3n de documentos compuestos por m\u00faltiples tintas o con deterioros importantes tales como pigmentos desvanecidas por disoluci\u00f3n, envejecimiento o eliminadas por procesos qu\u00edmicos. Todo ello, para que el misterio quede desvelado y entender los verdaderos motivos que conllev\u00f3 a una de las mayores falsificaciones de la humanidad\u201d.<\/p>\n<p>Como pueden ustedes comprobar, el misterio y el enigma contin\u00faan vivos y palpitantes. (M\u00e1s <a href=\"http:\/\/granadaimedia.com\/informe-caligrafico-grafiti-pintada-albaicin\/\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a> sobre PB Pericia Caligr\u00e1fica)<\/p>\n<p>Jes\u00fas Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hay ruta m\u00e1s bonita en Granada, para correr, que salir muy temprano desde el Puente Verde y dejar la vera del r\u00edo Genil para subir al Cerro del Sol por las antiguas minas romanas de oro, asom\u00e1ndonos a las blancas cumbres de Sierra Nevada. La vuelta a la ciudad la haremos por el lado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11774],"tags":[16062,16063,11776,4267,16066,16065,16064,16067,16061],"class_list":["post-24505","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-rincon-oscuro","tag-abadia-sacromonte","tag-begona-gonzalez","tag-el-rincon-oscuro","tag-fernando-de-villena","tag-libros-plomo-sacramente","tag-libros-plumbeos","tag-pb-pericia-caligrafica","tag-valparaiso","tag-valparaiso-el-secreto-del-sacromonte"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24505"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24505\/revisions"}],"predecessor-version":[{"id":24513,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24505\/revisions\/24513"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}