{"id":24111,"date":"2018-01-19T07:00:12","date_gmt":"2018-01-19T06:00:12","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=24111"},"modified":"2018-01-18T13:49:01","modified_gmt":"2018-01-18T12:49:01","slug":"lorca-miro-una-performance","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/lorca-miro-una-performance\/","title":{"rendered":"Lorca &#038; Mir\u00f3. Una performance"},"content":{"rendered":"<p>En realidad, es una performance. Lo del Centro Lorca, los cuatro millones de euros prestados \u2013e impagados- por La Caixa a la Fundaci\u00f3n lorquiana con el aval del Legado y la oscura e invisible transparencia que defienden a grito pelado el alcalde de Granada y la Consejer\u00eda de Cultura de la Junta de Andaluc\u00eda; es una performance que se va a prolongar durante diez a\u00f1os.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=24113\" rel=\"attachment wp-att-24113\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24113\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/01\/La-Caixa.gif\" alt=\"\" width=\"195\" height=\"146\" \/><\/a><\/p>\n<p>Diez a\u00f1os de performance ininterrumpida que situar\u00e1 a Granada en un puesto de vanguardia art\u00edstica y que contribuir\u00e1 a reforzar la candidatura de nuestra ciudad a la Capitalidad Cultural del 2031.<\/p>\n<p>&nbsp;<\/p>\n<p>Una performance radical y surrealista que juega con el ox\u00edmoron como piedra angular del proyecto, combinando conceptos contradictorios como cl\u00e1usulas secretas y transparencia o millones distra\u00eddos y cuentas claras. Una performance conceptual que invita al espectador a reflexionar sobre la dial\u00e9ctica claridad-turbiedad, aunque haya almas insensibles que conjuguen otras expresiones como comulgar con ruedas de molino, aceptar pulpo como animal de compa\u00f1\u00eda, tomadura de pelo y otras de tono m\u00e1s elevado, irreproducibles en esta columna.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=24112\" rel=\"attachment wp-att-24112\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-24112\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/01\/Lorca-Mir\u00f3-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/01\/Lorca-Mir\u00f3-300x170.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/01\/Lorca-Mir\u00f3-768x434.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/01\/Lorca-Mir\u00f3-644x364.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/01\/Lorca-Mir\u00f3.jpg 1050w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Uno de los momentos m\u00e1s vibrantes de la performance llegar\u00e1 cuando, sobre el n\u00edveo blanco del Centro Lorca aparezca representada una preciosa estrella azul acompa\u00f1ada de dos puntos, amarillo y rojo. Las mismas almas insensibles antes nombradas dir\u00e1n que es el logo de una entidad financiera, pero los esp\u00edritus m\u00e1s elevados responder\u00e1n que no. Que se trata de una obra pict\u00f3rica de Mir\u00f3, artista al que Federico Garc\u00eda Lorca admiraba con pasi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>La presencia de la estrella azul en todo lo referente al Centro Lorca, durante los pr\u00f3ximos diez a\u00f1os y a cambio de 400.000 euros por ejercicio, podr\u00edamos enmarcarla en el proyecto \u201cSon\u00e1mbulo\u201d, por ejemplo. En palabras de su creador, Theodore Usher, \u201ces una alegor\u00eda sobre la alegr\u00eda y el misterio de la vida\u201d. Un proyecto basado en un cortometraje animado, reinterpretaci\u00f3n audiovisual del aclamado poema lorquiano \u201cRomance Son\u00e1mbulo\u201d que \u201cjuega con el lenguaje audiovisual de la misma manera en que Lorca con las palabras, y Mir\u00f3 con las formas y colores, d\u00e1ndoles textura, personalidad y un significado distinto en cada cuadro\u201d.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/111910724\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfLe parecer\u00e1 al Consejero de Cultura de la Junta de Andaluc\u00eda que, con esta explicaci\u00f3n del desprop\u00f3sito lorquiano, hay suficiente altura de miras? Aunque, para algunos, lo que parece haber es hartura de miras\u2026 y es que hambre que espera hartura, no es hambre ninguna.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-24105 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-24105 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/01\/1-Twitter-Lens-1.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En realidad, es una performance. Lo del Centro Lorca, los cuatro millones de euros prestados \u2013e impagados- por La Caixa a la Fundaci\u00f3n lorquiana con el aval del Legado y la oscura e invisible transparencia que defienden a grito pelado el alcalde de Granada y la Consejer\u00eda de Cultura de la Junta de Andaluc\u00eda; es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15751,12056,13944,15750,15749,15748,15747],"class_list":["post-24111","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-la-caixa-centro-lorca","tag-legado-de-lorca","tag-oximoron","tag-romance-sonambulo-lorca","tag-sonambulo-lorca","tag-theodore-usher","tag-turbiedad-claridad"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=24111"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24111\/revisions"}],"predecessor-version":[{"id":24114,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/24111\/revisions\/24114"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=24111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=24111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=24111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}