{"id":23894,"date":"2017-12-22T08:56:33","date_gmt":"2017-12-22T07:56:33","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23894"},"modified":"2017-12-22T09:40:29","modified_gmt":"2017-12-22T08:40:29","slug":"urnas-bombos-y-balones","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/urnas-bombos-y-balones\/","title":{"rendered":"Urnas, bombos y balones"},"content":{"rendered":"<p>Ya est\u00e1n aqu\u00ed. Ya han llegado esos d\u00edas tan anunciados, previos a esos otros d\u00edas, tan se\u00f1alados. D\u00edas que tan bien reflejan c\u00f3mo somos. D\u00edas simbolizados, por las urnas, por ejemplo.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/urnas-bombos-y-balones\/nacionalismo-dinosaurio\/\" rel=\"attachment wp-att-23895\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23895\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Nacionalismo-dinosaurio-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Nacionalismo-dinosaurio-300x158.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Nacionalismo-dinosaurio-768x403.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Nacionalismo-dinosaurio-644x338.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Nacionalismo-dinosaurio.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A estas horas ya se sabr\u00e1 el resultado de las elecciones catalanas. Lo que no s\u00e9 si sabremos es si servir\u00e1n para algo. Unas elecciones convocadas para tratar de solucionar uno de los grandes problemas que nos aquejan\u2026 desde el siglo XIX: el nacionalismo. Ese nacionalismo que, cuando despertamos, siempre sigue ah\u00ed. El dinosaurio incombustible, aun en los tiempos de internet, la Uni\u00f3n Europea sin fronteras y la moneda \u00fanica.<\/p>\n<p>&nbsp;<\/p>\n<p>Hoy es el d\u00eda de analizar los resultados de las urnas, pero con el o\u00eddo puesto en el bombo. Porque hoy, todos somos ojalateros, invocando a la Diosa Fortuna a trav\u00e9s de un deseo, compartido y repartido por toda Espa\u00f1a, m\u00e1s all\u00e1 de ideolog\u00edas, credos y nacionalismos: Ojal\u00e1 toque aqu\u00ed. Ojal\u00e1 me toque el Gordo. Ojal\u00e1 me toque algo.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/urnas-bombos-y-balones\/gordo-loteria-navidad\/\" rel=\"attachment wp-att-23896\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23896\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Gordo-Loter\u00eda-Navidad-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Gordo-Loter\u00eda-Navidad-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Gordo-Loter\u00eda-Navidad.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Dentro de unas horas, la inmensa mayor\u00eda de nosotros apelaremos a ese otro milagro, el de la salud, portadores de un par de pedreas en el mejor de los casos. Pero no pasa nada. Estamos de enhorabuena y, para mitigar la decepci\u00f3n lotera, siempre nos quedar\u00e1 el bal\u00f3n. El Cl\u00e1sico, con may\u00fasculas. El \u00faltimo partido del siglo del a\u00f1o.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/urnas-bombos-y-balones\/clasico-madrid-barca\/\" rel=\"attachment wp-att-23897\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23897\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Cl\u00e1sico-madrid-Bar\u00e7a-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Cl\u00e1sico-madrid-Bar\u00e7a-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Cl\u00e1sico-madrid-Bar\u00e7a-768x433.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Cl\u00e1sico-madrid-Bar\u00e7a-644x363.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Cl\u00e1sico-madrid-Bar\u00e7a.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Que el problema no es el f\u00fatbol. Ni la loter\u00eda. Y unas urnas y unas elecciones siempre deber\u00edan ser bienvenidas. El problema es que, en tres d\u00edas, quedamos perfectamente retratados en las grandes cuestiones que nos preocupan y que consumen la mayor parte de nuestro tiempo: nacionalismo, loter\u00eda y f\u00fatbol.<\/p>\n<p>&nbsp;<\/p>\n<p>Hagan la prueba. Traten de contabilizar el tiempo que les est\u00e1n dedicando a esos tres temas ustedes mismos. Cuenten el minutaje de los informativos de radio y televisi\u00f3n o las p\u00e1ginas que les dedican los peri\u00f3dicos.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/urnas-bombos-y-balones\/forges-fisica\/\" rel=\"attachment wp-att-23901\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23901\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Forges-f\u00edsica-246x300.jpg\" alt=\"\" width=\"246\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Forges-f\u00edsica-246x300.jpg 246w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Forges-f\u00edsica-768x937.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Forges-f\u00edsica-644x786.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Forges-f\u00edsica.jpg 787w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" \/><\/a><\/p>\n<p>Vale. Son d\u00edas especiales. Ha sido pura casualidad. \u00bfSeguro? \u00bfDe verdad creen ustedes que, en las pr\u00f3ximas semanas, nos preocuparemos de los temas que realmente deber\u00edan importarnos? En fin. Les dejo. Que creo que ha salido el Gordo\u2026<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-23891 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23891 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1n aqu\u00ed. Ya han llegado esos d\u00edas tan anunciados, previos a esos otros d\u00edas, tan se\u00f1alados. D\u00edas que tan bien reflejan c\u00f3mo somos. D\u00edas simbolizados, por las urnas, por ejemplo. A estas horas ya se sabr\u00e1 el resultado de las elecciones catalanas. Lo que no s\u00e9 si sabremos es si servir\u00e1n para algo. Unas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15602,15601,15600,15603],"class_list":["post-23894","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-clasico-de-futbol","tag-lo-importante-es-tener-salud","tag-loteria-de-navidad","tag-nacionalismo-dinosaurios"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23894"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23894\/revisions"}],"predecessor-version":[{"id":23902,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23894\/revisions\/23902"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}