{"id":23823,"date":"2017-12-12T09:52:05","date_gmt":"2017-12-12T08:52:05","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23823"},"modified":"2017-12-12T09:52:05","modified_gmt":"2017-12-12T08:52:05","slug":"republica-andaluza-independiente","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/republica-andaluza-independiente\/","title":{"rendered":"Rep\u00fablica Andaluza Independiente"},"content":{"rendered":"<p>Ustedes saben que a m\u00ed, eso de los nacionalismos, del signo que sean, me provoca sarpullido. Que no lo entiendo. Que no va conmigo. Sin embargo, debo reconocer que la propuesta realizada por la Asamblea Nacional Andaluza (ANA), me seduce. Y mucho.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/republica-andaluza-independiente\/ana-libre\/\" rel=\"attachment wp-att-23824\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23824\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-libre-300x92.jpg\" alt=\"\" width=\"300\" height=\"92\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-libre-300x92.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-libre-768x236.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-libre-644x198.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-libre.jpg 1466w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Que Ana sea precisamente el nombre que los meteor\u00f3logos le han dado al temporal que nos acosa estos d\u00edas no es m\u00e1s que una feliz coincidencia, una met\u00e1fora sobre el terremoto emocional que la propuesta de la Asamblea Nacional ha provocado en mis poco s\u00f3lidas certezas y en mis todav\u00eda menos inmutables convicciones.<\/p>\n<p>&nbsp;<\/p>\n<p>Porque la cosa va de proclamar la independencia de la Rep\u00fablica Federal de Andaluc\u00eda. Pero ojito a la Andaluc\u00eda de la que hablamos: a las ocho provincias de nuestra actual autonom\u00eda habr\u00eda que sumar la regi\u00f3n de Murcia, el Algarve y Alentejo portugueses y el Rif marroqu\u00ed. Hablamos, por tanto, de una aut\u00e9ntica reunificaci\u00f3n en torno a la herencia cultural andaluza.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/republica-andaluza-independiente\/ana-andalucia\/\" rel=\"attachment wp-att-23825\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23825\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Ana-Andaluc\u00eda-300x231.jpg\" alt=\"\" width=\"300\" height=\"231\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Ana-Andaluc\u00eda-300x231.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Ana-Andaluc\u00eda-768x592.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Ana-Andaluc\u00eda-644x497.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/Ana-Andaluc\u00eda.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Reconozco que soy de ideas y apetitos b\u00e1sicos, pero la idea de formar parte de una naci\u00f3n que, al jam\u00f3n serrano y al aceite de oliva, le sume el cusc\u00fas y la cataplana, me hace salivar de gusto. Y ser nacional de un pa\u00eds que lo mismo bebe vino tinto que verde o gris, me har\u00eda compatibilizar, sin remordimientos, la cerveza Alhambra con la Flag y la Sagres.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfY la de fusiones musicales que surgir\u00edan de la mezcla del flamenco y el amazigh bereber, por ejemplo? Mi querida novela negra tambi\u00e9n se ver\u00eda beneficiada, que T\u00e1nger es tierra abonada al Noir. Lo que me hace pensar que no s\u00e9 nada de novela negra portuguesa. \u00bfVen? Esto de la Naci\u00f3n Andaluza transnacional no trae m\u00e1s que cosas buenas, abri\u00e9ndonos la mente y fomentando nuestra curiosidad por saber.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/republica-andaluza-independiente\/ana-andaluza\/\" rel=\"attachment wp-att-23826\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23826\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-Andaluza-300x241.png\" alt=\"\" width=\"300\" height=\"241\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-Andaluza-300x241.png 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/ANA-Andaluza.png 498w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Lo que no entiendo es por qu\u00e9 tendr\u00edamos que quedarnos en una Andaluc\u00eda circunscrita a esos estrechos l\u00edmites geogr\u00e1ficos: dado que ANA declara la independencia a trav\u00e9s de las redes sociales, deber\u00edamos ser m\u00e1s imaginativos e integrar las Andaluc\u00edas lejanas. Las de la cuenca del N\u00edger, por ejemplo, que el Mal\u00ed es andalus\u00ed. \u00bfY qu\u00e9 me dicen de la cantidad de Granadas y Alhambras que hay por el mundo? \u00bfY la huella andaluza en Florida o California, que Los \u00c1ngeles fue fundada por un t\u00edo de Ja\u00e9n?<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1Madre m\u00eda! Y yo que pensaba que era inmune al virus nacionalista\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-23654 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23654 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ustedes saben que a m\u00ed, eso de los nacionalismos, del signo que sean, me provoca sarpullido. Que no lo entiendo. Que no va conmigo. Sin embargo, debo reconocer que la propuesta realizada por la Asamblea Nacional Andaluza (ANA), me seduce. Y mucho. Que Ana sea precisamente el nombre que los meteor\u00f3logos le han dado al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15536,15534,15533,15535,15537],"class_list":["post-23823","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-alhambras-del-mundo","tag-ana-andalucia","tag-asamblea-nacional-andaluza","tag-republica-andaluza-independiente","tag-republica-virtual"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23823"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23823\/revisions"}],"predecessor-version":[{"id":23828,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23823\/revisions\/23828"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}